{"text_format":"1","workbook":"xlsx","n_sheets":11,"sheets":["General Info","Data Entry","Relative Precision","Report","Normal Dist Plot","Q-Q Plot","Graph, Y vs. X","Graph, Y vs. Y-hat","Graph, Residuals vs. X","Normal Plot Data Sheet","Example data set"],"not_rendered":{"charts":10,"images":1,"macros":1,"external_links":0,"defined_names":1,"comments":0,"pivot_tables":0},"unopened":[{"sheet":"Normal Dist Plot","index":4,"reason":"not_a_worksheet"},{"sheet":"Q-Q Plot","index":5,"reason":"not_a_worksheet"},{"sheet":"Graph, Y vs. X","index":6,"reason":"not_a_worksheet"},{"sheet":"Graph, Y vs. Y-hat","index":7,"reason":"not_a_worksheet"},{"sheet":"Graph, Residuals vs. X","index":8,"reason":"not_a_worksheet"}],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"General Info","index":0,"n_rows":13,"n_cols":19,"rows_kept":13,"cut":false,"hidden":false,"merged":[]}
["General Information"]
[]
["Project Title","Hypothetical Analytical Case"]
["Date","2004-03-16",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"B3&\", \"&B7&\", \"&B10&\" v \"&B9","v":"Hypothetical Analytical Case, Length, Tape measurement v Laser measurement"}]
["Refinery Name","ABC Refining Company",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"B3&\", \"&B7&\", \"&B10&\" v Predicted from \"&B9","v":"Hypothetical Analytical Case, Length, Tape measurement v Predicted from Laser measurement"}]
["Refinery Location","Somewhere, CA",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"B3&\",\"&B7&\", Residuals v \"&B9","v":"Hypothetical Analytical Case,Length, Residuals v Laser measurement"}]
["Gasoline Property","Length"]
["Units","feet"]
["Alternative Method","Laser measurement"]
["ASTM Designated Method","Tape measurement",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"B9&\" (\"&B8&\")\"","v":"Laser measurement (feet)"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"B10&\" (\"&B8&\")\"","v":"Tape measurement (feet)"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"\"Predicted \"&B10&\" (\"&B8&\")\"","v":"Predicted Tape measurement (feet)"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"B10&\" minus Prediction from \"&B9","v":"Tape measurement minus Prediction from Laser measurement"}]

{"sheet":"Data Entry","index":1,"n_rows":1001,"n_cols":24,"rows_kept":1001,"cut":false,"hidden":false,"merged":[]}
["Xdata","Ydata","Y-Hat","Y-Yhat","(X-Xbar)2",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Linest Array"]
[5073.57,5100,5072.2793293055374,{"$f":"+IF(B2<>\"\",B2-C2,\"\")","v":27.720670694462569},{"$f":"+IF(A2<>\"\",(A2-Report!D$19)^2,\"\")","v":571174.25918905984},null,"a1","a2","a",null,null,null,{"$f":"IF(Report!D29=\"Pass\",IF(Report!D28=\"Pass\",\"Pass\",\"Fail\"),\"Fail\")","v":"Pass"},null,null,null,null,null,null,{"$f":"LINEST($B$2:$B$560,$A$2:$A$560,,TRUE)","v":1.0002026531341139},-2.3188455561084993]
[5281.71,5280,5280.4615095288727,{"$f":"+IF(B3<>\"\",B3-C3,\"\")","v":-0.46150952887273888},{"$f":"+IF(A3<>\"\",(A3-Report!D$19)^2,\"\")","v":299888.44811428396},null,2.5000000000000001E-2,{"$f":"+I3-G3","v":2.5000000000000001E-2},0.05,null,null,null,null,null,null,null,null,null,null,1.8638331268044049E-3,10.876153334349615]
[5307.48,5300,5306.2367319001378,-6.2367319001377837,{"$f":"+IF(A4<>\"\",(A4-Report!D$19)^2,\"\")","v":272328.16933414148},null,null,null,null,null,null,null,null,null,null,null,null,null,null,0.99806956999990681,11.694797133993346]
[5352,5340,5350.7657540176697,-10.765754017669678,{"$f":"+IF(A5<>\"\",(A5-Report!D$19)^2,\"\")","v":227844.61202036665},null,null,null,null,null,null,null,null,null,null,null,null,null,null,287979.75086541055,557]
[5368.49,5340,5367.2590957678503,-27.25909576785034,{"$f":"+IF(A6<>\"\",(A6-Report!D$19)^2,\"\")","v":212374.16512108248},null,null,null,null,null,null,null,null,null,null,null,null,null,null,39386495.202205189,76179.931962929244]
[5333.87,5350,5332.6320799163477,17.36792008365228,{"$f":"+IF(A7<>\"\",(A7-Report!D$19)^2,\"\")","v":245481.32066669941},null,"Graph Table",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"BF Limits"]
[5342.72,5350,5341.4838733965853,8.5161266034147047,{"$f":"+IF(A8<>\"\",(A8-Report!D$19)^2,\"\")","v":236789.98850122502},null,"Percent",null,null,null,null,null,null,null,null,null,null,null,null,null,"alpha1",{"$f":"+Report!D17","v":2.5000000000000001E-2}]
[5356.23,5350,5354.9966112404263,-4.9966112404263185,{"$f":"+IF(A9<>\"\",(A9-Report!D$19)^2,\"\")","v":223824.28706669982},null,"of Range","X","Y-Hat","(X-Xbar)2","Yutb","Bound","Reprod Bound","Reprod Band","Zero","Test",null,null,null,null,"n",{"$f":"COUNT(A2:A999)","v":559}]
[5358.29,5350,5357.0570287058827,-7.057028705882658,{"$f":"+IF(A10<>\"\",(A10-Report!D$19)^2,\"\")","v":221879.3557185778},null,0,{"$f":"MIN(A1:A999)","v":5073.57},{"$f":"+Report!D$9+Report!D$10*H10","v":5072.2793293055374},{"$f":"+(H10-Report!D$19)^2","v":571174.25918905984},{"$f":"+Report!D$9+Report!D$10*H10+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J10/Report!D$20)+Report!D$24","v":5096.4140874455725},{"$f":"+K10-(Report!D$9+Report!D$10*H10)","v":24.134758140035046},35,{"$f":"+I10+M10","v":5107.2793293055374},0,{"$f":"IF(L10<M10,0,1)","v":0},null,null,null,null,"XA Mean",{"$f":"AVERAGE(A2:A999)","v":5829.3307155635039}]
[5360.11,5360,5358.8773975345866,1.1226024654133653,{"$f":"+IF(A11<>\"\",(A11-Report!D$19)^2,\"\")","v":220168.07991392692},null,{"$f":"+G10+0.025","v":2.5000000000000001E-2},{"$f":"H$10+G11*(H$50-H$10)","v":5108.5844999999999},{"$f":"+Report!D$9+Report!D$10*H11","v":5107.300925103702},{"$f":"+(H11-Report!D$19)^2","v":519475.10724911286},{"$f":"+Report!D$9+Report!D$10*H11+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J11/Report!D$20)+Report!D$24","v":5131.2836274898627},{"$f":"+K11-(Report!D$9+Report!D$10*H11)","v":23.982702386160781},{"$f":"+M10","v":35},{"$f":"+I11+M11","v":5142.300925103702},0,{"$f":"IF(L11<M11,0,1)","v":0},null,null,null,null,"Large Sx",{"$f":"SQRT(SUM(E2:E999)/V9)","v":265.38707161796066}]
[5363.19,5360,5361.9580217062394,-1.9580217062393785,{"$f":"+IF(A12<>\"\",(A12-Report!D$19)^2,\"\")","v":217287.16670605578},null,{"$f":"+G11+0.025","v":0.05},5143.5990000000002,{"$f":"+Report!D$9+Report!D$10*H12","v":5142.3225209018674},{"$f":"+(H12-Report!D$19)^2","v":470227.98572966596},{"$f":"+Report!D$9+Report!D$10*H12+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J12/Report!D$20)+Report!D$24","v":5166.1540485989926},{"$f":"+K12-(Report!D$9+Report!D$10*H12)","v":23.831527697125239},{"$f":"+M11","v":35},5177.3225209018674,0,0,null,null,null,null,"XA Max",{"$f":"+MAX(A2:A999)","v":6474.15}]
[5378.92,5360,5377.6912094400395,-17.691209440039529,{"$f":"+IF(A13<>\"\",(A13-Report!D$19)^2,\"\")","v":202869.81269442753},null,7.5000000000000011E-2,5178.6134999999995,{"$f":"+Report!D$9+Report!D$10*H13","v":5177.344116700031},{"$f":"+(H13-Report!D$19)^2","v":423432.89463072026},{"$f":"+Report!D$9+Report!D$10*H13+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J13/Report!D$20)+Report!D$24","v":5201.0254739856546},{"$f":"+K13-(Report!D$9+Report!D$10*H13)","v":23.681357285623562},35,5212.344116700031,0,0,null,null,null,null,"XA Min",{"$f":"MIN(A2:A999)","v":5073.57}]
[5365.66,5380,5364.4285222594808,15.571477740519185,{"$f":"+IF(A14<>\"\",(A14-Report!D$19)^2,\"\")","v":214990.53247117184},null,0.1,5213.6279999999997,{"$f":"+Report!D$9+Report!D$10*H14","v":5212.3657124981955},{"$f":"+(H14-Report!D$19)^2","v":379089.8339522733},{"$f":"+Report!D$9+Report!D$10*H14+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J14/Report!D$20)+Report!D$24","v":5235.8980498801611},{"$f":"+K14-(Report!D$9+Report!D$10*H14)","v":23.53233738196559},35,5247.3657124981955,0,0,null,null,null,null,"Z(XA) Max",{"$f":"+(V12-V10)/V11","v":2.4297313373454332},{"$f":"SQRT(V9-1)","v":23.622023622035432},{"$f":"ROUND(MIN(V14:W14),3)","v":2.4300000000000002}]
[5375.48,5380,5374.2505123132578,5.7494876867422136,{"$f":"+IF(A15<>\"\",(A15-Report!D$19)^2,\"\")","v":205980.47201750489},null,0.125,5248.6424999999999,{"$f":"+Report!D$9+Report!D$10*H15","v":5247.3873082963601},{"$f":"+(H15-Report!D$19)^2","v":337198.80369432643},{"$f":"+Report!D$9+Report!D$10*H15+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J15/Report!D$20)+Report!D$24","v":5270.7719508557711},{"$f":"+K15-(Report!D$9+Report!D$10*H15)","v":23.384642559411077},35,5282.3873082963601,0,0,null,null,null,null,"Z(XA) Min",{"$f":"+(V13-V10)/V11","v":-2.8477676435250903},{"$f":"-W14","v":-23.622023622035432},{"$f":"ROUND(MAX(V15:W15),3)","v":-2.8479999999999999}]
[5383.99,5380,5382.762236891429,-2.7622368914289837,{"$f":"+IF(A16<>\"\",(A16-Report!D$19)^2,\"\")","v":198328.35293861385},null,0.15,5283.6569999999992,{"$f":"+Report!D$9+Report!D$10*H16","v":5282.4089040945237},{"$f":"+(H16-Report!D$19)^2","v":297759.80385688058},{"$f":"+Report!D$9+Report!D$10*H16+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J16/Report!D$20)+Report!D$24","v":5305.6473865898379},{"$f":"+K16-(Report!D$9+Report!D$10*H16)","v":23.238482495314202},35,5317.4089040945237,0,0,null,null,null,null,"phi",{"$f":"ATAN(X14)-ATAN(X15)","v":2.4135171619265723},{"$f":"2*ATAN(SQRT((V9-1)/2))","v":3.0219985335131421},{"$f":"ROUND(MIN(V16:W16),3)","v":2.4140000000000001}]
[5384.3,5380,5383.072299713901,-3.0722997139009749,{"$f":"+IF(A17<>\"\",(A17-Report!D$19)^2,\"\")","v":198052.33779496411},null,0.17499999999999999,5318.6714999999995,{"$f":"+Report!D$9+Report!D$10*H17","v":5317.4304998926882},{"$f":"+(H17-Report!D$19)^2","v":260772.83443993365},{"$f":"+Report!D$9+Report!D$10*H17+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J17/Report!D$20)+Report!D$24","v":5340.5246104819189},{"$f":"+K17-(Report!D$9+Report!D$10*H17)","v":23.094110589230695},35,5352.4304998926882,0,0,null,null,null,null,"B.F. Constant",2.476]
[5376.19,5390,5374.9606561969831,15.039343803016891,{"$f":"+IF(A18<>\"\",(A18-Report!D$19)^2,\"\")","v":205336.50810140467},null,0.19999999999999998,5353.6859999999997,{"$f":"+Report!D$9+Report!D$10*H18","v":5352.4520956908527},{"$f":"+(H18-Report!D$19)^2","v":226237.89544348681},{"$f":"+Report!D$9+Report!D$10*H18+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J18/Report!D$20)+Report!D$24","v":5375.4039306686227},{"$f":"+K18-(Report!D$9+Report!D$10*H18)","v":22.951834977769977},35,5387.4520956908527,0,0]
[5378.95,5390,5377.7212155196339,12.278784480366085,{"$f":"+IF(A19<>\"\",(A19-Report!D$19)^2,\"\")","v":202842.78895149395},null,0.22499999999999998,5388.7004999999999,{"$f":"+Report!D$9+Report!D$10*H19","v":5387.4736914890182},{"$f":"+(H19-Report!D$19)^2","v":194154.98686753996},{"$f":"+Report!D$9+Report!D$10*H19+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J19/Report!D$20)+Report!D$24","v":5410.2857241123293},{"$f":"+K19-(Report!D$9+Report!D$10*H19)","v":22.812032623311097},35,5422.4736914890182,0,0]
[5392.21,5390,5390.9839027001917,-0.98390270019172021,{"$f":"+IF(A20<>\"\",(A20-Report!D$19)^2,\"\")","v":191074.51997474962},null,0.24999999999999997,5423.7149999999992,{"$f":"+Report!D$9+Report!D$10*H20","v":5422.4952872871818},{"$f":"+(H20-Report!D$19)^2","v":164524.1087120939},{"$f":"+Report!D$9+Report!D$10*H20+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J20/Report!D$20)+Report!D$24","v":5445.170454580787},{"$f":"+K20-(Report!D$9+Report!D$10*H20)","v":22.675167293605227},35,5457.4952872871818,0,0]
[5386.54,5400,5385.3127536569218,14.687246343078186,{"$f":"+IF(A21<>\"\",(A21-Report!D$19)^2,\"\")","v":196063.61778923983},null,0.27499999999999997,5458.7294999999995,{"$f":"+Report!D$9+Report!D$10*H21","v":5457.5168830853463},{"$f":"+(H21-Report!D$19)^2","v":137345.26097714706},{"$f":"+Report!D$9+Report!D$10*H21+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J21/Report!D$20)+Report!D$24","v":5480.0586954329592},{"$f":"+K21-(Report!D$9+Report!D$10*H21)","v":22.541812347612904},35,5492.5168830853463,0,0]
[5393.34,5400,5392.1141316982339,7.8858683017660951,{"$f":"+IF(A22<>\"\",(A22-Report!D$19)^2,\"\")","v":190087.904057576},null,0.3,5493.7439999999997,{"$f":"+Report!D$9+Report!D$10*H22","v":5492.5384788835108},{"$f":"+(H22-Report!D$19)^2","v":112618.44366270026},{"$f":"+Report!D$9+Report!D$10*H22+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J22/Report!D$20)+Report!D$24","v":5514.9511580824756},{"$f":"+K22-(Report!D$9+Report!D$10*H22)","v":22.412679198964724},35,5527.5384788835108,0,0]
[5404.19,5400,5402.9663304847381,-2.9663304847381369,{"$f":"+IF(A23<>\"\",(A23-Report!D$19)^2,\"\")","v":180744.62802984845},null,0.32500000000000001,5528.7584999999999,{"$f":"+Report!D$9+Report!D$10*H23","v":5527.5600746816754},{"$f":"+(H23-Report!D$19)^2","v":90343.656768753499},{"$f":"+Report!D$9+Report!D$10*H23+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J23/Report!D$20)+Report!D$24","v":5549.8487266155635},{"$f":"+K23-(Report!D$9+Report!D$10*H23)","v":22.288651933888104},35,5562.5600746816754,0,0]
[5426.57,5410,5425.3508658618803,-15.350865861880266,{"$f":"+IF(A24<>\"\",(A24-Report!D$19)^2,\"\")","v":162216.1940012259},null,0.35000000000000003,5563.7730000000001,{"$f":"+Report!D$9+Report!D$10*H24","v":5562.5816704798399},{"$f":"+(H24-Report!D$19)^2","v":70520.900295306754},{"$f":"+Report!D$9+Report!D$10*H24+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J24/Report!D$20)+Report!D$24","v":5584.7524979012442},{"$f":"+K24-(Report!D$9+Report!D$10*H24)","v":22.170827421404283},35,5597.5816704798399,0,0]
[5406.04,5420,5404.8167053930365,15.1832946069635,{"$f":"+IF(A25<>\"\",(A25-Report!D$19)^2,\"\")","v":179175.02988226316},null,0.37500000000000006,5598.7874999999995,{"$f":"+Report!D$9+Report!D$10*H25","v":5597.6032662780035},{"$f":"+(H25-Report!D$19)^2","v":53150.174242360466},{"$f":"+Report!D$9+Report!D$10*H25+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J25/Report!D$20)+Report!D$24","v":5619.6638239802742},{"$f":"+K25-(Report!D$9+Report!D$10*H25)","v":22.060557702270671},35,5632.6032662780035,0,0]
[5411.43,5420,5410.2077976934297,9.7922023065702888,{"$f":"+IF(A26<>\"\",(A26-Report!D$19)^2,\"\")","v":174641.00806848833},null,0.40000000000000008,5633.8019999999997,{"$f":"+Report!D$9+Report!D$10*H26","v":5632.6248620761689},{"$f":"+(H26-Report!D$19)^2","v":38231.478609913727},{"$f":"+Report!D$9+Report!D$10*H26+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J26/Report!D$20)+Report!D$24","v":5654.5843486139356},{"$f":"+K26-(Report!D$9+Report!D$10*H26)","v":21.959486537766679},35,5667.6248620761689,0,0]
[5416.91,5420,5415.6889082326043,4.3110917673957374,{"$f":"+IF(A27<>\"\",(A27-Report!D$19)^2,\"\")","v":170090.84662591267},null,0.4250000000000001,5668.8164999999999,{"$f":"+Report!D$9+Report!D$10*H27","v":5667.6464578743335},{"$f":"+(H27-Report!D$19)^2","v":25764.81339796702},{"$f":"+Report!D$9+Report!D$10*H27+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J27/Report!D$20)+Report!D$24","v":5689.5160217810053},{"$f":"+K27-(Report!D$9+Report!D$10*H27)","v":21.869563906671829},35,5702.6464578743335,0,0]
[5421.31,5420,5420.0897999063955,-8.9799906395455764E-2,{"$f":"+IF(A28<>\"\",(A28-Report!D$19)^2,\"\")","v":166480.90432895342},null,0.45000000000000012,5703.8310000000001,{"$f":"+Report!D$9+Report!D$10*H28","v":5702.668053672498},{"$f":"+(H28-Report!D$19)^2","v":15750.178606520343},{"$f":"+Report!D$9+Report!D$10*H28+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J28/Report!D$20)+Report!D$24","v":5724.461065267109},{"$f":"+K28-(Report!D$9+Report!D$10*H28)","v":21.793011594611016},35,5737.668053672498,0,0]
[5422.28,5420,5421.0599964799349,-1.0599964799348527,{"$f":"+IF(A29<>\"\",(A29-Report!D$19)^2,\"\")","v":165690.28504076073},null,0.47500000000000014,5738.8454999999994,{"$f":"+Report!D$9+Report!D$10*H29","v":5737.6896494706616},{"$f":"+(H29-Report!D$19)^2","v":8187.5742355738639},{"$f":"+Report!D$9+Report!D$10*H29+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J29/Report!D$20)+Report!D$24","v":5759.4218542811441},{"$f":"+K29-(Report!D$9+Report!D$10*H29)","v":21.732204810482472},35,5772.6896494706616,0,0]
[5429.95,5420,5428.7315508294732,-8.7315508294732354,{"$f":"+IF(A30<>\"\",(A30-Report!D$19)^2,\"\")","v":159504.95596401652},null,0.50000000000000011,5773.86,{"$f":"+Report!D$9+Report!D$10*H30","v":5772.7112452688261},{"$f":"+(H30-Report!D$19)^2","v":3077.000285127187},{"$f":"+Report!D$9+Report!D$10*H30+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J30/Report!D$20)+Report!D$24","v":5794.4006865932852},{"$f":"+K30-(Report!D$9+Report!D$10*H30)","v":21.68944132445904},35,5807.7112452688261,0,0]
[5441.75,5420,5440.5339421364561,-20.533942136456062,{"$f":"+IF(A31<>\"\",(A31-Report!D$19)^2,\"\")","v":150218.81107671768},null,0.52500000000000013,5808.8744999999999,{"$f":"+Report!D$9+Report!D$10*H31","v":5807.7328410669907},{"$f":"+(H31-Report!D$19)^2","v":418.45675518054225},{"$f":"+Report!D$9+Report!D$10*H31+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J31/Report!D$20)+Report!D$24","v":5829.3994481094369},{"$f":"+K31-(Report!D$9+Report!D$10*H31)","v":21.66660704244623},35,5842.7328410669907,0,0]
[5396.6,5430,5395.3747923474511,34.625207652548852,{"$f":"+IF(A32<>\"\",(A32-Report!D$19)^2,\"\")","v":187255.87219210179},null,0.55000000000000016,5843.8890000000001,{"$f":"+Report!D$9+Report!D$10*H32","v":5842.7544368651552},{"$f":"+(H32-Report!D$19)^2","v":211.94364573392897},{"$f":"+Report!D$9+Report!D$10*H32+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J32/Report!D$20)+Report!D$24","v":5864.4192523696665},{"$f":"+K32-(Report!D$9+Report!D$10*H32)","v":21.664815504511353},35,5877.7544368651552,0,0]
[5417.15,5430,5415.9289568693566,14.071043130643375,{"$f":"+IF(A33<>\"\",(A33-Report!D$19)^2,\"\")","v":169892.94228244238},null,0.57500000000000018,5878.9035000000003,{"$f":"+Report!D$9+Report!D$10*H33","v":5877.7760326633206},{"$f":"+(H33-Report!D$19)^2","v":2457.4609567873472},{"$f":"+Report!D$9+Report!D$10*H33+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J33/Report!D$20)+Report!D$24","v":5899.46019015195},{"$f":"+K33-(Report!D$9+Report!D$10*H33)","v":21.684157488629353},35,5912.7760326633206,0,0]
[5427.51,5430,5426.2910563558262,3.7089436441738144,{"$f":"+IF(A34<>\"\",(A34-Report!D$19)^2,\"\")","v":161459.88745596612},null,0.6000000000000002,5913.9179999999997,{"$f":"+Report!D$9+Report!D$10*H34","v":5912.7976284614842},{"$f":"+(H34-Report!D$19)^2","v":7155.0086883406429},{"$f":"+Report!D$9+Report!D$10*H34+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J34/Report!D$20)+Report!D$24","v":5934.5213078135994},{"$f":"+K34-(Report!D$9+Report!D$10*H34)","v":21.723679352115141},35,5947.7976284614842,0,0]
[5429.21,5430,5427.9914008661544,2.0085991338455642,{"$f":"+IF(A35<>\"\",(A35-Report!D$19)^2,\"\")","v":160096.58702305035},null,0.62500000000000022,5948.9324999999999,{"$f":"+Report!D$9+Report!D$10*H35","v":5947.8192242596488},{"$f":"+(H35-Report!D$19)^2","v":14304.58684039406},{"$f":"+Report!D$9+Report!D$10*H35+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J35/Report!D$20)+Report!D$24","v":5969.6008254332191},{"$f":"+K35-(Report!D$9+Report!D$10*H35)","v":21.78160117357038},35,5982.8192242596488,0,0]
[5432.59,5430,5431.3720858337474,-1.3720858337474056,{"$f":"+IF(A36<>\"\",(A36-Report!D$19)^2,\"\")","v":157403.19538584095},null,0.65000000000000024,5983.9470000000001,{"$f":"+Report!D$9+Report!D$10*H36","v":5982.8408200578133},{"$f":"+(H36-Report!D$19)^2","v":23906.195412947509},{"$f":"+Report!D$9+Report!D$10*H36+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J36/Report!D$20)+Report!D$24","v":6004.6964890954414},{"$f":"+K36-(Report!D$9+Report!D$10*H36)","v":21.855669037628104},35,6017.8408200578133,0,0]
[5433.76,5430,5432.5423229379148,-2.5423229379148324,{"$f":"+IF(A37<>\"\",(A37-Report!D$19)^2,\"\")","v":156476.19101142231},null,0.67500000000000027,6018.9615000000003,{"$f":"+Report!D$9+Report!D$10*H37","v":6017.8624158559778},{"$f":"+(H37-Report!D$19)^2","v":35959.834406000991},{"$f":"+Report!D$9+Report!D$10*H37+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J37/Report!D$20)+Report!D$24","v":6039.8059172190442},{"$f":"+K37-(Report!D$9+Report!D$10*H37)","v":21.943501363066389},35,6052.8624158559778,0,0]
[5435.37,5430,5434.1526492094599,-4.1526492094599234,{"$f":"+IF(A38<>\"\",(A38-Report!D$19)^2,\"\")","v":155205.04540730809},null,0.70000000000000029,6053.9760000000006,{"$f":"+Report!D$9+Report!D$10*H38","v":6052.8840116541423},{"$f":"+(H38-Report!D$19)^2","v":50465.503819554506},{"$f":"+Report!D$9+Report!D$10*H38+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J38/Report!D$20)+Report!D$24","v":6074.9268510652091},{"$f":"+K38-(Report!D$9+Report!D$10*H38)","v":22.04283941106678},35,6087.8840116541423,0,0]
[5440.46,5430,5439.2436807139129,-9.2436807139129087,{"$f":"+IF(A39<>\"\",(A39-Report!D$19)^2,\"\")","v":151220.43342287152},null,0.72500000000000031,6088.9904999999999,{"$f":"+Report!D$9+Report!D$10*H39","v":6087.905607452306},{"$f":"+(H39-Report!D$19)^2","v":67423.203653607576},{"$f":"+Report!D$9+Report!D$10*H39+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J39/Report!D$20)+Report!D$24","v":6110.0572906301595},{"$f":"+K39-(Report!D$9+Report!D$10*H39)","v":22.151683177853556},35,6122.905607452306,0,0]
[5429.97,5440,5428.7515548825368,11.248445117463234,{"$f":"+IF(A40<>\"\",(A40-Report!D$19)^2,\"\")","v":159488.98113539364},null,0.75000000000000033,6124.0050000000001,{"$f":"+Report!D$9+Report!D$10*H40","v":6122.9272032504714},{"$f":"+(H40-Report!D$19)^2","v":86832.933908161081},{"$f":"+Report!D$9+Report!D$10*H40+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J40/Report!D$20)+Report!D$24","v":6145.1955406496181},{"$f":"+K40-(Report!D$9+Report!D$10*H40)","v":22.268337399146731},35,6157.9272032504714,0,0]
[5430.9,5440,5429.6817433499509,10.318256650049079,{"$f":"+IF(A41<>\"\",(A41-Report!D$19)^2,\"\")","v":158747.03510444603},null,0.77500000000000036,6159.0195000000003,{"$f":"+Report!D$9+Report!D$10*H41","v":6157.9487990486359},{"$f":"+(H41-Report!D$19)^2","v":108694.69458321463},{"$f":"+Report!D$9+Report!D$10*H41+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J41/Report!D$20)+Report!D$24","v":6180.3402021588827},{"$f":"+K41-(Report!D$9+Report!D$10*H41)","v":22.391403110246756},35,6192.9487990486359,0,0]
[5433.93,5440,5432.7123573889476,7.2876426110524335,{"$f":"+IF(A42<>\"\",(A42-Report!D$19)^2,\"\")","v":156341.72586813066},null,0.80000000000000038,6194.0339999999997,{"$f":"+Report!D$9+Report!D$10*H42","v":6192.9703948467995},{"$f":"+(H42-Report!D$19)^2","v":133008.48567876755},{"$f":"+Report!D$9+Report!D$10*H42+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J42/Report!D$20)+Report!D$24","v":6215.4901382530361},{"$f":"+K42-(Report!D$9+Report!D$10*H42)","v":22.519743406236557},35,6227.9703948467995,0,0]
[5446.59,5440,5445.3749229776249,-5.3749229776249194,{"$f":"+IF(A43<>\"\",(A43-Report!D$19)^2,\"\")","v":146490.45535006287},null,0.8250000000000004,6229.0484999999999,{"$f":"+Report!D$9+Report!D$10*H43","v":6227.9919906449641},{"$f":"+(H43-Report!D$19)^2","v":159774.3071948211},{"$f":"+Report!D$9+Report!D$10*H43+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J43/Report!D$20)+Report!D$24","v":6250.6444319349293},{"$f":"+K43-(Report!D$9+Report!D$10*H43)","v":22.652441289965282},35,6262.9919906449641,0,0]
[5462.47,5440,5461.2581411093952,-21.258141109395183,{"$f":"+IF(A44<>\"\",(A44-Report!D$19)^2,\"\")","v":134586.78462376591},null,0.85000000000000042,6264.0630000000001,{"$f":"+Report!D$9+Report!D$10*H44","v":6263.0135864431286},{"$f":"+(H44-Report!D$19)^2","v":188992.15913137468},{"$f":"+Report!D$9+Report!D$10*H44+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J44/Report!D$20)+Report!D$24","v":6285.802345297313},{"$f":"+K44-(Report!D$9+Report!D$10*H44)","v":22.78875885418438},35,6298.0135864431286,0,0]
[5443.95,5450,5442.7343879733507,7.2656120266492508,{"$f":"+IF(A45<>\"\",(A45-Report!D$19)^2,\"\")","v":148518.29592823843},null,0.87500000000000044,6299.0775000000003,{"$f":"+Report!D$9+Report!D$10*H45","v":6298.0351822412931},{"$f":"+(H45-Report!D$19)^2","v":220662.04148842828},{"$f":"+Report!D$9+Report!D$10*H45+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J45/Report!D$20)+Report!D$24","v":6320.9632838859688},{"$f":"+K45-(Report!D$9+Report!D$10*H45)","v":22.928101644675735},35,6333.0351822412931,0,0]
[5444.6,5450,5443.3845196978882,6.6154803021117914,{"$f":"+IF(A46<>\"\",(A46-Report!D$19)^2,\"\")","v":148017.72349800545},null,0.90000000000000047,6334.0920000000006,{"$f":"+Report!D$9+Report!D$10*H46","v":6333.0567780394576},{"$f":"+(H46-Report!D$19)^2","v":254783.95426598191},{"$f":"+Report!D$9+Report!D$10*H46+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J46/Report!D$20)+Report!D$24","v":6356.1267672140257},{"$f":"+K46-(Report!D$9+Report!D$10*H46)","v":23.069989174568036},35,6368.0567780394576,0,0]
[5449.36,5450,5448.1454843268066,1.8545156731934185,{"$f":"+IF(A47<>\"\",(A47-Report!D$19)^2,\"\")","v":144377.7446858414},null,0.92500000000000049,6369.1064999999999,{"$f":"+Report!D$9+Report!D$10*H47","v":6368.0783738376222},{"$f":"+(H47-Report!D$19)^2","v":291357.89746403461},{"$f":"+Report!D$9+Report!D$10*H47+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J47/Report!D$20)+Report!D$24","v":6391.2924050759621},{"$f":"+K47-(Report!D$9+Report!D$10*H47)","v":23.214031238339885},35,6403.0783738376222,0,0]
[5452.88,5450,5451.6661976658388,-1.6661976658388085,{"$f":"+IF(A48<>\"\",(A48-Report!D$19)^2,\"\")","v":141715.14124827401},null,0.95000000000000051,6404.1210000000001,{"$f":"+Report!D$9+Report!D$10*H48","v":6403.0999696357867},{"$f":"+(H48-Report!D$19)^2","v":330383.87108258822},{"$f":"+Report!D$9+Report!D$10*H48+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J48/Report!D$20)+Report!D$24","v":6426.4598788238955},{"$f":"+K48-(Report!D$9+Report!D$10*H48)","v":23.359909188108759},35,6438.0999696357867,0,0]
[5458.81,5450,5457.5973993989246,-7.5973993989246082,{"$f":"+IF(A49<>\"\",(A49-Report!D$19)^2,\"\")","v":137285.60066169064},null,0.97500000000000053,6439.1355000000003,{"$f":"+Report!D$9+Report!D$10*H49","v":6438.1215654339512},{"$f":"+(H49-Report!D$19)^2","v":371861.8751216419},{"$f":"+Report!D$9+Report!D$10*H49+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J49/Report!D$20)+Report!D$24","v":6461.6289266842541},{"$f":"+K49-(Report!D$9+Report!D$10*H49)","v":23.507361250302893},35,6473.1215654339512,0,0]
[5459.02,5450,5457.8074419560826,-7.8074419560825845,{"$f":"+IF(A50<>\"\",(A50-Report!D$19)^2,\"\")","v":137130.02606115394},null,1,{"$f":"MAX(A1:A999)","v":6474.15},{"$f":"+Report!D$9+Report!D$10*H50","v":6473.1431612321148},{"$f":"+(H50-Report!D$19)^2","v":415791.9095811944},{"$f":"+Report!D$9+Report!D$10*H50+Report!D$18*Report!D$14*SQRT(1/COUNT(A$2:A$999)+J50/Report!D$20)+Report!D$24","v":6496.7993322765033},{"$f":"+K50-(Report!D$9+Report!D$10*H50)","v":23.656171044388429},35,6508.1431612321148,0,0]
[5462.24,5450,5461.0280944991737,-11.028094499173676,{"$f":"+IF(A51<>\"\",(A51-Report!D$19)^2,\"\")","v":134755.59345292547}]
[5443.46,5460,5442.2442886733152,17.755711326684832,{"$f":"+IF(A52<>\"\",(A52-Report!D$19)^2,\"\")","v":148896.20912949048}]
[5449.47,5460,5448.2555066186515,11.744493381348548,{"$f":"+IF(A53<>\"\",(A53-Report!D$19)^2,\"\")","v":144294.16322841699}]
[5450.31,5460,5449.0956768472843,10.904323152715733,{"$f":"+IF(A54<>\"\",(A54-Report!D$19)^2,\"\")","v":143656.70282627019}]
[5453.07,5460,5451.8562361699342,8.1437638300658364,{"$f":"+IF(A55<>\"\",(A55-Report!D$19)^2,\"\")","v":141572.12607636017}]
[5464.35,5460,5463.138522097287,-3.1385220972870229,{"$f":"+IF(A56<>\"\",(A56-Report!D$19)^2,\"\")","v":133210.92273324705}]
[5473.59,5460,5472.3803946122462,-12.380394612246164,{"$f":"+IF(A57<>\"\",(A57-Report!D$19)^2,\"\")","v":126551.45670963367}]
[5476.52,5460,5475.3109883859297,-15.310988385929704,{"$f":"+IF(A58<>\"\",(A58-Report!D$19)^2,\"\")","v":124475.40101643132}]
[5490.68,5460,5489.4738579543082,-29.473857954308187,{"$f":"+IF(A59<>\"\",(A59-Report!D$19)^2,\"\")","v":114684.30715167301}]
[5473.4,5470,5472.1903561081508,-2.1903561081508087,{"$f":"+IF(A60<>\"\",(A60-Report!D$19)^2,\"\")","v":126686.67428154816}]
[5475.31,5470,5474.100743175637,-4.1007431756370352,{"$f":"+IF(A61<>\"\",(A61-Report!D$19)^2,\"\")","v":125330.66704809503}]
[5480.58,5470,5479.3718111576536,-9.3718111576536103,{"$f":"+IF(A62<>\"\",(A62-Report!D$19)^2,\"\")","v":121627.06160605603}]
[5481.8,5470,5480.5920583944771,-10.592058394477135,{"$f":"+IF(A63<>\"\",(A63-Report!D$19)^2,\"\")","v":120777.59826008091}]
[5465.21,5480,5463.9986963789825,16.001303621017541,{"$f":"+IF(A64<>\"\",(A64-Report!D$19)^2,\"\")","v":132583.89550247806}]
[5475.33,5480,5474.1207472286997,5.8792527713003437,{"$f":"+IF(A65<>\"\",(A65-Report!D$19)^2,\"\")","v":125316.50661947283}]
[5476.71,5480,5475.5010268900251,4.4989731099749406,{"$f":"+IF(A66<>\"\",(A66-Report!D$19)^2,\"\")","v":124341.36904451747}]
[5477.21,5480,5476.0011282165915,{"$f":"+IF(B67<>\"\",B67-C67,\"\")","v":3.9988717834085037},{"$f":"+IF(A67<>\"\",(A67-Report!D$19)^2,\"\")","v":123988.99832895397}]
[5484.85,5480,5483.6426764865364,-3.6426764865364021,{"$f":"+IF(A68<>\"\",(A68-Report!D$19)^2,\"\")","v":118666.96339514341}]
[5485.68,5480,5484.4728446886384,-4.4728446886383608,{"$f":"+IF(A69<>\"\",(A69-Report!D$19)^2,\"\")","v":118095.81430730804}]
[5479.68,5490,5478.4716287698329,11.528371230167068,{"$f":"+IF(A70<>\"\",(A70-Report!D$19)^2,\"\")","v":122255.62289407008}]
[5485.92,5490,5484.7128933253898,5.287106674610186,{"$f":"+IF(A71<>\"\",(A71-Report!D$19)^2,\"\")","v":117930.91956383771}]
[5486.16,5490,5484.9529419621422,5.0470580378578234,{"$f":"+IF(A72<>\"\",(A72-Report!D$19)^2,\"\")","v":117766.14002036738}]
[5486.68,5490,5485.4730473417721,4.5269526582278559,{"$f":"+IF(A73<>\"\",(A73-Report!D$19)^2,\"\")","v":117409.51287618103}]
[5490.26,5490,5489.0537728399922,0.94622716000776563,{"$f":"+IF(A74<>\"\",(A74-Report!D$19)^2,\"\")","v":114968.9501527464}]
[5492.1,5490,5490.8941457217588,-0.89414572175883222,{"$f":"+IF(A75<>\"\",(A75-Report!D$19)^2,\"\")","v":113724.5555194726}]
[5492.71,5490,5491.5042693401701,-1.5042693401701399,{"$f":"+IF(A76<>\"\",(A76-Report!D$19)^2,\"\")","v":113313.50614648535}]
[5493.78,5490,5492.5744861790236,-2.5744861790235518,{"$f":"+IF(A77<>\"\",(A77-Report!D$19)^2,\"\")","v":112594.28271517965}]
[5493.92,5490,5492.7145145504628,-2.714514550462809,{"$f":"+IF(A78<>\"\",(A78-Report!D$19)^2,\"\")","v":112500.34811482165}]
[5496.82,5490,5495.6151022445511,-5.6151022445510534,{"$f":"+IF(A79<>\"\",(A79-Report!D$19)^2,\"\")","v":110563.37596455358}]
[5487.61,5500,5486.4032358091863,13.596764190813701,{"$f":"+IF(A80<>\"\",(A80-Report!D$19)^2,\"\")","v":116773.04744523334}]
[5496.08,5500,5494.8749522812323,5.1250477187677461,{"$f":"+IF(A81<>\"\",(A81-Report!D$19)^2,\"\")","v":111056.03942358741}]
[5496.27,5500,5495.0649907853285,4.9350092146714815,{"$f":"+IF(A82<>\"\",(A82-Report!D$19)^2,\"\")","v":110929.44025167295}]
[5498.75,5500,5497.5454933651008,2.4545066348991895,{"$f":"+IF(A83<>\"\",(A83-Report!D$19)^2,\"\")","v":109283.60950247826}]
[5499.8,5500,5498.5957061508916,1.4042938491083987,{"$f":"+IF(A84<>\"\",(A84-Report!D$19)^2,\"\")","v":108590.49249979477}]
[5500.33,5500,5499.1258135570524,0.87418644294757542,{"$f":"+IF(A85<>\"\",(A85-Report!D$19)^2,\"\")","v":108241.47084129763}]
[5504.95,5500,5503.7467498145315,-3.7467498145315403,{"$f":"+IF(A86<>\"\",(A86-Report!D$19)^2,\"\")","v":105222.84862949092}]
[5507.87,5500,5506.6673415616833,-6.6673415616833154,{"$f":"+IF(A87<>\"\",(A87-Report!D$19)^2,\"\")","v":103336.99165060002}]
[5518.47,5500,5517.2694896849052,-17.269489684905238,{"$f":"+IF(A88<>\"\",(A88-Report!D$19)^2,\"\")","v":96634.384480653505}]
[5526.25,5500,5525.0510663262885,-25.051066326288492,{"$f":"+IF(A89<>\"\",(A89-Report!D$19)^2,\"\")","v":91857.920146485543}]
[5494.19,5510,5492.9845692668086,17.015430733191351,{"$f":"+IF(A90<>\"\",(A90-Report!D$19)^2,\"\")","v":112319.29922841767}]
[5502.26,5510,5501.0562046776013,8.9437953223987279,{"$f":"+IF(A91<>\"\",(A91-Report!D$19)^2,\"\")","v":106975.25297922231}]
[5517.06,5510,5515.8592039439864,-5.8592039439863584,{"$f":"+IF(A92<>\"\",(A92-Report!D$19)^2,\"\")","v":97512.999798542485}]
[5503,5520,5501.7963546409201,18.203645359079928,{"$f":"+IF(A93<>\"\",(A93-Report!D$19)^2,\"\")","v":106491.73592018847}]
[5516.65,5520,5515.4491208562004,4.5508791437996479,{"$f":"+IF(A94<>\"\",(A94-Report!D$19)^2,\"\")","v":97769.229885305045}]
[5517.43,5520,5516.2292789256462,3.7707210743537871,{"$f":"+IF(A95<>\"\",(A95-Report!D$19)^2,\"\")","v":97282.056369025566}]
[5521.84,5520,5520.6401726259674,-0.64017262596735236,{"$f":"+IF(A96<>\"\",(A96-Report!D$19)^2,\"\")","v":94550.54015775556}]
[5522.72,5520,5521.5203509607254,-1.5203509607254091,{"$f":"+IF(A97<>\"\",(A97-Report!D$19)^2,\"\")","v":94010.130898363714}]
[5524.78,5520,5523.5807684261808,-3.580768426180839,{"$f":"+IF(A98<>\"\",(A98-Report!D$19)^2,\"\")","v":92751.1383502424}]
[5526.36,5520,5525.1610886181334,-5.1610886181333626,{"$f":"+IF(A99<>\"\",(A99-Report!D$19)^2,\"\")","v":91791.254489061772}]
[5527.25,5520,5526.0512689794232,-6.0512689794231846,{"$f":"+IF(A100<>\"\",(A100-Report!D$19)^2,\"\")","v":91252.758715358534}]
[5530.85,5520,5529.6519985307059,-9.651998530705896,{"$f":"+IF(A101<>\"\",(A101-Report!D$19)^2,\"\")","v":89090.737563301082}]
[5531.83,5520,5530.6321971307771,-10.632197130777058,{"$f":"+IF(A102<>\"\",(A102-Report!D$19)^2,\"\")","v":88506.675760796876}]
[5532.41,5520,5531.2123146695949,-11.212314669594889,{"$f":"+IF(A103<>\"\",(A103-Report!D$19)^2,\"\")","v":88161.911330743256}]
[5529.1,5530,5527.9016438877215,2.0983561122784522,{"$f":"+IF(A104<>\"\",(A104-Report!D$19)^2,\"\")","v":90138.482567773346}]
[5542.64,5530,5541.444387811157,-11.444387811156957,{"$f":"+IF(A105<>\"\",(A105-Report!D$19)^2,\"\")","v":82191.566390313688}]
[5545.99,5530,5544.7950666991555,-14.795066699155541,{"$f":"+IF(A106<>\"\",(A106-Report!D$19)^2,\"\")","v":80281.961096038533}]
[5523.61,5540,5522.4105313220143,17.589468677985678,{"$f":"+IF(A107<>\"\",(A107-Report!D$19)^2,\"\")","v":93465.155924661041}]
[5541.33,5540,5540.1341223355512,-0.13412233555118291,{"$f":"+IF(A108<>\"\",(A108-Report!D$19)^2,\"\")","v":82944.412165090311}]
[5541.97,5540,5540.7742520335569,-0.774252033556877,{"$f":"+IF(A109<>\"\",(A109-Report!D$19)^2,\"\")","v":82576.180849168828}]
[5542.67,5540,5541.4743938907504,-1.4743938907504344,{"$f":"+IF(A110<>\"\",(A110-Report!D$19)^2,\"\")","v":82174.365847380031}]
[5546.65,5540,5545.4552004502239,-5.455200450223856,{"$f":"+IF(A111<>\"\",(A111-Report!D$19)^2,\"\")","v":79908.386951494787}]
[5550.84,5540,5549.6460495668571,-9.6460495668570729,{"$f":"+IF(A112<>\"\",(A112-Report!D$19)^2,\"\")","v":77557.078655072342}]
[5553.63,5540,5552.4366149691004,-12.436614969100447,{"$f":"+IF(A113<>\"\",(A113-Report!D$19)^2,\"\")","v":76010.884562228006}]
[5539.88,5550,5538.6838284885071,11.316171511492939,{"$f":"+IF(A114<>\"\",(A114-Report!D$19)^2,\"\")","v":83781.716740224365}]
[5545.95,5550,5544.7550585930303,5.2449414069697013,{"$f":"+IF(A115<>\"\",(A115-Report!D$19)^2,\"\")","v":80304.629953283584}]
[5551.89,5550,5550.6962623526479,-0.69626235264786374,{"$f":"+IF(A116<>\"\",(A116-Report!D$19)^2,\"\")","v":76973.350652388879}]
[5553.51,5550,5552.3165906507247,-2.31659065072472,{"$f":"+IF(A117<>\"\",(A117-Report!D$19)^2,\"\")","v":76077.067133963181}]
[5564.63,5550,5563.4388441535757,-13.438844153575701,{"$f":"+IF(A118<>\"\",(A118-Report!D$19)^2,\"\")","v":70066.46881983093}]
[5567.58,5550,5566.3894419803219,-16.389441980321863,{"$f":"+IF(A119<>\"\",(A119-Report!D$19)^2,\"\")","v":68513.43709800634}]
[5550.12,5560,5548.9259036566,11.074096343400015,{"$f":"+IF(A120<>\"\",(A120-Report!D$19)^2,\"\")","v":77958.623685483923}]
[5559.5,5560,5558.3078045429984,1.6921954570016169,{"$f":"+IF(A121<>\"\",(A121-Report!D$19)^2,\"\")","v":72808.615061512537}]
[5559.55,5560,5558.3578146756545,1.6421853243455189,{"$f":"+IF(A122<>\"\",(A122-Report!D$19)^2,\"\")","v":72781.634489956079}]
[5561.14,5560,5559.9481368941379,5.1863105862139491E-2,{"$f":"+IF(A123<>\"\",(A123-Report!D$19)^2,\"\")","v":71926.25991446407}]
[5564.46,5560,5563.268809702543,-3.268809702542967,{"$f":"+IF(A124<>\"\",(A124-Report!D$19)^2,\"\")","v":70156.49596312255}]
[5579.57,5560,5578.3818717913991,-18.381871791399135,{"$f":"+IF(A125<>\"\",(A125-Report!D$19)^2,\"\")","v":62380.415038793632}]
[5561.11,5570,5559.9181308145435,10.081869185456526,{"$f":"+IF(A126<>\"\",(A126-Report!D$19)^2,\"\")","v":71942.352257398219}]
[5570.26,5570,5569.0699850907213,0.9300149092787251,{"$f":"+IF(A127<>\"\",(A127-Report!D$19)^2,\"\")","v":67117.635662585817}]
[5574.07,5570,5572.880757199162,-2.8807571991619625,{"$f":"+IF(A128<>\"\",(A128-Report!D$19)^2,\"\")","v":65158.03290999218}]
[5574.09,5570,5572.9007612522246,-2.9007612522245836,{"$f":"+IF(A129<>\"\",(A129-Report!D$19)^2,\"\")","v":65147.822881369415}]
[5581.65,5570,5580.4622933099181,-10.462293309918095,{"$f":"+IF(A130<>\"\",(A130-Report!D$19)^2,\"\")","v":61345.736862049489}]
[5593.15,5570,5591.9646238209607,{"$f":"+IF(B131<>\"\",B131-C131,\"\")","v":-21.964623820960696},{"$f":"+IF(A131<>\"\",(A131-Report!D$19)^2,\"\")","v":55781.330404088891}]
[5574.39,5580,5573.2008220481648,6.7991779518351905,{"$f":"+IF(A132<>\"\",(A132-Report!D$19)^2,\"\")","v":64994.768452031218}]
[5577.68,5580,5576.4914887769764,3.5085112230235609,{"$f":"+IF(A133<>\"\",(A133-Report!D$19)^2,\"\")","v":63328.082643623384}]
[5586.07,5580,5584.883189036771,-4.8831890367710002,{"$f":"+IF(A134<>\"\",(A134-Report!D$19)^2,\"\")","v":59175.77573646808}]
[5579.91,5590,5578.7219406934655,11.278059306534487,{"$f":"+IF(A135<>\"\",(A135-Report!D$19)^2,\"\")","v":62210.693352210379}]
[5594.19,5590,5593.0048345802197,-3.0048345802197218,{"$f":"+IF(A136<>\"\",(A136-Report!D$19)^2,\"\")","v":55291.156115716818}]
[5612.61,5590,5611.4285674509501,-21.42856745095014,{"$f":"+IF(A137<>\"\",(A137-Report!D$19)^2,\"\")","v":46967.868554357294}]
[5579.56,5600,5578.3718697648683,21.628130235131721,{"$f":"+IF(A138<>\"\",(A138-Report!D$19)^2,\"\")","v":62385.410353104555}]
[5592.91,5600,5591.7245751842083,8.2754248157916663,{"$f":"+IF(A139<>\"\",(A139-Report!D$19)^2,\"\")","v":55894.754747559273}]
[5594.44,5600,5593.2548852435038,6.7451147564961502,{"$f":"+IF(A140<>\"\",(A140-Report!D$19)^2,\"\")","v":55173.64825793507}]
[5601.08,5600,5599.8962308603141,0.10376913968593726,{"$f":"+IF(A141<>\"\",(A141-Report!D$19)^2,\"\")","v":52098.389155251585}]
[5601.53,5600,5600.3463220542244,-0.34632205422440165,{"$f":"+IF(A142<>\"\",(A142-Report!D$19)^2,\"\")","v":51893.16601124451}]
[5602.15,5600,5600.9664476991675,-0.96644769916747464,{"$f":"+IF(A143<>\"\",(A143-Report!D$19)^2,\"\")","v":51611.077523945816}]
[5602.27,5610,5601.0864720175441,8.9135279824558893,{"$f":"+IF(A144<>\"\",(A144-Report!D$19)^2,\"\")","v":51556.568552210214}]
[5605.25,5610,5604.0670759238837,5.9329240761162509,{"$f":"+IF(A145<>\"\",(A145-Report!D$19)^2,\"\")","v":50212.167087451926}]
[5605.64,5610,5604.4571549586062,5.5428450413937753,{"$f":"+IF(A146<>\"\",(A146-Report!D$19)^2,\"\")","v":50037.536229312245}]
[5610.82,5610,5609.6382047018406,0.36179529815944989,{"$f":"+IF(A147<>\"\",(A147-Report!D$19)^2,\"\")","v":47746.932816074623}]
[5623.62,5610,5622.4407986619572,-12.44079866195716,{"$f":"+IF(A148<>\"\",(A148-Report!D$19)^2,\"\")","v":42316.898497648843}]
[5613.91,5620,5612.7288309000251,7.2711690999749408,{"$f":"+IF(A149<>\"\",(A149-Report!D$19)^2,\"\")","v":46406.084693892102}]
[5617.98,5620,5616.7996556982807,3.2003443017192694,{"$f":"+IF(A150<>\"\",(A150-Report!D$19)^2,\"\")","v":44669.124969205302}]
[5627.6,5620,5626.4216052214315,-6.4216052214314914,{"$f":"+IF(A151<>\"\",(A151-Report!D$19)^2,\"\")","v":40695.281601763156}]
[5637.03,5620,5635.853516240486,-15.853516240485988,{"$f":"+IF(A152<>\"\",(A152-Report!D$19)^2,\"\")","v":36979.565206235719}]
[5651.15,5620,5649.9763777027392,-29.976377702739228,{"$f":"+IF(A153<>\"\",(A153-Report!D$19)^2,\"\")","v":31748.367398722399}]
[5608.29,5630,5607.1076919894113,22.892308010588749,{"$f":"+IF(A154<>\"\",(A154-Report!D$19)^2,\"\")","v":48858.997936825843}]
[5619.44,5630,5618.2599515718566,11.740048428143382,{"$f":"+IF(A155<>\"\",(A155-Report!D$19)^2,\"\")","v":44054.112479759853}]
[5634.39,5630,5633.2129812362118,-3.2129812362118173,{"$f":"+IF(A156<>\"\",(A156-Report!D$19)^2,\"\")","v":38001.882584410792}]
[5645.53,5630,5644.3552387921254,-14.355238792125419,{"$f":"+IF(A157<>\"\",(A157-Report!D$19)^2,\"\")","v":33782.703041656147}]
[5647.54,5630,5646.3656461249257,-16.365646124925661,{"$f":"+IF(A158<>\"\",(A158-Report!D$19)^2,\"\")","v":33047.864265090786}]
[5650.3,5630,5649.1262054475756,-19.126205447575558,{"$f":"+IF(A159<>\"\",(A159-Report!D$19)^2,\"\")","v":32051.997115180162}]
[5625.16,5640,5623.9811107477835,16.018889252216468,{"$f":"+IF(A160<>\"\",(A160-Report!D$19)^2,\"\")","v":41685.681093713261}]
[5635.06,5640,5633.8831170138119,6.1168829861881022,{"$f":"+IF(A161<>\"\",(A161-Report!D$19)^2,\"\")","v":37741.110925555673}]
[5640.99,5640,5639.8143187468968,0.18568125310321193,{"$f":"+IF(A162<>\"\",(A162-Report!D$19)^2,\"\")","v":35472.225138972753}]
[5644.44,5640,5643.2650179002094,-3.2650179002093864,{"$f":"+IF(A163<>\"\",(A163-Report!D$19)^2,\"\")","v":34184.576701584643}]
[5649.89,5640,5648.7161223597905,-8.7161223597904609,{"$f":"+IF(A164<>\"\",(A164-Report!D$19)^2,\"\")","v":32198.970401942184}]
[5650.91,5640,5649.7363290659869,-9.7363290659868653,{"$f":"+IF(A165<>\"\",(A165-Report!D$19)^2,\"\")","v":31833.951742192807}]
[5654.38,5640,5653.207032272363,-13.207032272362994,{"$f":"+IF(A166<>\"\",(A166-Report!D$19)^2,\"\")","v":30607.752876181999}]
[5658.84,5640,5657.6679361053411,-17.667936105341141,{"$f":"+IF(A167<>\"\",(A167-Report!D$19)^2,\"\")","v":29067.084093355534}]
[5660.49,5640,5659.3182704830115,-19.318270483011474,{"$f":"+IF(A168<>\"\",(A168-Report!D$19)^2,\"\")","v":28507.187231996093}]
[5616.72,5650,5615.539400355332,34.460599644668036,{"$f":"+IF(A169<>\"\",(A169-Report!D$19)^2,\"\")","v":45203.316372425041}]
[5651.76,5650,5650.5865013211514,-0.58650132115144515,{"$f":"+IF(A170<>\"\",(A170-Report!D$19)^2,\"\")","v":31531.35902573472}]
[5655.74,5650,5654.5673078806249,-4.5673078806248668,{"$f":"+IF(A171<>\"\",(A171-Report!D$19)^2,\"\")","v":30133.736529849382}]
[5666.66,5650,5665.4895208528496,-15.489520852849637,{"$f":"+IF(A172<>\"\",(A172-Report!D$19)^2,\"\")","v":26461.761701942429}]
[5635.83,5660,5634.6532730567251,25.346726943274916,{"$f":"+IF(A173<>\"\",(A173-Report!D$19)^2,\"\")","v":37442.526923588055}]
[5640.88,5660,5639.7042964550519,20.295703544948083,{"$f":"+IF(A174<>\"\",(A174-Report!D$19)^2,\"\")","v":35513.672196396597}]
[5650.65,5660,5649.4762763761719,10.523723623828118,{"$f":"+IF(A175<>\"\",(A175-Report!D$19)^2,\"\")","v":31926.798114285906}]
[5661.33,5660,5660.1584407116443,-0.15844071164428897,{"$f":"+IF(A176<>\"\",(A176-Report!D$19)^2,\"\")","v":28224.240429849357}]
[5665.82,5660,5664.6493506242168,-4.6493506242168223,{"$f":"+IF(A177<>\"\",(A177-Report!D$19)^2,\"\")","v":26735.754104089163}]
[5653.64,5670,5652.4668823090442,17.533117690955805,{"$f":"+IF(A178<>\"\",(A178-Report!D$19)^2,\"\")","v":30867.227535215909}]
[5659.39,5670,5658.2180475645646,11.781952435435414,{"$f":"+IF(A179<>\"\",(A179-Report!D$19)^2,\"\")","v":28879.846806235615}]
[5661.03,5670,5659.8583799157041,10.141620084295937,{"$f":"+IF(A180<>\"\",(A180-Report!D$19)^2,\"\")","v":28325.13085918752}]
[5662.55,5670,5661.3786879484687,8.6213120515312767,{"$f":"+IF(A181<>\"\",(A181-Report!D$19)^2,\"\")","v":27815.807083874322}]
[5670.9,5670,5669.730380102138,0.26961989786195772,{"$f":"+IF(A182<>\"\",(A182-Report!D$19)^2,\"\")","v":25100.291633963985}]
[5674.49,5670,5673.3211076268899,-3.3211076268898978,{"$f":"+IF(A183<>\"\",(A183-Report!D$19)^2,\"\")","v":23975.647196217978}]
[5665.26,5680,5664.0892371384616,15.910762861538387,{"$f":"+IF(A184<>\"\",(A184-Report!D$19)^2,\"\")","v":26919.199705520121}]
[5669,5680,5667.8299950611836,12.170004938816419,{"$f":"+IF(A185<>\"\",(A185-Report!D$19)^2,\"\")","v":25705.938353105183}]
[5671.56,5680,5670.3905138532073,9.6094861467927331,{"$f":"+IF(A186<>\"\",(A186-Report!D$19)^2,\"\")","v":24891.598689419916}]
[5672.99,5680,5671.8208036471888,8.1791963528112319,{"$f":"+IF(A187<>\"\",(A187-Report!D$19)^2,\"\")","v":24442.419342908492}]
[5688.36,5680,5687.1939184258599,-7.1939184258599198,{"$f":"+IF(A188<>\"\",(A188-Report!D$19)^2,\"\")","v":19872.742646486404}]
[5691.88,5680,5690.7146317648921,-10.714631764892147,{"$f":"+IF(A189<>\"\",(A189-Report!D$19)^2,\"\")","v":18892.699208919217}]
[5708.84,5680,5707.6780687620467,-27.678068762046678,{"$f":"+IF(A190<>\"\",(A190-Report!D$19)^2,\"\")","v":14518.012537005159}]
[5677.19,5690,5676.021654790351,13.978345209648978,{"$f":"+IF(A191<>\"\",(A191-Report!D$19)^2,\"\")","v":23146.797332175112}]
[5701.17,5690,5700.0065144125083,-10.006514412508295,{"$f":"+IF(A192<>\"\",(A192-Report!D$19)^2,\"\")","v":16425.169013749324}]
[5709.46,5690,5708.2981944069898,-18.298194406989751,{"$f":"+IF(A193<>\"\",(A193-Report!D$19)^2,\"\")","v":14368.988449706441}]
[5689.51,5700,5688.3441514769647,11.655848523035274,{"$f":"+IF(A194<>\"\",(A194-Report!D$19)^2,\"\")","v":19549.832500690194}]
[5689.97,5700,5688.8042446974059,{"$f":"+IF(B195<>\"\",B195-C195,\"\")","v":11.19575530259408},{"$f":"+IF(A195<>\"\",(A195-Report!D$19)^2,\"\")","v":19421.409042371761}]
[5691.42,5700,5690.25453854445,9.7454614555499575,{"$f":"+IF(A196<>\"\",(A196-Report!D$19)^2,\"\")","v":19019.365467237651}]
[5691.9,5700,5690.7346358179539,9.2653641820461417,{"$f":"+IF(A197<>\"\",(A197-Report!D$19)^2,\"\")","v":18887.201580296805}]
[5696.8,5700,5695.6356288183124,4.3643711816876021,{"$f":"+IF(A198<>\"\",(A198-Report!D$19)^2,\"\")","v":17564.390567774321}]
[5719.55,5700,5718.3902391771135,-18.390239177113472,{"$f":"+IF(A199<>\"\",(A199-Report!D$19)^2,\"\")","v":12051.805509634902}]
[5726.4,5700,5725.2416273510808,-25.241627351080751,{"$f":"+IF(A200<>\"\",(A200-Report!D$19)^2,\"\")","v":10594.732206415014}]
[5688.63,5710,5687.4639731422058,22.536026857794241,{"$f":"+IF(A201<>\"\",(A201-Report!D$19)^2,\"\")","v":19796.69136008199}]
[5696.89,5710,5695.7256470570937,14.274352942906262,{"$f":"+IF(A202<>\"\",(A202-Report!D$19)^2,\"\")","v":17540.543138972851}]
[5700.94,5710,5699.7764678022868,10.223532197713212,{"$f":"+IF(A203<>\"\",(A203-Report!D$19)^2,\"\")","v":16484.175842908659}]
[5702.07,5710,5700.9066968003281,9.0933031996719365,{"$f":"+IF(A204<>\"\",(A204-Report!D$19)^2,\"\")","v":16195.289725735111}]
[5704.65,5710,5703.4872196454144,6.5127803545856295,{"$f":"+IF(A205<>\"\",(A205-Report!D$19)^2,\"\")","v":15545.280833427447}]
[5716.99,5710,5715.8297203850898,-5.8297203850897859,{"$f":"+IF(A206<>\"\",(A206-Report!D$19)^2,\"\")","v":12620.43637332013}]
[5718.68,5710,5717.5200628688863,-7.5200628688862707,{"$f":"+IF(A207<>\"\",(A207-Report!D$19)^2,\"\")","v":12243.580854715374}]
[5724.25,5710,5723.0911916468431,-13.091191646843072,{"$f":"+IF(A208<>\"\",(A208-Report!D$19)^2,\"\")","v":11041.956783338004}]
[5707.82,5720,5706.6578620558494,13.342137944150636,{"$f":"+IF(A209<>\"\",(A209-Report!D$19)^2,\"\")","v":14764.853996754813}]
[5721.89,5720,5720.7307133854474,-0.73071338544741593,{"$f":"+IF(A210<>\"\",(A210-Report!D$19)^2,\"\")","v":11543.507360797674}]
[5716.22,5730,5715.0595643421766,14.9404356578234,{"$f":"+IF(A211<>\"\",(A211-Report!D$19)^2,\"\")","v":12794.033975287819}]
[5724.57,5730,5723.4112564958459,6.5887435041540812,{"$f":"+IF(A212<>\"\",(A212-Report!D$19)^2,\"\")","v":10974.807525377424}]
[5730.97,5730,5729.8125534759047,0.18744652409532137,{"$f":"+IF(A213<>\"\",(A213-Report!D$19)^2,\"\")","v":9674.8303661644622}]
[5731.03,5730,5729.8725656350925,0.12743436490745808,{"$f":"+IF(A214<>\"\",(A214-Report!D$19)^2,\"\")","v":9663.0306802969426}]
[5739.96,5740,5738.8043753275806,1.1956246724193988,{"$f":"+IF(A215<>\"\",(A215-Report!D$19)^2,\"\")","v":7987.1248003327064}]
[5743.5,5740,5742.3450927196745,-2.3450927196745397,{"$f":"+IF(A216<>\"\",(A216-Report!D$19)^2,\"\")","v":7366.9117341431056}]
[5751,5740,5749.8466126181811,-9.8466126181810978,{"$f":"+IF(A217<>\"\",(A217-Report!D$19)^2,\"\")","v":6135.7010006905475}]
[5751.25,5740,5750.0966632814643,-10.096663281464316,{"$f":"+IF(A218<>\"\",(A218-Report!D$19)^2,\"\")","v":6096.598142908796}]
[5751.27,5740,5750.1166673345278,-10.116667334527847,{"$f":"+IF(A219<>\"\",(A219-Report!D$19)^2,\"\")","v":6093.4753142861873}]
[5763.76,5740,5762.6091984721725,-22.609198472172466,{"$f":"+IF(A220<>\"\",(A220-Report!D$19)^2,\"\")","v":4299.5187395099001}]
[5733.93,5750,5732.7731533291817,17.226846670818304,{"$f":"+IF(A221<>\"\",(A221-Report!D$19)^2,\"\")","v":9101.2965300285141}]
[5745.6,5750,5744.445518291257,5.5544817087429692,{"$f":"+IF(A222<>\"\",(A222-Report!D$19)^2,\"\")","v":7010.8327287763286}]
[5760.91,5750,5759.7586209107394,-9.7586209107394097,{"$f":"+IF(A223<>\"\",(A223-Report!D$19)^2,\"\")","v":4681.3943182219209}]
[5765.75,5750,5764.5996017519092,-14.599601751909177,{"$f":"+IF(A224<>\"\",(A224-Report!D$19)^2,\"\")","v":4042.5073915671837}]
[5768.17,5750,5767.0200921724936,-17.020092172493605,{"$f":"+IF(A225<>\"\",(A225-Report!D$19)^2,\"\")","v":3740.633128239816}]
[5786.52,5750,5785.3738108575053,-35.373810857505305,{"$f":"+IF(A226<>\"\",(A226-Report!D$19)^2,\"\")","v":1832.7573670591953}]
[5743.75,5760,5742.5951433829587,17.404856617041332,{"$f":"+IF(A227<>\"\",(A227-Report!D$19)^2,\"\")","v":7324.0588763613541}]
[5750.26,5760,5749.1064626548614,10.893537345138611,{"$f":"+IF(A228<>\"\",(A228-Report!D$19)^2,\"\")","v":6252.1780597244988}]
[5752.89,5760,5751.7369956326047,8.2630043673952969,{"$f":"+IF(A229<>\"\",(A229-Report!D$19)^2,\"\")","v":5843.182995860453}]
[5764.43,5760,5763.2793342497725,-3.2793342497725462,{"$f":"+IF(A230<>\"\",(A230-Report!D$19)^2,\"\")","v":4212.1028806547956}]
[5765.3,5760,5764.1495105579988,-4.1495105579988376,{"$f":"+IF(A231<>\"\",(A231-Report!D$19)^2,\"\")","v":4099.932535574314}]
[5760.53,5770,5759.3785439025487,10.621456097451301,{"$f":"+IF(A232<>\"\",(A232-Report!D$19)^2,\"\")","v":4733.5384620501991}]
[5762.03,5770,5760.8788478822498,9.1211521177501709,{"$f":"+IF(A233<>\"\",(A233-Report!D$19)^2,\"\")","v":4529.3863153596867}]
[5784.46,5770,5783.3133933920481,-13.313393392048056,{"$f":"+IF(A234<>\"\",(A234-Report!D$19)^2,\"\")","v":2013.3811151808654}]
[5785.85,5770,5784.7036750799052,-14.703675079905224,{"$f":"+IF(A235<>\"\",(A235-Report!D$19)^2,\"\")","v":1890.5726259142962}]
[5761.72,5780,5760.5687850597787,19.431214940221253,{"$f":"+IF(A236<>\"\",(A236-Report!D$19)^2,\"\")","v":4571.2088590089907}]
[5762.61,5780,5761.4589654210677,18.54103457893234,{"$f":"+IF(A237<>\"\",(A237-Report!D$19)^2,\"\")","v":4451.653885306032}]
[5779.98,5780,5778.8324855060073,1.1675144939927122,{"$f":"+IF(A238<>\"\",(A238-Report!D$19)^2,\"\")","v":2435.4931266299063}]
[5782.51,5780,5781.3629982184366,-1.3629982184365872,{"$f":"+IF(A239<>\"\",(A239-Report!D$19)^2,\"\")","v":2192.1794058785135}]
[5794.5,5780,5793.3554280295148,-13.355428029514769,{"$f":"+IF(A240<>\"\",(A240-Report!D$19)^2,\"\")","v":1213.1787466657108}]
[5795.19,5780,5794.0455678601766,-14.045567860176561,{"$f":"+IF(A241<>\"\",(A241-Report!D$19)^2,\"\")","v":1165.5884591881029}]
[5796.48,5780,5795.3358292827197,-15.335829282719715,{"$f":"+IF(A242<>\"\",(A242-Report!D$19)^2,\"\")","v":1079.1695130342641}]
[5798.01,5780,5796.8661393420152,-16.866139342015231,{"$f":"+IF(A243<>\"\",(A243-Report!D$19)^2,\"\")","v":980.98722340990003}]
[5805.04,5780,5803.8975639935479,-23.897563993547919,{"$f":"+IF(A244<>\"\",(A244-Report!D$19)^2,\"\")","v":590.03886258705097}]
[5813.08,5780,5811.9391933247462,-31.939193324746157,{"$f":"+IF(A245<>\"\",(A245-Report!D$19)^2,\"\")","v":264.08575632590936}]
[5815.51,5780,5814.3696857718624,-34.369685771862351,{"$f":"+IF(A246<>\"\",(A246-Report!D$19)^2,\"\")","v":191.01217868727213}]
[5783.44,5790,5782.2931866858507,7.7068133141492581,{"$f":"+IF(A247<>\"\",(A247-Report!D$19)^2,\"\")","v":2105.9577749304531}]
[5791.19,5790,5790.0447572476405,-4.4757247640518472E-2,{"$f":"+IF(A248<>\"\",(A248-Report!D$19)^2,\"\")","v":1454.7141836961371}]
[5792.04,5790,5790.8949295028051,-0.89492950280509831,{"$f":"+IF(A249<>\"\",(A249-Report!D$19)^2,\"\")","v":1390.5974672381526}]
[5790.79,5800,5789.6446761863872,10.355323813612813,{"$f":"+IF(A250<>\"\",(A250-Report!D$19)^2,\"\")","v":1485.3867561469124}]
[5792.15,5800,5791.0049517946491,8.9950482053509404,{"$f":"+IF(A251<>\"\",(A251-Report!D$19)^2,\"\")","v":1382.4056098142062}]
[5806.25,5800,5805.1078092038406,-5.1078092038405885,{"$f":"+IF(A252<>\"\",(A252-Report!D$19)^2,\"\")","v":532.71943092336994}]
[5791.91,5810,5790.7649031578976,19.235096842102394,{"$f":"+IF(A253<>\"\",(A253-Report!D$19)^2,\"\")","v":1400.3099532846718}]
[5796.65,5810,5795.5058637337524,14.494136266247551,{"$f":"+IF(A254<>\"\",(A254-Report!D$19)^2,\"\")","v":1068.029169742668}]
[5806,5810,5804.8577585405574,5.14224145944263,{"$f":"+IF(A255<>\"\",(A255-Report!D$19)^2,\"\")","v":544.32228870512188}]
[5811.92,5810,5810.7789582471114,-0.77895824711140449,{"$f":"+IF(A256<>\"\",(A256-Report!D$19)^2,\"\")","v":303.13301643323342}]
[5814.32,5810,5813.1794446146323,-3.1794446146323025,{"$f":"+IF(A257<>\"\",(A257-Report!D$19)^2,\"\")","v":225.32158172842611}]
[5821.05,5810,5819.9108084702257,-9.9108084702256747,{"$f":"+IF(A258<>\"\",(A258-Report!D$19)^2,\"\")","v":68.570250243652239}]
[5823.33,5810,5822.1912705193708,{"$f":"+IF(B259<>\"\",B259-C259,\"\")","v":-12.191270519370846},{"$f":"+IF(A259<>\"\",(A259-Report!D$19)^2,\"\")","v":36.008587274078472}]
[5830.59,5810,5829.452741781125,-19.452741781125042,{"$f":"+IF(A260<>\"\",(A260-Report!D$19)^2,\"\")","v":1.5857972920017358}]
[5832.07,5810,5830.9330417077626,-20.933041707762641,{"$f":"+IF(A261<>\"\",(A261-Report!D$19)^2,\"\")","v":7.5036792240283123}]
[5787.41,5820,5786.2639912187933,33.736008781206692,{"$f":"+IF(A262<>\"\",(A262-Report!D$19)^2,\"\")","v":1757.346393356208}]
[5813.32,5820,5812.1792419614985,7.8207580385014808,{"$f":"+IF(A263<>\"\",(A263-Report!D$19)^2,\"\")","v":256.34301285543444}]
[5813.59,5820,5812.4492966778453,7.5507033221547317,{"$f":"+IF(A264<>\"\",(A264-Report!D$19)^2,\"\")","v":247.77012645112845}]
[5814.17,5820,5813.0294142166631,6.9705857833369009,{"$f":"+IF(A265<>\"\",(A265-Report!D$19)^2,\"\")","v":229.84729639746635}]
[5826.76,5820,5825.6219656196217,-5.6219656196217329,{"$f":"+IF(A266<>\"\",(A266-Report!D$19)^2,\"\")","v":6.6085785084399111}]
[5827.75,5820,5826.6121662462238,-6.6121662462237509,{"$f":"+IF(A267<>\"\",(A267-Report!D$19)^2,\"\")","v":2.4986616927033651}]
[5829.36,5820,5828.2224925177698,-8.2224925177697514,{"$f":"+IF(A268<>\"\",(A268-Report!D$19)^2,\"\")","v":8.5757822087654514E-4}]
[5840.25,5820,5839.1146994104001,-19.114699410400135,{"$f":"+IF(A269<>\"\",(A269-Report!D$19)^2,\"\")","v":119.23077260510655}]
[5825.74,5830,5824.6017589134244,5.398241086575581,{"$f":"+IF(A270<>\"\",(A270-Report!D$19)^2,\"\")","v":12.8932382579905}]
[5830.27,5830,5829.1326769321222,0.86732306787780544,{"$f":"+IF(A271<>\"\",(A271-Report!D$19)^2,\"\")","v":0.88225525264466775}]
[5827.25,5840,5826.1120649196573,13.887935080342686,{"$f":"+IF(A272<>\"\",(A272-Report!D$19)^2,\"\")","v":4.3293772562072377}]
[5834.04,5840,5832.9034409344376,7.09655906556236,{"$f":"+IF(A273<>\"\",(A273-Report!D$19)^2,\"\")","v":22.177359903824307}]
[5835.95,5840,5834.8138280019239,5.1861719980761336,{"$f":"+IF(A274<>\"\",(A274-Report!D$19)^2,\"\")","v":43.814926451237447}]
[5839.94,5840,5838.8046365879281,1.1953634120718561,{"$f":"+IF(A275<>\"\",(A275-Report!D$19)^2,\"\")","v":112.55691625447047}]
[5846.55,5840,5845.4159761251458,-5.4159761251457894,{"$f":"+IF(A276<>\"\",(A276-Report!D$19)^2,\"\")","v":296.50375650496403}]
[5848.67,5840,5847.53640574979,-7.5364057497899921,{"$f":"+IF(A277<>\"\",(A277-Report!D$19)^2,\"\")","v":374.00792251570414}]
[5851.19,5840,5850.0569164356875,-10.056916435687526,{"$f":"+IF(A278<>\"\",(A278-Report!D$19)^2,\"\")","v":477.82831607562434}]
[5855.06,5840,5853.927700703317,-13.927700703316987,{"$f":"+IF(A279<>\"\",(A279-Report!D$19)^2,\"\")","v":661.99607761414245}]
[5832.45,5850,5831.3131187159543,18.686881284045739,{"$f":"+IF(A280<>\"\",(A280-Report!D$19)^2,\"\")","v":9.7299353957658283}]
[5834.47,5850,5833.3335280752854,16.666471924714642,{"$f":"+IF(A281<>\"\",(A281-Report!D$19)^2,\"\")","v":26.412244519213935}]
[5850.71,5850,5849.5768191621837,0.42318083781628957,{"$f":"+IF(A282<>\"\",(A282-Report!D$19)^2,\"\")","v":457.07380301660709}]
[5850.84,5850,5849.7068455070912,0.29315449290879769,{"$f":"+IF(A283<>\"\",(A283-Report!D$19)^2,\"\")","v":462.64931697010081}]
[5851.77,5850,5850.6370339745063,-0.63703397450626653,{"$f":"+IF(A284<>\"\",(A284-Report!D$19)^2,\"\")","v":503.52148602199691}]
[5852.31,5850,5851.1771434071979,-1.1771434071979456,{"$f":"+IF(A285<>\"\",(A285-Report!D$19)^2,\"\")","v":528.04751321341155}]
[5852.83,5850,5851.6972487868279,-1.6972487868279131,{"$f":"+IF(A286<>\"\",(A286-Report!D$19)^2,\"\")","v":552.21636902734565}]
[5873.7,5850,5872.5714781577362,-22.571478157736237,{"$f":"+IF(A287<>\"\",(A287-Report!D$19)^2,\"\")","v":1968.6334014066813}]
[5847.8,5860,5846.6662294415628,13.333770558437209,{"$f":"+IF(A288<>\"\",(A288-Report!D$19)^2,\"\")","v":341.1144675962048}]
[5857.94,5860,5856.8082843443426,3.19171565565739,{"$f":"+IF(A289<>\"\",(A289-Report!D$19)^2,\"\")","v":818.49115596831666}]
[5865.06,5860,5863.9297272346585,-3.9297272346584577,{"$f":"+IF(A290<>\"\",(A290-Report!D$19)^2,\"\")","v":1276.581766344073}]
[5869.31,5870,5868.1805885104786,1.8194114895213715,{"$f":"+IF(A291<>\"\",(A291-Report!D$19)^2,\"\")","v":1598.3431840542935}]
[5875.57,5870,5874.4418571190972,-4.4418571190972216,{"$f":"+IF(A292<>\"\",(A292-Report!D$19)^2,\"\")","v":2138.0714251991662}]
[5862.8,5880,5861.669269238575,18.330730761425002,{"$f":"+IF(A293<>\"\",(A293-Report!D$19)^2,\"\")","v":1120.1930006910941}]
[5871.29,5880,5870.1609897636836,9.839010236316426,{"$f":"+IF(A294<>\"\",(A294-Report!D$19)^2,\"\")","v":1760.581550422783}]
[5875.73,5880,5874.6018895435982,5.3981104564018096,{"$f":"+IF(A295<>\"\",(A295-Report!D$19)^2,\"\")","v":2152.8935962188311}]
[5876.91,5880,5875.7821286742965,4.217871325703527,{"$f":"+IF(A296<>\"\",(A296-Report!D$19)^2,\"\")","v":2263.7883074889887}]
[5878.77,5880,5877.6425056091266,2.3574943908733985,{"$f":"+IF(A297<>\"\",(A297-Report!D$19)^2,\"\")","v":2444.2428455928116}]
[5879.25,5880,5878.1226028826313,1.8773971173686732,{"$f":"+IF(A298<>\"\",(A298-Report!D$19)^2,\"\")","v":2491.9349586518047}]
[5883.08,5880,5881.9533790441346,-1.9533790441346355,{"$f":"+IF(A299<>\"\",(A299-Report!D$19)^2,\"\")","v":2888.9855774353568}]
[5887.54,5880,5886.4142828771128,-6.4142828771127824,{"$f":"+IF(A300<>\"\",(A300-Report!D$19)^2,\"\")","v":3388.320794608906}]
[5887.96,5880,5886.8343679914287,-6.834367991428735,{"$f":"+IF(A301<>\"\",(A301-Report!D$19)^2,\"\")","v":3437.3929935355713}]
[5889.66,5880,5888.534712501757,-8.5347125017569851,{"$f":"+IF(A302<>\"\",(A302-Report!D$19)^2,\"\")","v":3639.6225606196363}]
[5890.45,5880,5889.3248725977328,-9.3248725977327922,{"$f":"+IF(A303<>\"\",(A303-Report!D$19)^2,\"\")","v":3735.5669300292957}]
[5875.88,5890,5874.7519199415692,15.248080058430787,{"$f":"+IF(A304<>\"\",(A304-Report!D$19)^2,\"\")","v":2166.8358815498309}]
[5884.39,5890,5883.2636445197404,6.73635548025959,{"$f":"+IF(A305<>\"\",(A305-Report!D$19)^2,\"\")","v":3031.5248026590207}]
[5887.82,5890,5886.6943396199904,3.3056603800096127,{"$f":"+IF(A306<>\"\",(A306-Report!D$19)^2,\"\")","v":3420.9963938933142}]
[5888.55,5890,5887.4244875567783,2.5755124432216689,{"$f":"+IF(A307<>\"\",(A307-Report!D$19)^2,\"\")","v":3506.9236491706538}]
[5889.69,5890,5888.5647185813505,1.435281418649538,{"$f":"+IF(A308<>\"\",(A308-Report!D$19)^2,\"\")","v":3643.2432176857951}]
[5891.7,5890,5890.5751259141507,-0.57512591415070347,{"$f":"+IF(A309<>\"\",(A309-Report!D$19)^2,\"\")","v":3889.9276411205356}]
[5892.61,5890,5891.4853103285022,-1.4853103285022371,{"$f":"+IF(A310<>\"\",(A310-Report!D$19)^2,\"\")","v":4004.2678387949395}]
[5904.26,5890,5903.137671237515,-13.137671237514951,{"$f":"+IF(A311<>\"\",(A311-Report!D$19)^2,\"\")","v":5614.3976661653733}]
[5896.32,5900,5895.1960621716298,4.8039378283701808,{"$f":"+IF(A312<>\"\",(A312-Report!D$19)^2,\"\")","v":4487.5642293137435}]
[5898.47,5900,5897.3464978758684,2.6535021241315917,{"$f":"+IF(A313<>\"\",(A313-Report!D$19)^2,\"\")","v":4780.2406523907512}]
[5898.89,5900,5897.7665829901853,2.2334170098147297,{"$f":"+IF(A314<>\"\",(A314-Report!D$19)^2,\"\")","v":4838.4940513174179}]
[5900.13,5900,5899.0068342800714,0.99316571992858371,{"$f":"+IF(A315<>\"\",(A315-Report!D$19)^2,\"\")","v":5012.5386767198979}]
[5902.04,5900,5900.9172213475576,-0.91722134755764273,{"$f":"+IF(A316<>\"\",(A316-Report!D$19)^2,\"\")","v":5286.6400432672926}]
[5904.37,5900,5903.2476935293598,-3.2476935293598217,{"$f":"+IF(A317<>\"\",(A317-Report!D$19)^2,\"\")","v":5630.8942087413534}]
[5904.97,5900,5903.8478151212403,-3.8478151212402736,{"$f":"+IF(A318<>\"\",(A318-Report!D$19)^2,\"\")","v":5721.3013500652041}]
[5906.51,5900,5905.3881272070666,-5.3881272070666455,{"$f":"+IF(A319<>\"\",(A319-Report!D$19)^2,\"\")","v":5956.6419461296073}]
[5907.5,5900,5906.3783278336696,-6.378327833669573,{"$f":"+IF(A320<>\"\",(A320-Report!D$19)^2,\"\")","v":6110.4370293138354}]
[5918.5,5900,5917.3805570181448,-17.380557018144827,{"$f":"+IF(A321<>\"\",(A321-Report!D$19)^2,\"\")","v":7951.1612869167502}]
[5892.52,5910,5891.3952920897209,18.604707910279103,{"$f":"+IF(A322<>\"\",(A322-Report!D$19)^2,\"\")","v":3992.8856675964671}]
[5903.36,5910,5902.2374888496943,{"$f":"+IF(B323<>\"\",B323-C323,\"\")","v":7.7625111503057269},{"$f":"+IF(A323<>\"\",(A323-Report!D$19)^2,\"\")","v":5480.3349541795997}]
[5907.93,5910,5906.8084149745173,3.1915850254827092,{"$f":"+IF(A324<>\"\",(A324-Report!D$19)^2,\"\")","v":6177.8475139292677}]
[5915.16,5910,5914.0398801566771,-4.0398801566770999,{"$f":"+IF(A325<>\"\",(A325-Report!D$19)^2,\"\")","v":7366.6660668809318}]
[5915.87,5910,5914.7500240404024,-4.7500240404024225,{"$f":"+IF(A326<>\"\",(A326-Report!D$19)^2,\"\")","v":7489.0477507807618}]
[5912.54,5920,5911.4193492054656,8.5806507945344492,{"$f":"+IF(A327<>\"\",(A327-Report!D$19)^2,\"\")","v":6923.7850164337106}]
[5932.33,5920,5931.2133597109896,-11.213359710989607,{"$f":"+IF(A328<>\"\",(A328-Report!D$19)^2,\"\")","v":10608.852594430218}]
[5936.12,5920,5935.0041277663677,-15.004127766367674,{"$f":"+IF(A329<>\"\",(A329-Report!D$19)^2,\"\")","v":11403.951270458851}]
[5919.79,5930,5918.670818440688,11.329181559312019,{"$f":"+IF(A330<>\"\",(A330-Report!D$19)^2,\"\")","v":8182.8821407629039}]
[5921.68,5930,5920.5612014551116,9.4387985448884137,{"$f":"+IF(A331<>\"\",(A331-Report!D$19)^2,\"\")","v":8528.3903359329197}]
[5921.94,5930,5920.8212541449257,9.1787458550743395,{"$f":"+IF(A332<>\"\",(A332-Report!D$19)^2,\"\")","v":8576.47956383977}]
[5922.82,5930,5921.7014324796837,8.2985675203162828,{"$f":"+IF(A333<>\"\",(A333-Report!D$19)^2,\"\")","v":8740.2463044480228}]
[5928.86,5930,5927.7426565046144,2.2573434953856122,{"$f":"+IF(A334<>\"\",(A334-Report!D$19)^2,\"\")","v":9906.0784604408855}]
[5929.11,5930,5927.9927071678976,2.0072928321023937,{"$f":"+IF(A335<>\"\",(A335-Report!D$19)^2,\"\")","v":9955.9056026591334}]
[5932.56,5930,5931.4434063212111,-1.4434063212111141,{"$f":"+IF(A336<>\"\",(A336-Report!D$19)^2,\"\")","v":10656.285165271103}]
[5932.81,5930,5931.6934569844943,-1.6934569844943326,{"$f":"+IF(A337<>\"\",(A337-Report!D$19)^2,\"\")","v":10707.962307489352}]
[5934.85,5930,5933.7338703968881,-3.7338703968880509,{"$f":"+IF(A338<>\"\",(A338-Report!D$19)^2,\"\")","v":11134.31938799025}]
[5934.97,5930,5933.8538947152638,-3.8538947152637775,{"$f":"+IF(A339<>\"\",(A339-Report!D$19)^2,\"\")","v":11159.658416254986}]
[5937.82,5930,5936.7044722766959,-6.7044722766959239,{"$f":"+IF(A340<>\"\",(A340-Report!D$19)^2,\"\")","v":11769.924837542898}]
[5939.51,5930,5938.3948147604924,-8.3948147604924088,{"$f":"+IF(A341<>\"\",(A341-Report!D$19)^2,\"\")","v":12139.474718938365}]
[5939.7,5930,5938.5848532645878,-8.584853264587764,{"$f":"+IF(A342<>\"\",(A342-Report!D$19)^2,\"\")","v":12181.378947024146}]
[5947.91,5930,5946.7965170468187,-16.796517046818735,{"$f":"+IF(A343<>\"\",(A343-Report!D$19)^2,\"\")","v":14061.046697471418}]
[5959.23,5930,5958.1188110802968,-28.118811080296837,{"$f":"+IF(A344<>\"\",(A344-Report!D$19)^2,\"\")","v":16873.824097113611}]
[5902.01,5940,5900.8872152679633,39.112784732036744,{"$f":"+IF(A345<>\"\",(A345-Report!D$19)^2,\"\")","v":5282.2783862011402}]
[5926.89,5940,5925.7722572779403,14.227742722059702,{"$f":"+IF(A346<>\"\",(A346-Report!D$19)^2,\"\")","v":9517.8139797612203}]
[5930.66,5940,5929.5430212802557,10.456978719744257,{"$f":"+IF(A347<>\"\",(A347-Report!D$19)^2,\"\")","v":10267.623884412307}]
[5931.48,5940,5930.363187455825,9.6368125441749726,{"$f":"+IF(A348<>\"\",(A348-Report!D$19)^2,\"\")","v":10434.476310888102}]
[5937.11,5940,5935.9943283929706,4.0056716070293987,{"$f":"+IF(A349<>\"\",(A349-Report!D$19)^2,\"\")","v":11616.374153643066}]
[5939.29,5940,5938.1747701768027,1.8252298231973327,{"$f":"+IF(A350<>\"\",(A350-Report!D$19)^2,\"\")","v":12091.044233786251}]
[5940.14,5940,5939.0249424319672,0.9750575680327529,{"$f":"+IF(A351<>\"\",(A351-Report!D$19)^2,\"\")","v":12278.697517328375}]
[5947.66,5940,5946.5464663835355,-6.5464663835355168,{"$f":"+IF(A352<>\"\",(A352-Report!D$19)^2,\"\")","v":14001.819555253171}]
[5950.83,5940,5949.7171087939705,-9.7171087939705103,{"$f":"+IF(A353<>\"\",(A353-Report!D$19)^2,\"\")","v":14762.076118580573}]
[5956.99,5940,5955.8783571372769,-15.878357137276907,{"$f":"+IF(A354<>\"\",(A354-Report!D$19)^2,\"\")","v":16296.892902838166}]
[5957.71,5940,5956.5985030475331,-16.598503047533086,{"$f":"+IF(A355<>\"\",(A355-Report!D$19)^2,\"\")","v":16481.240672426786}]
[5964.79,5940,5963.6799378317228,-23.679937831722782,{"$f":"+IF(A356<>\"\",(A356-Report!D$19)^2,\"\")","v":18349.217740047552}]
[5920.77,5950,5919.6510170407601,30.348982959239947,{"$f":"+IF(A357<>\"\",(A357-Report!D$19)^2,\"\")","v":8361.1427382585225}]
[5940.37,5950,5939.2549890421878,10.745010957812156,{"$f":"+IF(A358<>\"\",(A358-Report!D$19)^2,\"\")","v":12329.722688169068}]
[5946.34,5950,5945.2261988813989,4.7738011186011136,{"$f":"+IF(A359<>\"\",(A359-Report!D$19)^2,\"\")","v":13691.17264434089}]
[5947.05,5950,5945.9363427651242,4.0636572348757909,{"$f":"+IF(A360<>\"\",(A360-Report!D$19)^2,\"\")","v":13857.829928240722}]
[5950.32,5950,5949.2070054408723,0.7929945591276919,{"$f":"+IF(A361<>\"\",(A361-Report!D$19)^2,\"\")","v":14638.406948455293}]
[5950.86,5950,5949.7471148735649,0.2528851264351033,{"$f":"+IF(A362<>\"\",(A362-Report!D$19)^2,\"\")","v":14769.366975646701}]
[5959.26,5950,5958.1488171598912,-8.1488171598912231,{"$f":"+IF(A363<>\"\",(A363-Report!D$19)^2,\"\")","v":16881.618954179972}]
[5949.39,5960,5948.2768169734582,11.723183026541847,{"$f":"+IF(A364<>\"\",(A364-Report!D$19)^2,\"\")","v":14414.231779403561}]
[5953.81,5960,5952.6977127003111,7.3022872996889419,{"$f":"+IF(A365<>\"\",(A365-Report!D$19)^2,\"\")","v":15495.092253822206}]
[5956.31,5960,5955.198219333146,4.8017806668540288,{"$f":"+IF(A366<>\"\",(A366-Report!D$19)^2,\"\")","v":16123.738676004688}]
[5964.32,5960,5963.2098425847498,-3.209842584749822,{"$f":"+IF(A367<>\"\",(A367-Report!D$19)^2,\"\")","v":18222.106912677176}]
[5956.56,5970,5955.4482699964292,14.55173000357081,{"$f":"+IF(A368<>\"\",(A368-Report!D$19)^2,\"\")","v":16187.290818222937}]
[5963.33,5970,5962.2196419581469,7.7803580418531055,{"$f":"+IF(A369<>\"\",(A369-Report!D$19)^2,\"\")","v":17955.808229492974}]
[5964.92,5970,5963.8099641766303,6.1900358233697261,{"$f":"+IF(A370<>\"\",(A370-Report!D$19)^2,\"\")","v":18384.454054001071}]
[5969.56,5970,5968.4509044871729,1.5490955128270798,{"$f":"+IF(A371<>\"\",(A371-Report!D$19)^2,\"\")","v":19664.252213571846}]
[5974.07,5970,5972.9618184528072,-2.9618184528071652,{"$f":"+IF(A372<>\"\",(A372-Report!D$19)^2,\"\")","v":20949.460459188846}]
[5963.04,5980,5961.9295831887384,18.070416811261566,{"$f":"+IF(A373<>\"\",(A373-Report!D$19)^2,\"\")","v":17878.172744519816}]
[5974.75,5980,5973.641956256939,6.3580437430609891,{"$f":"+IF(A374<>\"\",(A374-Report!D$19)^2,\"\")","v":21146.768286022565}]
[5977.64,5980,5976.5325419244964,3.4674580755036004,{"$f":"+IF(A375<>\"\",(A375-Report!D$19)^2,\"\")","v":21995.643850065611}]
[5983.74,5980,5982.633778108614,-2.6337781086140239,{"$f":"+IF(A376<>\"\",(A376-Report!D$19)^2,\"\")","v":23842.227120190699}]
[5986.57,5980,5985.4643516169835,-5.4643516169835493,{"$f":"+IF(A377<>\"\",(A377-Report!D$19)^2,\"\")","v":24724.192570101241}]
[5989.1,5980,5987.9948643294138,-7.9948643294137582,{"$f":"+IF(A378<>\"\",(A378-Report!D$19)^2,\"\")","v":25526.224249350122}]
[5995.35,5980,5994.2461309115015,-14.246130911501496,{"$f":"+IF(A379<>\"\",(A379-Report!D$19)^2,\"\")","v":27562.402804806326}]
[5971.83,5990,5970.7213645097872,19.278635490212764,{"$f":"+IF(A380<>\"\",(A380-Report!D$19)^2,\"\")","v":20306.046064913407}]
[5993.06,5990,5991.9556668358246,-1.9556668358245588,{"$f":"+IF(A381<>\"\",(A381-Report!D$19)^2,\"\")","v":26807.278582087183}]
[5993.49,5990,5992.3857539766723,-2.3857539766722766,{"$f":"+IF(A382<>\"\",(A382-Report!D$19)^2,\"\")","v":26948.270666702367}]
[6006.87,5990,6005.7684654756067,-15.768465475606718,{"$f":"+IF(A383<>\"\",(A383-Report!D$19)^2,\"\")","v":31520.197518223038}]
[5986.08,6000,5984.974252316948,15.025747683052032,{"$f":"+IF(A384<>\"\",(A384-Report!D$19)^2,\"\")","v":24570.338171353545}]
[5989.59,6000,5988.4849636294493,11.515036370550661,{"$f":"+IF(A385<>\"\",(A385-Report!D$19)^2,\"\")","v":25683.038248097815}]
[5990.48,6000,5989.3751439907383,10.624856009261748,{"$f":"+IF(A386<>\"\",(A386-Report!D$19)^2,\"\")","v":25969.091874394591}]
[5995.15,6000,5994.0460903808744,{"$f":"+IF(B387<>\"\",B387-C387,\"\")","v":5.9539096191256249},{"$f":"+IF(A387<>\"\",(A387-Report!D$19)^2,\"\")","v":27496.035091031485}]
[5998.74,6000,5997.6368179056262,2.3631820943737694,{"$f":"+IF(A388<>\"\",(A388-Report!D$19)^2,\"\")","v":28699.505653285574}]
[6001.33,6000,6000.2273427772434,-0.22734277724339336,{"$f":"+IF(A389<>\"\",(A389-Report!D$19)^2,\"\")","v":29583.753846666674}]
[6001.7,6000,6000.5974177589032,-0.59741775890324789,{"$f":"+IF(A390<>\"\",(A390-Report!D$19)^2,\"\")","v":29711.170217149644}]
[6004.51,6000,6003.4079872142102,-3.4079872142101522,{"$f":"+IF(A391<>\"\",(A391-Report!D$19)^2,\"\")","v":30687.78169568289}]
[6008.81,6000,6007.7088586226873,-7.7088586226873304,{"$f":"+IF(A392<>\"\",(A392-Report!D$19)^2,\"\")","v":32212.813541836826}]
[6009.12,6000,6008.0189214451584,-8.0189214451584121,{"$f":"+IF(A393<>\"\",(A393-Report!D$19)^2,\"\")","v":32324.186798187271}]
[6022.69,6000,6021.5916714481882,-21.591671448188208,{"$f":"+IF(A394<>\"\",(A394-Report!D$19)^2,\"\")","v":37387.812877793658}]
[5988.74,6010,5987.6347913742848,22.36520862571524,{"$f":"+IF(A395<>\"\",(A395-Report!D$19)^2,\"\")","v":25411.319964555656}]
[5995.67,6010,5994.5661957605043,15.433804239495657,{"$f":"+IF(A396<>\"\",(A396-Report!D$19)^2,\"\")","v":27668.757546845587}]
[5999.44,6010,5998.3369597628198,11.663040237180212,{"$f":"+IF(A397<>\"\",(A397-Report!D$19)^2,\"\")","v":28937.168651496606}]
[6012.85,6010,6011.7496773413486,-1.7496773413486153,{"$f":"+IF(A398<>\"\",(A398-Report!D$19)^2,\"\")","v":33679.327760083703}]
[6040.95,6010,6039.8553718944167,-29.855371894416749,{"$f":"+IF(A399<>\"\",(A399-Report!D$19)^2,\"\")","v":44782.721545414577}]
[6010.76,6020,6009.6592537962988,10.340746203701201,{"$f":"+IF(A400<>\"\",(A400-Report!D$19)^2,\"\")","v":32916.585251139099}]
[6016.85,6020,6015.7504879538856,4.2495120461144325,{"$f":"+IF(A401<>\"\",(A401-Report!D$19)^2,\"\")","v":35163.482035575675}]
[6018.81,6020,6017.7108851540279,2.289114845972108,{"$f":"+IF(A402<>\"\",(A402-Report!D$19)^2,\"\")","v":35902.399230566756}]
[6027.2,6020,6026.1025854138225,-6.1025854138224531,{"$f":"+IF(A403<>\"\",(A403-Report!D$19)^2,\"\")","v":39152.253723410933}]
[6034.91,6020,6033.814147869487,-13.814147869486987,{"$f":"+IF(A404<>\"\",(A404-Report!D$19)^2,\"\")","v":42262.842189421717}]
[6060.93,6020,6059.8394209040371,-39.83942090403707,{"$f":"+IF(A405<>\"\",(A405-Report!D$19)^2,\"\")","v":53638.228551497174}]
[6022.06,6030,6020.9615437767143,9.0384562232857206,{"$f":"+IF(A406<>\"\",(A406-Report!D$19)^2,\"\")","v":37144.577079403985}]
[6022.26,6030,6021.1615843073405,8.8384156926595097,{"$f":"+IF(A407<>\"\",(A407-Report!D$19)^2,\"\")","v":37221.708793178514}]
[6023.66,6030,6022.5618680217285,7.4381319782714854,{"$f":"+IF(A408<>\"\",(A408-Report!D$19)^2,\"\")","v":37763.870789600558}]
[6024.25,6030,6023.1519875870772,6.8480124129227988,{"$f":"+IF(A409<>\"\",(A409-Report!D$19)^2,\"\")","v":37993.527445235683}]
[6027.9,6030,6026.8027272710169,3.19727272898308,{"$f":"+IF(A410<>\"\",(A410-Report!D$19)^2,\"\")","v":39429.760721621962}]
[6028.12,6040,6027.0227718547067,12.977228145293338,{"$f":"+IF(A411<>\"\",(A411-Report!D$19)^2,\"\")","v":39517.179606774116}]
[6035.33,6040,6034.2342329838029,5.76576701619706,{"$f":"+IF(A412<>\"\",(A412-Report!D$19)^2,\"\")","v":42435.705188348409}]
[6037.93,6040,6036.8347598819528,3.1652401180472225,{"$f":"+IF(A413<>\"\",(A413-Report!D$19)^2,\"\")","v":43513.661467418337}]
[6044.14,6040,6043.0460183579153,-3.0460183579152726,{"$f":"+IF(A414<>\"\",(A414-Report!D$19)^2,\"\")","v":46143.028680119642}]
[6044.16,6040,6043.0660224109779,-3.0660224109778937,{"$f":"+IF(A415<>\"\",(A415-Report!D$19)^2,\"\")","v":46151.621451496896}]
[6047.46,6040,6046.3666911663204,-6.3666911663203791,{"$f":"+IF(A416<>\"\",(A416-Report!D$19)^2,\"\")","v":47580.384728777848}]
[6049.52,6040,6048.4271086317767,-8.4271086317767185,{"$f":"+IF(A417<>\"\",(A417-Report!D$19)^2,\"\")","v":48483.32098065639}]
[6041.28,6050,6040.1854387699514,9.8145612300486391,{"$f":"+IF(A418<>\"\",(A418-Report!D$19)^2,\"\")","v":44922.499173142634}]
[6043.77,6050,6042.6759433762554,7.3240566237445819,{"$f":"+IF(A419<>\"\",(A419-Report!D$19)^2,\"\")","v":45984.206709636681}]
[6058.34,6050,6057.2488960324199,-7.248896032419907,{"$f":"+IF(A420<>\"\",(A420-Report!D$19)^2,\"\")","v":52445.252358116057}]
[6060.13,6050,6059.0392587815295,-9.0392587815294974,{"$f":"+IF(A421<>\"\",(A421-Report!D$19)^2,\"\")","v":53268.309696398697}]
[6062.23,6050,6061.1396843531102,-11.139684353110169,{"$f":"+IF(A422<>\"\",(A422-Report!D$19)^2,\"\")","v":54242.076691031725}]
[6063.05,6050,6061.9598505286813,-11.959850528681272,{"$f":"+IF(A423<>\"\",(A423-Report!D$19)^2,\"\")","v":54624.703917507868}]
[6066.05,6050,6064.9604584880835,-14.960458488083532,{"$f":"+IF(A424<>\"\",(A424-Report!D$19)^2,\"\")","v":56036.019624126842}]
[6044.04,6060,6042.9459980926013,17.054001907398742,{"$f":"+IF(A425<>\"\",(A425-Report!D$19)^2,\"\")","v":46100.076823232186}]
[6046.05,6060,6044.9564054254015,15.043594574598501,{"$f":"+IF(A426<>\"\",(A426-Report!D$19)^2,\"\")","v":46967.24824666699}]
[6056.68,6060,6055.5885596282169,4.411440371783101,{"$f":"+IF(A427<>\"\",(A427-Report!D$19)^2,\"\")","v":51687.697133786955}]
[6060.56,6060,6059.4693459223772,0.53065407762278483,{"$f":"+IF(A428<>\"\",(A428-Report!D$19)^2,\"\")","v":53466.981981014214}]
[6070.17,6060,6069.0812934189962,-9.0812934189962107,{"$f":"+IF(A429<>\"\",(A429-Report!D$19)^2,\"\")","v":58003.560927883518}]
[6072.94,6060,6071.851854768177,-11.851854768176963,{"$f":"+IF(A430<>\"\",(A430-Report!D$19)^2,\"\")","v":59345.483463661476}]
[6075.04,6060,6073.9522803397595,-13.952280339759454,{"$f":"+IF(A431<>\"\",(A431-Report!D$19)^2,\"\")","v":60373.052458294944}]
[6044.33,6070,6043.2360568620106,26.763943137989372,{"$f":"+IF(A432<>\"\",(A432-Report!D$19)^2,\"\")","v":46224.692308205333}]
[6066.73,6070,6065.6405962922145,4.3594037077855319,{"$f":"+IF(A433<>\"\",(A433-Report!D$19)^2,\"\")","v":56358.420250960182}]
[6067.56,6070,6066.4707644943164,3.5292355056835731,{"$f":"+IF(A434<>\"\",(A434-Report!D$19)^2,\"\")","v":56753.191963125166}]
[6080.92,6070,6079.8334719401873,-9.8334719401873372,{"$f":"+IF(A435<>\"\",(A435-Report!D$19)^2,\"\")","v":63297.16804326819}]
[6081.73,6070,6080.6436360892258,-10.643636089225765,{"$f":"+IF(A436<>\"\",(A436-Report!D$19)^2,\"\")","v":63705.398784055054}]
[6083.84,6070,6082.7540636873391,-12.754063687339112,{"$f":"+IF(A437<>\"\",(A437-Report!D$19)^2,\"\")","v":64774.975864377368}]
[6058.26,6080,6057.1688798201685,22.831120179831487,{"$f":"+IF(A438<>\"\",(A438-Report!D$19)^2,\"\")","v":52408.61727260625}]
[6067.15,6080,6066.0606814065304,13.939318593469579,{"$f":"+IF(A439<>\"\",(A439-Report!D$19)^2,\"\")","v":56558.012049886878}]
[6079.11,6080,6078.0231051380142,1.9768948619857838,{"$f":"+IF(A440<>\"\",(A440-Report!D$19)^2,\"\")","v":62389.690933607875}]
[6082.44,6080,6081.3537799729511,-1.353779972951088,{"$f":"+IF(A441<>\"\",(A441-Report!D$19)^2,\"\")","v":64064.3098679549}]
[6083.62,6080,6082.5340191036494,-2.5340191036493707,{"$f":"+IF(A442<>\"\",(A442-Report!D$19)^2,\"\")","v":64663.04017922518}]
[6086.19,6080,6085.1045399222039,-5.1045399222039123,{"$f":"+IF(A443<>\"\",(A443-Report!D$19)^2,\"\")","v":65976.692001228614}]
[6087.98,6080,6086.8949026713144,-6.8949026713144121,{"$f":"+IF(A444<>\"\",(A444-Report!D$19)^2,\"\")","v":66899.452339511248}]
[6096.5,6080,6095.4166292760174,-15.416629276017375,{"$f":"+IF(A445<>\"\",(A445-Report!D$19)^2,\"\")","v":71379.426546309376}]
[6077.73,6090,6076.6428254766897,13.357174523310277,{"$f":"+IF(A446<>\"\",(A446-Report!D$19)^2,\"\")","v":61702.204508563089}]
[6081.7,6090,6080.6136300096323,9.3863699903677116,{"$f":"+IF(A447<>\"\",(A447-Report!D$19)^2,\"\")","v":63690.255726988995}]
[6085.33,6090,6084.2443656405094,5.7556343594906139,{"$f":"+IF(A448<>\"\",(A448-Report!D$19)^2,\"\")","v":65535.633631998011}]
[6094.07,6090,6092.9861368289012,-2.9861368289011807,{"$f":"+IF(A449<>\"\",(A449-Report!D$19)^2,\"\")","v":70086.88872394785}]
[6096.57,6090,6095.4866434617361,-5.4866434617360937,{"$f":"+IF(A450<>\"\",(A450-Report!D$19)^2,\"\")","v":71416.835146130325}]
[6097.32,6090,6096.2367954515867,{"$f":"+IF(B451<>\"\",B451-C451,\"\")","v":-6.2367954515866586},{"$f":"+IF(A451<>\"\",(A451-Report!D$19)^2,\"\")","v":71818.256572785074}]
[6100.21,6090,6099.127381119145,-9.1273811191449568,{"$f":"+IF(A452<>\"\",(A452-Report!D$19)^2,\"\")","v":73375.586736828191}]
[6100.97,6090,6099.8875351355273,-9.8875351355272869,{"$f":"+IF(A453<>\"\",(A453-Report!D$19)^2,\"\")","v":73787.900849171783}]
[6103.79,6090,6102.708106617365,-12.708106617365047,{"$f":"+IF(A454<>\"\",(A454-Report!D$19)^2,\"\")","v":75327.898813393462}]
[6081.94,6100,6080.8536786463837,19.146321353616258,{"$f":"+IF(A455<>\"\",(A455-Report!D$19)^2,\"\")","v":63811.450583518403}]
[6091.98,6100,6090.8957132838505,9.1042867161495451,{"$f":"+IF(A456<>\"\",(A456-Report!D$19)^2,\"\")","v":68984.646615003221}]
[6096.56,6100,6095.4766414352052,4.5233585647947621,{"$f":"+IF(A457<>\"\",(A457-Report!D$19)^2,\"\")","v":71411.490460441972}]
[6097.26,6100,6096.1767832923997,3.8232167076002952,{"$f":"+IF(A458<>\"\",(A458-Report!D$19)^2,\"\")","v":71786.101458652964}]
[6098.08,6100,6096.996949467969,3.0030505320310112,{"$f":"+IF(A459<>\"\",(A459-Report!D$19)^2,\"\")","v":72226.177885128665}]
[6102.39,6100,6101.307822902977,-1.3078229029770227,{"$f":"+IF(A460<>\"\",(A460-Report!D$19)^2,\"\")","v":74561.372816971474}]
[6103.22,6100,6102.137991105079,-2.1379911050789815,{"$f":"+IF(A461<>\"\",(A461-Report!D$19)^2,\"\")","v":75015.340129136021}]
[6107.12,6100,6106.038781452301,-6.0387814523010093,{"$f":"+IF(A462<>\"\",(A462-Report!D$19)^2,\"\")","v":77166.886547740491}]
[6108.76,6100,6107.6791138034414,-7.6791138034413962,{"$f":"+IF(A463<>\"\",(A463-Report!D$19)^2,\"\")","v":78080.725000692386}]
[6109.76,6100,6108.6793164565761,-8.679316456576089,{"$f":"+IF(A464<>\"\",(A464-Report!D$19)^2,\"\")","v":78640.583569565366}]
[6111.35,6100,6110.2696386750595,-10.269638675059468,{"$f":"+IF(A465<>\"\",(A465-Report!D$19)^2,\"\")","v":79534.876794073512}]
[6113.98,6100,6112.900171652801,-12.900171652800964,{"$f":"+IF(A466<>\"\",(A466-Report!D$19)^2,\"\")","v":81025.215130209035}]
[6106.17,6110,6105.0885889318242,4.9114110681757666,{"$f":"+IF(A467<>\"\",(A467-Report!D$19)^2,\"\")","v":76639.989407311252}]
[6112.29,6110,6111.2098291690045,-1.2098291690044789,{"$f":"+IF(A468<>\"\",(A468-Report!D$19)^2,\"\")","v":80065.956648813895}]
[6114.65,6110,6113.570307430401,-3.5703074304010443,{"$f":"+IF(A469<>\"\",(A469-Report!D$19)^2,\"\")","v":81407.094071353975}]
[6121.24,6110,6120.1616429145552,-10.161642914555159,{"$f":"+IF(A470<>\"\",(A470-Report!D$19)^2,\"\")","v":85211.030340227066}]
[6128.38,6110,6127.3030898579327,-17.303089857932719,{"$f":"+IF(A471<>\"\",(A471-Report!D$19)^2,\"\")","v":89430.474521980432}]
[6130,6110,6128.9234181560096,-18.923418156009575,{"$f":"+IF(A472<>\"\",(A472-Report!D$19)^2,\"\")","v":90402.018603554607}]
[6114.27,6120,6113.1902304222103,6.8097695777896661,{"$f":"+IF(A473<>\"\",(A473-Report!D$19)^2,\"\")","v":81190.395815182696}]
[6114.72,6120,6113.6403216161207,6.3596783838793272,{"$f":"+IF(A474<>\"\",(A474-Report!D$19)^2,\"\")","v":81447.04367117543}]
[6119.36,6120,6118.2812619266624,1.7187380733375903,{"$f":"+IF(A475<>\"\",(A475-Report!D$19)^2,\"\")","v":84116.985830745791}]
[6120.21,6120,6119.131434181827,0.86856581817301048,{"$f":"+IF(A476<>\"\",(A476-Report!D$19)^2,\"\")","v":84610.758114288037}]
[6120.61,6120,6119.5315152430803,0.46848475691967906,{"$f":"+IF(A477<>\"\",(A477-Report!D$19)^2,\"\")","v":84843.621541837027}]
[6131.8,6120,6130.7237829316518,-10.72378293165184,{"$f":"+IF(A478<>\"\",(A478-Report!D$19)^2,\"\")","v":91487.668027526102}]
[6116.64,6130,6115.5607107101387,14.439289289861335,{"$f":"+IF(A479<>\"\",(A479-Report!D$19)^2,\"\")","v":82546.624923411626}]
[6123.04,6130,6121.9620076901965,8.0379923098034851,{"$f":"+IF(A480<>\"\",(A480-Report!D$19)^2,\"\")","v":86265.143764198569}]
[6126.06,6130,6124.9826197026623,5.0173802973376951,{"$f":"+IF(A481<>\"\",(A481-Report!D$19)^2,\"\")","v":88048.268242195263}]
[6134.88,6130,6133.8044071033046,-3.8044071033045839,{"$f":"+IF(A482<>\"\",(A482-Report!D$19)^2,\"\")","v":93360.365219654879}]
[6135.09,6130,6134.0144496604626,-4.0144496604625601,{"$f":"+IF(A483<>\"\",(A483-Report!D$19)^2,\"\")","v":93488.740019118239}]
[6136.52,6130,6135.444739454445,-5.4447394544449708,{"$f":"+IF(A484<>\"\",(A484-Report!D$19)^2,\"\")","v":94365.256472606794}]
[6154.98,6130,6153.9084804312997,-23.908480431299722,{"$f":"+IF(A485<>\"\",(A485-Report!D$19)^2,\"\")","v":106047.45645400167}]
[6138.03,6140,6136.955045460677,3.0449545393230437,{"$f":"+IF(A486<>\"\",(A486-Report!D$19)^2,\"\")","v":95295.248211604587}]
[6145.24,6140,6144.1665065897732,-4.1665065897732347,{"$f":"+IF(A487<>\"\",(A487-Report!D$19)^2,\"\")","v":99798.675993178869}]
[6149.48,6140,6148.4073658390616,-8.4073658390616401,{"$f":"+IF(A488<>\"\",(A488-Report!D$19)^2,\"\")","v":102495.56432520022}]
[6150.27,6140,6149.1975259350393,-9.1975259350392662,{"$f":"+IF(A489<>\"\",(A489-Report!D$19)^2,\"\")","v":103002.02429461044}]
[6150.62,6140,6149.5475968636356,-9.5475968636355901,{"$f":"+IF(A490<>\"\",(A490-Report!D$19)^2,\"\")","v":103226.80429371564}]
[6160.05,6140,6158.9795078826901,-18.979507882690086,{"$f":"+IF(A491<>\"\",(A491-Report!D$19)^2,\"\")","v":109375.24509818816}]
[6138.1,6150,6137.0250596463966,12.974940353603415,{"$f":"+IF(A492<>\"\",(A492-Report!D$19)^2,\"\")","v":95338.471011426082}]
[6140.16,6150,6139.085477111852,10.914522888147985,{"$f":"+IF(A493<>\"\",(A493-Report!D$19)^2,\"\")","v":96614.844063304117}]
[6147.98,6150,6146.9070618593605,3.0929381406394896,{"$f":"+IF(A494<>\"\",(A494-Report!D$19)^2,\"\")","v":101537.36647189074}]
[6148.83,6150,6147.7572341145251,2.2427658854749097,{"$f":"+IF(A495<>\"\",(A495-Report!D$19)^2,\"\")","v":102079.79275543301}]
[6154.31,6150,6153.2383446537006,-3.2383446537005511,{"$f":"+IF(A496<>\"\",(A496-Report!D$19)^2,\"\")","v":105611.53531285732}]
[6158.74,6150,6157.6692424070843,-7.6692424070843117,{"$f":"+IF(A497<>\"\",(A497-Report!D$19)^2,\"\")","v":108510.47667296427}]
[6170.02,6150,6168.9515283344372,-18.951528334437171,{"$f":"+IF(A498<>\"\",(A498-Report!D$19)^2,\"\")","v":116069.18852985206}]
[6173.3,6150,6172.232193036717,-22.232193036717035,{"$f":"+IF(A499<>\"\",(A499-Report!D$19)^2,\"\")","v":118314.86863575531}]
[6138.71,6160,6137.6351832648079,22.364816735192107,{"$f":"+IF(A500<>\"\",(A500-Report!D$19)^2,\"\")","v":95715.541638438401}]
[6152.24,6160,6151.1679251617124,8.8320748382875536,{"$f":"+IF(A501<>\"\",(A501-Report!D$19)^2,\"\")","v":104270.40597528982}]
[6158.77,6160,6157.6992484866787,2.3007515133213019,{"$f":"+IF(A502<>\"\",(A502-Report!D$19)^2,\"\")","v":108530.24213003089}]
[6161.44,6160,6160.3697895705463,-0.3697895705463452,{"$f":"+IF(A503<>\"\",(A503-Report!D$19)^2,\"\")","v":110296.57680892122}]
[6169.59,6160,6168.5214411935895,-8.5214411935894532,{"$f":"+IF(A504<>\"\",(A504-Report!D$19)^2,\"\")","v":115776.38064523648}]
[6170.59,6160,6169.5216438467241,-9.521643846724146,{"$f":"+IF(A505<>\"\",(A505-Report!D$19)^2,\"\")","v":116457.89921410946}]
[6170.94,6160,6169.8717147753205,-9.8717147753204699,{"$f":"+IF(A506<>\"\",(A506-Report!D$19)^2,\"\")","v":116696.90321321464}]
[6173.59,6160,6172.5222518061264,-12.522251806126405,{"$f":"+IF(A507<>\"\",(A507-Report!D$19)^2,\"\")","v":118514.45492072844}]
[6162.42,6170,6161.3499881706184,8.6500118293815831,{"$f":"+IF(A508<>\"\",(A508-Report!D$19)^2,\"\")","v":110948.47140641707}]
[6163.13,6170,6162.0601320543428,7.9398679456571699,{"$f":"+IF(A509<>\"\",(A509-Report!D$19)^2,\"\")","v":111421.96229031692}]
[6164.18,6170,6163.1103448401345,6.8896551598654696,{"$f":"+IF(A510<>\"\",(A510-Report!D$19)^2,\"\")","v":112124.04328763369}]
[6167.79,6170,6166.7210764179481,3.2789235820519025,{"$f":"+IF(A511<>\"\",(A511-Report!D$19)^2,\"\")","v":114554.68722126496}]
[6173.22,6170,6172.1521768244666,-2.1521768244665509,{"$f":"+IF(A512<>\"\",(A512-Report!D$19)^2,\"\")","v":118259.83995024551}]
[6176.1,6170,6175.0327604654931,-5.0327604654930838,{"$f":"+IF(A513<>\"\",(A513-Report!D$19)^2,\"\")","v":120248.93662859981}]
[6176.88,6180,6175.8129185349371,4.1870814650628745,{"$f":"+IF(A514<>\"\",(A514-Report!D$19)^2,\"\")","v":120790.50511232056}]
[6177.46,6180,6176.393036073755,{"$f":"+IF(B515<>\"\",B515-C515,\"\")","v":3.6069639262450437},{"$f":"+IF(A515<>\"\",(A515-Report!D$19)^2,\"\")","v":121193.99868226684}]
[6178.02,6180,6176.9531495595102,3.046850440489834,{"$f":"+IF(A516<>\"\",(A516-Report!D$19)^2,\"\")","v":121584.21708083601}]
[6183.73,6180,6182.6643067089053,-2.6643067089053147,{"$f":"+IF(A517<>\"\",(A517-Report!D$19)^2,\"\")","v":125598.85280910018}]
[6164.34,6190,6163.2703772646355,26.729622735364501,{"$f":"+IF(A518<>\"\",(A518-Report!D$19)^2,\"\")","v":112231.22065865327}]
[6193.05,6190,6191.9861954361158,-1.9861954361158496,{"$f":"+IF(A519<>\"\",(A519-Report!D$19)^2,\"\")","v":132291.71787099692}]
[6180.97,6200,6179.9037473862563,20.096252613743673,{"$f":"+IF(A520<>\"\",(A520-Report!D$19)^2,\"\")","v":123650.1863590112}]
[6181.76,6200,6180.6939074822321,19.306092517767866,{"$f":"+IF(A521<>\"\",(A521-Report!D$19)^2,\"\")","v":124206.40052842084}]
[6186.05,6200,6184.9847768641775,15.015223135822453,{"$f":"+IF(A522<>\"\",(A522-Report!D$19)^2,\"\")","v":127248.64788888596}]
[6190.05,6200,6188.9855874767136,11.01441252328641,{"$f":"+IF(A523<>\"\",(A523-Report!D$19)^2,\"\")","v":130118.40216437793}]
[6191.67,6200,6190.6059157747904,9.3940842252095536,{"$f":"+IF(A524<>\"\",(A524-Report!D$19)^2,\"\")","v":131289.75704595211}]
[6202.01,6200,6200.9480112081974,-0.94801120819738571,{"$f":"+IF(A525<>\"\",(A525-Report!D$19)^2,\"\")","v":138889.84904809896}]
[6206.43,6200,6205.3689069350503,-5.3689069350502905,{"$f":"+IF(A526<>\"\",(A526-Report!D$19)^2,\"\")","v":142203.87032251764}]
[6214.36,6200,6213.3005139744037,-13.300513974403657,{"$f":"+IF(A527<>\"\",(A527-Report!D$19)^2,\"\")","v":148247.54987367999}]
[6194.38,6210,6193.3164649647842,16.683535035215755,{"$f":"+IF(A528<>\"\",(A528-Report!D$19)^2,\"\")","v":133260.98006759793}]
[6202.08,6210,6201.018025393917,8.9819746060829857,{"$f":"+IF(A529<>\"\",(A529-Report!D$19)^2,\"\")","v":138942.02904791984}]
[6207.29,6210,6206.2290812167457,3.7709187832542739,{"$f":"+IF(A530<>\"\",(A530-Report!D$19)^2,\"\")","v":142853.22069174817}]
[6211.62,6210,6210.5599587048164,-0.55995870481638121,{"$f":"+IF(A531<>\"\",(A531-Report!D$19)^2,\"\")","v":146145.09699496816}]
[6218.51,6220,6217.4513549849107,2.5486450150892779,{"$f":"+IF(A532<>\"\",(A532-Report!D$19)^2,\"\")","v":151460.51543450332}]
[6231.95,6220,6230.894078643033,-10.894078643033026,{"$f":"+IF(A533<>\"\",(A533-Report!D$19)^2,\"\")","v":162102.28820015604}]
[6211.61,6230,6210.5499566782846,19.450043321715384,{"$f":"+IF(A534<>\"\",(A534-Report!D$19)^2,\"\")","v":146137.45130927925}]
[6227.69,6230,6226.6332153406811,3.3667846593189097,{"$f":"+IF(A535<>\"\",(A535-Report!D$19)^2,\"\")","v":158690.1194967569}]
[6232.1,6230,6231.0441090410031,-1.0441090410031393,{"$f":"+IF(A536<>\"\",(A536-Report!D$19)^2,\"\")","v":162223.09648548742}]
[6236.38,6230,6235.3249763964168,-5.3249763964167869,{"$f":"+IF(A537<>\"\",(A537-Report!D$19)^2,\"\")","v":165689.1199602636}]
[6228.52,6240,6227.463383542783,12.536616457216951,{"$f":"+IF(A538<>\"\",(A538-Report!D$19)^2,\"\")","v":159352.08480892217}]
[6266.58,6250,6265.5310965210674,-15.531096521067411,{"$f":"+IF(A539<>\"\",(A539-Report!D$19)^2,\"\")","v":191186.93674022783}]
[6251.13,6270,6250.0779655301449,19.922034469855134,{"$f":"+IF(A540<>\"\",(A540-Report!D$19)^2,\"\")","v":177914.63635114025}]
[6258.08,6270,6257.0293739694271,12.97062603057293,{"$f":"+IF(A541<>\"\",(A541-Report!D$19)^2,\"\")","v":183825.94890480739}]
[6273.42,6270,6272.3724826685047,-2.3724826685047447,{"$f":"+IF(A542<>\"\",(A542-Report!D$19)^2,\"\")","v":197215.29255131923}]
[6278.24,6290,6277.193459456611,12.806540543389019,{"$f":"+IF(A543<>\"\",(A543-Report!D$19)^2,\"\")","v":201519.5456532868}]
[6281.88,6290,6280.8341971140189,9.1658028859810656,{"$f":"+IF(A544<>\"\",(A544-Report!D$19)^2,\"\")","v":204800.85484398477}]
[6291.5,6300,6290.4561466371697,9.5438533628303048,{"$f":"+IF(A545<>\"\",(A545-Report!D$19)^2,\"\")","v":213600.44747654287}]
[6315.12,6300,6314.0809333041971,-14.08093330419706,{"$f":"+IF(A546<>\"\",(A546-Report!D$19)^2,\"\")","v":235991.22887332283}]
[6298.15,6310,6297.1074942805108,12.892505719489236,{"$f":"+IF(A547<>\"\",(A547-Report!D$19)^2,\"\")","v":219791.52145954792}]
[6302.83,6310,6301.7884426971787,8.2115573028213475,{"$f":"+IF(A548<>\"\",(A548-Report!D$19)^2,\"\")","v":224201.57236187378}]
[6307.57,6310,6306.5294032730344,3.4705967269655957,{"$f":"+IF(A549<>\"\",(A549-Report!D$19)^2,\"\")","v":228712.81317833156}]
[6315.11,6310,6314.0709312776653,-4.0709312776652951,{"$f":"+IF(A550<>\"\",(A550-Report!D$19)^2,\"\")","v":235981.51318763389}]
[6321.26,6310,6320.2221775944408,-10.222177594440836,{"$f":"+IF(A551<>\"\",(A551-Report!D$19)^2,\"\")","v":241994.42088620333}]
[6316.07,6320,6315.0311258246738,4.9688741753261638,{"$f":"+IF(A552<>\"\",(A552-Report!D$19)^2,\"\")","v":236915.13101375199}]
[6342.87,6340,6341.8365569286689,-1.8365569286688697,{"$f":"+IF(A553<>\"\",(A553-Report!D$19)^2,\"\")","v":263722.59665954835}]
[6339.88,6360,6338.8459509957975,21.154049004202534,{"$f":"+IF(A554<>\"\",(A554-Report!D$19)^2,\"\")","v":260660.57183861834}]
[6362.51,6360,6361.4805370362228,-1.4805370362228132,{"$f":"+IF(A555<>\"\",(A555-Report!D$19)^2,\"\")","v":284280.1493522143}]
[6393.86,6380,6392.8368902119773,-12.836890211977334,{"$f":"+IF(A556<>\"\",(A556-Report!D$19)^2,\"\")","v":318693.31298638199}]
[6400.03,6400,6399.0081405818146,0.99185941818541323,{"$f":"+IF(A557<>\"\",(A557-Report!D$19)^2,\"\")","v":325697.67325632845}]
[6406.39,6430,6405.3694294557481,24.630570544251896,{"$f":"+IF(A558<>\"\",(A558-Report!D$19)^2,\"\")","v":332997.41775436135}]
[6463.71,6470,6462.7010455333948,7.2989544666052097,{"$f":"+IF(A559<>\"\",(A559-Report!D$19)^2,\"\")","v":402437.0765221609}]
[6474.15,6480,6473.1431612321148,6.856838767885165,{"$f":"+IF(A560<>\"\",(A560-Report!D$19)^2,\"\")","v":415791.9095811944}]
[null,null,null,"",{"$f":"+IF(A561<>\"\",(A561-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A562<>\"\",(A562-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A563<>\"\",(A563-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A564<>\"\",(A564-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A565<>\"\",(A565-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A566<>\"\",(A566-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A567<>\"\",(A567-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A568<>\"\",(A568-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A569<>\"\",(A569-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A570<>\"\",(A570-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A571<>\"\",(A571-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A572<>\"\",(A572-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A573<>\"\",(A573-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A574<>\"\",(A574-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A575<>\"\",(A575-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A576<>\"\",(A576-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A577<>\"\",(A577-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A578<>\"\",(A578-Report!D$19)^2,\"\")","v":""}]
[null,null,null,{"$f":"+IF(B579<>\"\",B579-C579,\"\")","v":""},{"$f":"+IF(A579<>\"\",(A579-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A580<>\"\",(A580-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A581<>\"\",(A581-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A582<>\"\",(A582-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A583<>\"\",(A583-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A584<>\"\",(A584-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A585<>\"\",(A585-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A586<>\"\",(A586-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A587<>\"\",(A587-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A588<>\"\",(A588-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A589<>\"\",(A589-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A590<>\"\",(A590-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A591<>\"\",(A591-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A592<>\"\",(A592-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A593<>\"\",(A593-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A594<>\"\",(A594-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A595<>\"\",(A595-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A596<>\"\",(A596-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A597<>\"\",(A597-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A598<>\"\",(A598-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A599<>\"\",(A599-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A600<>\"\",(A600-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A601<>\"\",(A601-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A602<>\"\",(A602-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A603<>\"\",(A603-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A604<>\"\",(A604-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A605<>\"\",(A605-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A606<>\"\",(A606-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A607<>\"\",(A607-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A608<>\"\",(A608-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A609<>\"\",(A609-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A610<>\"\",(A610-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A611<>\"\",(A611-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A612<>\"\",(A612-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A613<>\"\",(A613-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A614<>\"\",(A614-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A615<>\"\",(A615-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A616<>\"\",(A616-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A617<>\"\",(A617-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A618<>\"\",(A618-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A619<>\"\",(A619-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A620<>\"\",(A620-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A621<>\"\",(A621-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A622<>\"\",(A622-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A623<>\"\",(A623-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A624<>\"\",(A624-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A625<>\"\",(A625-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A626<>\"\",(A626-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A627<>\"\",(A627-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A628<>\"\",(A628-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A629<>\"\",(A629-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A630<>\"\",(A630-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A631<>\"\",(A631-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A632<>\"\",(A632-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A633<>\"\",(A633-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A634<>\"\",(A634-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A635<>\"\",(A635-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A636<>\"\",(A636-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A637<>\"\",(A637-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A638<>\"\",(A638-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A639<>\"\",(A639-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A640<>\"\",(A640-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A641<>\"\",(A641-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A642<>\"\",(A642-Report!D$19)^2,\"\")","v":""}]
[null,null,null,{"$f":"+IF(B643<>\"\",B643-C643,\"\")","v":""},{"$f":"+IF(A643<>\"\",(A643-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A644<>\"\",(A644-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A645<>\"\",(A645-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A646<>\"\",(A646-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A647<>\"\",(A647-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A648<>\"\",(A648-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A649<>\"\",(A649-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A650<>\"\",(A650-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A651<>\"\",(A651-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A652<>\"\",(A652-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A653<>\"\",(A653-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A654<>\"\",(A654-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A655<>\"\",(A655-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A656<>\"\",(A656-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A657<>\"\",(A657-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A658<>\"\",(A658-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A659<>\"\",(A659-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A660<>\"\",(A660-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A661<>\"\",(A661-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A662<>\"\",(A662-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A663<>\"\",(A663-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A664<>\"\",(A664-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A665<>\"\",(A665-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A666<>\"\",(A666-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A667<>\"\",(A667-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A668<>\"\",(A668-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A669<>\"\",(A669-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A670<>\"\",(A670-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A671<>\"\",(A671-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A672<>\"\",(A672-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A673<>\"\",(A673-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A674<>\"\",(A674-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A675<>\"\",(A675-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A676<>\"\",(A676-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A677<>\"\",(A677-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A678<>\"\",(A678-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A679<>\"\",(A679-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A680<>\"\",(A680-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A681<>\"\",(A681-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A682<>\"\",(A682-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A683<>\"\",(A683-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A684<>\"\",(A684-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A685<>\"\",(A685-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A686<>\"\",(A686-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A687<>\"\",(A687-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A688<>\"\",(A688-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A689<>\"\",(A689-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A690<>\"\",(A690-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A691<>\"\",(A691-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A692<>\"\",(A692-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A693<>\"\",(A693-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A694<>\"\",(A694-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A695<>\"\",(A695-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A696<>\"\",(A696-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A697<>\"\",(A697-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A698<>\"\",(A698-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A699<>\"\",(A699-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A700<>\"\",(A700-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A701<>\"\",(A701-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A702<>\"\",(A702-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A703<>\"\",(A703-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A704<>\"\",(A704-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A705<>\"\",(A705-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A706<>\"\",(A706-Report!D$19)^2,\"\")","v":""}]
[null,null,null,{"$f":"+IF(B707<>\"\",B707-C707,\"\")","v":""},{"$f":"+IF(A707<>\"\",(A707-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A708<>\"\",(A708-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A709<>\"\",(A709-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A710<>\"\",(A710-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A711<>\"\",(A711-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A712<>\"\",(A712-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A713<>\"\",(A713-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A714<>\"\",(A714-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A715<>\"\",(A715-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A716<>\"\",(A716-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A717<>\"\",(A717-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A718<>\"\",(A718-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A719<>\"\",(A719-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A720<>\"\",(A720-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A721<>\"\",(A721-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A722<>\"\",(A722-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A723<>\"\",(A723-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A724<>\"\",(A724-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A725<>\"\",(A725-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A726<>\"\",(A726-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A727<>\"\",(A727-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A728<>\"\",(A728-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A729<>\"\",(A729-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A730<>\"\",(A730-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A731<>\"\",(A731-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A732<>\"\",(A732-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A733<>\"\",(A733-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A734<>\"\",(A734-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A735<>\"\",(A735-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A736<>\"\",(A736-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A737<>\"\",(A737-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A738<>\"\",(A738-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A739<>\"\",(A739-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A740<>\"\",(A740-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A741<>\"\",(A741-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A742<>\"\",(A742-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A743<>\"\",(A743-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A744<>\"\",(A744-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A745<>\"\",(A745-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A746<>\"\",(A746-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A747<>\"\",(A747-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A748<>\"\",(A748-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A749<>\"\",(A749-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A750<>\"\",(A750-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A751<>\"\",(A751-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A752<>\"\",(A752-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A753<>\"\",(A753-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A754<>\"\",(A754-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A755<>\"\",(A755-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A756<>\"\",(A756-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A757<>\"\",(A757-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A758<>\"\",(A758-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A759<>\"\",(A759-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A760<>\"\",(A760-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A761<>\"\",(A761-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A762<>\"\",(A762-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A763<>\"\",(A763-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A764<>\"\",(A764-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A765<>\"\",(A765-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A766<>\"\",(A766-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A767<>\"\",(A767-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A768<>\"\",(A768-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A769<>\"\",(A769-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A770<>\"\",(A770-Report!D$19)^2,\"\")","v":""}]
[null,null,null,{"$f":"+IF(B771<>\"\",B771-C771,\"\")","v":""},{"$f":"+IF(A771<>\"\",(A771-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A772<>\"\",(A772-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A773<>\"\",(A773-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A774<>\"\",(A774-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A775<>\"\",(A775-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A776<>\"\",(A776-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A777<>\"\",(A777-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A778<>\"\",(A778-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A779<>\"\",(A779-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A780<>\"\",(A780-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A781<>\"\",(A781-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A782<>\"\",(A782-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A783<>\"\",(A783-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A784<>\"\",(A784-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A785<>\"\",(A785-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A786<>\"\",(A786-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A787<>\"\",(A787-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A788<>\"\",(A788-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A789<>\"\",(A789-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A790<>\"\",(A790-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A791<>\"\",(A791-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A792<>\"\",(A792-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A793<>\"\",(A793-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A794<>\"\",(A794-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A795<>\"\",(A795-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A796<>\"\",(A796-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A797<>\"\",(A797-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A798<>\"\",(A798-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A799<>\"\",(A799-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A800<>\"\",(A800-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A801<>\"\",(A801-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A802<>\"\",(A802-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A803<>\"\",(A803-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A804<>\"\",(A804-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A805<>\"\",(A805-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A806<>\"\",(A806-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A807<>\"\",(A807-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A808<>\"\",(A808-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A809<>\"\",(A809-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A810<>\"\",(A810-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A811<>\"\",(A811-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A812<>\"\",(A812-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A813<>\"\",(A813-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A814<>\"\",(A814-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A815<>\"\",(A815-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A816<>\"\",(A816-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A817<>\"\",(A817-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A818<>\"\",(A818-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A819<>\"\",(A819-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A820<>\"\",(A820-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A821<>\"\",(A821-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A822<>\"\",(A822-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A823<>\"\",(A823-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A824<>\"\",(A824-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A825<>\"\",(A825-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A826<>\"\",(A826-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A827<>\"\",(A827-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A828<>\"\",(A828-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A829<>\"\",(A829-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A830<>\"\",(A830-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A831<>\"\",(A831-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A832<>\"\",(A832-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A833<>\"\",(A833-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A834<>\"\",(A834-Report!D$19)^2,\"\")","v":""}]
[null,null,null,{"$f":"+IF(B835<>\"\",B835-C835,\"\")","v":""},{"$f":"+IF(A835<>\"\",(A835-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A836<>\"\",(A836-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A837<>\"\",(A837-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A838<>\"\",(A838-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A839<>\"\",(A839-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A840<>\"\",(A840-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A841<>\"\",(A841-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A842<>\"\",(A842-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A843<>\"\",(A843-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A844<>\"\",(A844-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A845<>\"\",(A845-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A846<>\"\",(A846-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A847<>\"\",(A847-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A848<>\"\",(A848-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A849<>\"\",(A849-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A850<>\"\",(A850-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A851<>\"\",(A851-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A852<>\"\",(A852-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A853<>\"\",(A853-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A854<>\"\",(A854-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A855<>\"\",(A855-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A856<>\"\",(A856-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A857<>\"\",(A857-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A858<>\"\",(A858-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A859<>\"\",(A859-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A860<>\"\",(A860-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A861<>\"\",(A861-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A862<>\"\",(A862-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A863<>\"\",(A863-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A864<>\"\",(A864-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A865<>\"\",(A865-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A866<>\"\",(A866-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A867<>\"\",(A867-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A868<>\"\",(A868-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A869<>\"\",(A869-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A870<>\"\",(A870-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A871<>\"\",(A871-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A872<>\"\",(A872-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A873<>\"\",(A873-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A874<>\"\",(A874-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A875<>\"\",(A875-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A876<>\"\",(A876-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A877<>\"\",(A877-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A878<>\"\",(A878-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A879<>\"\",(A879-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A880<>\"\",(A880-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A881<>\"\",(A881-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A882<>\"\",(A882-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A883<>\"\",(A883-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A884<>\"\",(A884-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A885<>\"\",(A885-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A886<>\"\",(A886-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A887<>\"\",(A887-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A888<>\"\",(A888-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A889<>\"\",(A889-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A890<>\"\",(A890-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A891<>\"\",(A891-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A892<>\"\",(A892-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A893<>\"\",(A893-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A894<>\"\",(A894-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A895<>\"\",(A895-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A896<>\"\",(A896-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A897<>\"\",(A897-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A898<>\"\",(A898-Report!D$19)^2,\"\")","v":""}]
[null,null,null,{"$f":"+IF(B899<>\"\",B899-C899,\"\")","v":""},{"$f":"+IF(A899<>\"\",(A899-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A900<>\"\",(A900-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A901<>\"\",(A901-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A902<>\"\",(A902-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A903<>\"\",(A903-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A904<>\"\",(A904-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A905<>\"\",(A905-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A906<>\"\",(A906-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A907<>\"\",(A907-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A908<>\"\",(A908-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A909<>\"\",(A909-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A910<>\"\",(A910-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A911<>\"\",(A911-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A912<>\"\",(A912-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A913<>\"\",(A913-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A914<>\"\",(A914-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A915<>\"\",(A915-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A916<>\"\",(A916-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A917<>\"\",(A917-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A918<>\"\",(A918-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A919<>\"\",(A919-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A920<>\"\",(A920-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A921<>\"\",(A921-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A922<>\"\",(A922-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A923<>\"\",(A923-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A924<>\"\",(A924-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A925<>\"\",(A925-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A926<>\"\",(A926-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A927<>\"\",(A927-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A928<>\"\",(A928-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A929<>\"\",(A929-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A930<>\"\",(A930-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A931<>\"\",(A931-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A932<>\"\",(A932-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A933<>\"\",(A933-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A934<>\"\",(A934-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A935<>\"\",(A935-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A936<>\"\",(A936-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A937<>\"\",(A937-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A938<>\"\",(A938-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A939<>\"\",(A939-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A940<>\"\",(A940-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A941<>\"\",(A941-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A942<>\"\",(A942-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A943<>\"\",(A943-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A944<>\"\",(A944-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A945<>\"\",(A945-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A946<>\"\",(A946-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A947<>\"\",(A947-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A948<>\"\",(A948-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A949<>\"\",(A949-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A950<>\"\",(A950-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A951<>\"\",(A951-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A952<>\"\",(A952-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A953<>\"\",(A953-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A954<>\"\",(A954-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A955<>\"\",(A955-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A956<>\"\",(A956-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A957<>\"\",(A957-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A958<>\"\",(A958-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A959<>\"\",(A959-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A960<>\"\",(A960-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A961<>\"\",(A961-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A962<>\"\",(A962-Report!D$19)^2,\"\")","v":""}]
[null,null,null,{"$f":"+IF(B963<>\"\",B963-C963,\"\")","v":""},{"$f":"+IF(A963<>\"\",(A963-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A964<>\"\",(A964-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A965<>\"\",(A965-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A966<>\"\",(A966-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A967<>\"\",(A967-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A968<>\"\",(A968-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A969<>\"\",(A969-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A970<>\"\",(A970-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A971<>\"\",(A971-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A972<>\"\",(A972-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A973<>\"\",(A973-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A974<>\"\",(A974-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A975<>\"\",(A975-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A976<>\"\",(A976-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A977<>\"\",(A977-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A978<>\"\",(A978-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A979<>\"\",(A979-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A980<>\"\",(A980-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A981<>\"\",(A981-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A982<>\"\",(A982-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A983<>\"\",(A983-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A984<>\"\",(A984-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A985<>\"\",(A985-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A986<>\"\",(A986-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A987<>\"\",(A987-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A988<>\"\",(A988-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A989<>\"\",(A989-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A990<>\"\",(A990-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A991<>\"\",(A991-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A992<>\"\",(A992-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A993<>\"\",(A993-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A994<>\"\",(A994-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A995<>\"\",(A995-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A996<>\"\",(A996-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A997<>\"\",(A997-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A998<>\"\",(A998-Report!D$19)^2,\"\")","v":""}]
[null,null,null,"",{"$f":"+IF(A999<>\"\",(A999-Report!D$19)^2,\"\")","v":""}]
[null,null,null,""]
[null,null,null,""]

{"sheet":"Relative Precision","index":2,"n_rows":11,"n_cols":2,"rows_kept":11,"cut":false,"hidden":false,"merged":[]}
[]
[]
[]
["Alternative Method (X)"]
["Average:…………………………..",{"$f":"AVERAGE('Data Entry'!A:A)","v":5829.3307155635039}]
[]
["Designated Method (Y)"]
["Average:…………………………..",{"$f":"AVERAGE('Data Entry'!B:B)","v":5828.193202146691}]
[]
["Change of Mean %"]
["(Ybar-Xbar)/Ybar",{"$f":"(B8-B5)/B8","v":-1.9517428083782966E-4}]

{"sheet":"Report","index":3,"n_rows":29,"n_cols":11,"rows_kept":29,"cut":false,"hidden":false,"merged":[]}
["CARB Site Specific Test Method Certification",null,null,null,null,null,"Date",null,null,null,{"$f":"+'General Info'!B4","v":"2004-03-16"}]
[{"$f":"'General Info'!B3","v":"Hypothetical Analytical Case"},null,null,null,null,null,"Refinery Name",null,null,null,{"$f":"+'General Info'!B5","v":"ABC Refining Company"}]
[null,null,null,null,null,null,"Refinery location",null,null,null,{"$f":"+'General Info'!B6","v":"Somewhere, CA"}]
[null,null,null,null,null,null,"Gasoline Property",null,null,null,{"$f":"+'General Info'!B7","v":"Length"}]
[null,null,null,null,null,null,"Alternative Test Method",null,null,null,{"$f":"+'General Info'!B9","v":"Laser measurement"}]
[null,null,null,null,null,null,"Designated Test Method",null,null,null,{"$f":"+'General Info'!B10","v":"Tape measurement"}]
["For regression equation"]
[]
[null,"b0",null,{"$f":"+'Data Entry'!U2","v":-2.3188455561084993},null,null,"Coefficient Values"]
[null,"b1",null,{"$f":"+'Data Entry'!T2","v":1.0002026531341139},null,null,null,null,"Standard"]
[null,"r2",null,{"$f":"+'Data Entry'!T4","v":0.99806956999990681},null,null,null,"Coefficients","Error","t Stat","P-value"]
[null,"F",null,{"$f":"+K17","v":287979.75086541055},null,null,"Intercept",{"$f":"+D9","v":-2.3188455561084993},{"$f":"+'Data Entry'!U3","v":10.876153334349615},{"$f":"+H12/I12","v":-0.21320456643296895},{"$f":"TDIST(ABS(J12),D13,2)","v":0.83124541760657156}]
[null,"d.f.",null,{"$f":"+'Data Entry'!U5","v":557},null,null,"X Variable",{"$f":"+D10","v":1.0002026531341139},{"$f":"+'Data Entry'!T3","v":1.8638331268044049E-3},{"$f":"+H13/I13","v":536.63744825106198},{"$f":"TDIST(ABS(J13),D13,2)","v":0}]
[null,"s",null,{"$f":"+'Data Entry'!U4","v":11.694797133993346}]
[null,"Std Error, b0",null,{"$f":"+'Data Entry'!U3","v":10.876153334349615},null,null,"ANOVA"]
[null,"Std Error, b1",null,{"$f":"+'Data Entry'!T3","v":1.8638331268044049E-3},null,null,null,"df","SS","MS","F"]
[null,"a1",null,{"$f":"+'Data Entry'!G3","v":2.5000000000000001E-2},null,null,"Regression",1,{"$f":"+'Data Entry'!T6","v":39386495.202205189},{"$f":"+I17/H17","v":39386495.202205189},{"$f":"+J17/J18","v":287979.75086541055}]
[null,"BF Constant",null,{"$f":"+'Data Entry'!V17","v":2.476},null,null,"Residual",{"$f":"+D13","v":557},{"$f":"+'Data Entry'!U6","v":76179.931962929244},{"$f":"+I18/H18","v":136.76828000525896}]
[null,"Xbar",null,{"$f":"AVERAGE('Data Entry'!A2:A999)","v":5829.3307155635039},null,null,"Total",{"$f":"+H17+H18","v":558},{"$f":"+I18+I17","v":39462675.134168118}]
[null,"S(X-Xbar)2",null,{"$f":"SUM('Data Entry'!E2:E999)","v":39370536.460113734}]
[null,"a2",null,{"$f":"+'Data Entry'!H3","v":2.5000000000000001E-2}]
[null,"C2",null,{"$f":"CHIINV(1-D21,COUNT('Data Entry'!A2:A999)-2)","v":493.49740055443095}]
[null,"Sucb",null,{"$f":"SQRT((COUNT('Data Entry'!A2:A999)-2)*D14^2/D22)","v":12.424469535048432}]
[null,"XDRESucb",null,{"$f":"1.645*D23","v":20.438252385154673}]
[null,"Anderson-Darling, Crit",null,{"$f":"+'Normal Plot Data Sheet'!M4","v":1}]
[null,"Anderson-Darling, Calc",null,{"$f":"+'Normal Plot Data Sheet'!K5","v":0.32666607944264037}]
[]
[null,"r2 greater than 0.8",null,{"$f":"IF(D11>=0.8,\"Pass\",\"Fail\")","v":"Pass"}]
[null,"Upper Bound Determination",null,{"$f":"IF(SUM('Data Entry'!P10:P50)=0,\"Pass\",\"Fail\")","v":"Pass"}]

{"sheet":"Normal Plot Data Sheet","index":9,"n_rows":562,"n_cols":18,"rows_kept":562,"cut":false,"hidden":false,"merged":[]}
[null,null,null,null,null,null,null,null,null,"n=",{"$f":"COUNT(A4:A1003)","v":559},null,null,null,0]
["Resid","Resid","Rank","Rank","Used to Calculate",null,null,null,null,"mean=",{"$f":"AVERAGE(A4:A1003)","v":-2.8374933092879908E-12}]
["Y-Yhat","(in Z)",null,"(in Z)","Anderson-Darlilng",null,null,null,null,"std. dev.=",{"$f":"STDEV(A4:A1003)","v":11.684313225894332}]
[-39.83942090403707,{"$f":"+IF(A4<>\"\",(A4-K$2)/K$3,\"\")","v":-3.4096501979888405},{"$f":"IF(A4<>\"\",RANK(A4,A$4:A$1003,1)+SUM(IF(A$4:A4=A4,1,0))-1.5,\"\")","v":0.5},{"$f":"IF(A4<>\"\",NORMSINV(C4/($K$1)),\"\")","v":-3.1232086556278902},{"$f":"IF(A4<>\"\",NORMDIST(A4,$K$2,$K$3,1),\"\")","v":3.2523124911306768E-4},{"$f":"IF(A4<>\"\",-2*C4*LN(E4)-(2*$K$1-2*C4)*LN(1-E4),\"\")","v":8.3943164865363968},null,null,null,null,null,"crit. Val",1]
[-35.373810857505305,{"$f":"+IF(A5<>\"\",(A5-K$2)/K$3,\"\")","v":-3.0274617064448743},{"$f":"IF(A5<>\"\",RANK(A5,A$4:A$1003,1)+SUM(IF(A$4:A5=A5,1,0))-1.5,\"\")","v":1.5},{"$f":"IF(A5<>\"\",NORMSINV(C5/($K$1)),\"\")","v":-2.784155712066708},{"$f":"IF(A5<>\"\",NORMDIST(A5,$K$2,$K$3,1),\"\")","v":1.233084792500806E-3},{"$f":"IF(A5<>\"\",-2*C5*LN(E5)-(2*$K$1-2*C5)*LN(1-E5),\"\")","v":21.470446782521744},null,null,null,"A*=",{"$f":"(SUM(F4:F1003)/$K$1-$K$1)*(1+0.75/$K$1+2.25/$K$1^2)","v":0.32666607944264037}]
[-34.369685771862351,-2.9415238283488261,{"$f":"IF(A6<>\"\",RANK(A6,A$4:A$1003,1)+SUM(IF(A$4:A6=A6,1,0))-1.5,\"\")","v":2.5},-2.6141664905746809,1.6330085700090537E-3,33.905680268987645]
[-31.939193324746157,-2.7335105373554081,{"$f":"IF(A7<>\"\",RANK(A7,A$4:A$1003,1)+SUM(IF(A$4:A7=A7,1,0))-1.5,\"\")","v":3.5},-2.4970717585635263,3.1331559123196052E-3,43.846402319699891,null,null,"Normal Plot data"]
[-29.976377702739228,-2.5655232894907232,{"$f":"IF(A8<>\"\",RANK(A8,A$4:A$1003,1)+SUM(IF(A$4:A8=A8,1,0))-1.5,\"\")","v":4.5},-2.4066366628024016,5.1510152566410766E-3,53.14429218258784,null,null,-4,{"$f":"+I8-0.5","v":-4.5},{"$f":"+I8+0.5","v":-3.5},{"$f":"+$K$2+J8*$K$3","v":-52.579409516527328},{"$f":"+$K$2+K8*$K$3","v":-40.895096290632999},{"$f":"(COUNTIF(A$4:A$1004,\"<\"&M8)-COUNTIF(A$4:A$1004,\"<\"&L8))","v":0},{"$f":"(COUNTIF(A$4:A$1004,\"<\"&M8)-COUNTIF(A$4:A$1004,\"<\"&L8))/K$1","v":0},{"$f":"NORMDIST(J8,0,1,1)","v":3.3976731247300535E-6},{"$f":"NORMDIST(K8,0,1,1)","v":2.3262907903552504E-4},{"$f":"+Q8-P8","v":2.2923140591079498E-4}]
[-29.855371894416749,-2.5551670275536233,{"$f":"IF(A9<>\"\",RANK(A9,A$4:A$1003,1)+SUM(IF(A$4:A9=A9,1,0))-1.5,\"\")","v":5.5},-2.3324316174480222,5.3068426997340198E-3,63.516658598387679,null,null,{"$f":"+I8+1","v":-3},{"$f":"+I9-0.5","v":-3.5},{"$f":"+I9+0.5","v":-2.5},{"$f":"+$K$2+J9*$K$3","v":-40.895096290632999},{"$f":"+$K$2+K9*$K$3","v":-29.210783064738667},{"$f":"(COUNTIF(A$4:A$1004,\"<\"&M9)-COUNTIF(A$4:A$1004,\"<\"&L9))","v":7},{"$f":"(COUNTIF(A$4:A$1004,\"<\"&M9)-COUNTIF(A$4:A$1004,\"<\"&L9))/K$1","v":1.2522361359570662E-2},{"$f":"NORMDIST(J9,0,1,1)","v":2.3262907903552504E-4},{"$f":"NORMDIST(K9,0,1,1)","v":6.2096653257761331E-3},{"$f":"+Q9-P9","v":5.9770362467406078E-3}]
[-29.473857954308187,-2.5225152205768073,{"$f":"IF(A10<>\"\",RANK(A10,A$4:A$1003,1)+SUM(IF(A$4:A10=A10,1,0))-1.5,\"\")","v":6.5},-2.2692057962849637,5.8259453787852166E-3,73.347137501028556,null,null,{"$f":"+I9+1","v":-2},{"$f":"+I10-0.5","v":-2.5},{"$f":"+I10+0.5","v":-1.5},{"$f":"+$K$2+J10*$K$3","v":-29.210783064738667},{"$f":"+$K$2+K10*$K$3","v":-17.526469838844339},{"$f":"(COUNTIF(A$4:A$1004,\"<\"&M10)-COUNTIF(A$4:A$1004,\"<\"&L10))","v":29},{"$f":"(COUNTIF(A$4:A$1004,\"<\"&M10)-COUNTIF(A$4:A$1004,\"<\"&L10))/K$1","v":5.1878354203935599E-2},{"$f":"NORMDIST(J10,0,1,1)","v":6.2096653257761331E-3},{"$f":"NORMDIST(K10,0,1,1)","v":6.6807201268858057E-2},{"$f":"+Q10-P10","v":6.0597535943081926E-2}]
[-28.118811080296837,-2.4065437597117949,{"$f":"IF(A11<>\"\",RANK(A11,A$4:A$1003,1)+SUM(IF(A$4:A11=A11,1,0))-1.5,\"\")","v":7.5},-2.2139294645272254,8.0521372743396387E-3,81.244723931702481,null,null,-1,-1.5,-0.5,-17.526469838844339,-5.8421566129500038,126,0.22540250447227192,6.6807201268858057E-2,0.30853753872598688,0.24173033745712882]
[-27.678068762046678,-2.3688229018633935,{"$f":"IF(A12<>\"\",RANK(A12,A$4:A$1003,1)+SUM(IF(A$4:A12=A12,1,0))-1.5,\"\")","v":8.5},-2.1646897963197604,8.9223979286949268E-3,90.093886635891096,null,null,0,-0.5,0.5,-5.8421566129500038,5.8421566129443283,225,0.40250447227191416,0.30853753872598688,0.69146246127401312,0.38292492254802624]
[-27.25909576785034,-2.3329651679858192,{"$f":"IF(A13<>\"\",RANK(A13,A$4:A$1003,1)+SUM(IF(A$4:A13=A13,1,0))-1.5,\"\")","v":9.5},-2.1201990020987798,9.8249867671678249E-3,98.684756800682607,null,null,1,0.5,1.5,5.8421566129443283,17.526469838838661,137,0.24508050089445438,0.69146246127401312,0.93319279873114191,0.2417303374571288]
[-25.241627351080751,-2.1603004697904176,{"$f":"IF(A14<>\"\",RANK(A14,A$4:A$1003,1)+SUM(IF(A$4:A14=A14,1,0))-1.5,\"\")","v":10.5},-2.0795472015725598,1.5374708316428612E-2,104.67271499027565,null,null,2,1.5,2.5,17.526469838838661,29.21078306473299,30,5.3667262969588549E-2,0.93319279873114191,0.99379033467422384,6.0597535943081926E-2]
[-25.051066326288492,-2.1439913362446008,{"$f":"IF(A15<>\"\",RANK(A15,A$4:A$1003,1)+SUM(IF(A$4:A15=A15,1,0))-1.5,\"\")","v":11.5},-2.042066840166632,1.6016790490103548E-2,112.76506504302557,null,null,3,2.5,3.5,29.21078306473299,40.895096290627329,5,8.9445438282647581E-3,0.99379033467422384,0.99976737092096446,5.9770362467406191E-3]
[-23.908480431299722,-2.0462033128581161,{"$f":"IF(A16<>\"\",RANK(A16,A$4:A$1003,1)+SUM(IF(A$4:A16=A16,1,0))-1.5,\"\")","v":12.5},-2.0072531101066917,2.0368185773625636E-2,119.8368040123255,null,null,4,3.5,4.5,40.895096290627329,52.579409516521658,0,0,0.99976737092096446,0.99999660232687526,2.2923140591080138E-4]
[-23.897563993547919,-2.0452690313525834,{"$f":"IF(A17<>\"\",RANK(A17,A$4:A$1003,1)+SUM(IF(A$4:A17=A17,1,0))-1.5,\"\")","v":13.5},-1.9747146745228339,2.0414171043740246E-2,127.573534324574]
[-23.679937831722782,-2.0266435325647865,{"$f":"IF(A18<>\"\",RANK(A18,A$4:A$1003,1)+SUM(IF(A$4:A18=A18,1,0))-1.5,\"\")","v":14.5},-1.9441417966631021,2.1349440577504809E-2,135.05647556844644,null,null,"q-q line plot data"]
[-22.609198472172466,-1.9350044829390554,{"$f":"IF(A19<>\"\",RANK(A19,A$4:A$1003,1)+SUM(IF(A$4:A19=A19,1,0))-1.5,\"\")","v":15.5},-1.9152849666553875,2.6494872784344533E-2,141.74325308284745,null,null,-4]
[-22.571478157736237,-1.9317761961149196,{"$f":"IF(A20<>\"\",RANK(A20,A$4:A$1003,1)+SUM(IF(A$4:A20=A20,1,0))-1.5,\"\")","v":16.5},-1.8879401232066657,2.6693567674682488E-2,148.92607477988076,null,null,4]
[-22.232193036717035,-1.9027385355815396,{"$f":"IF(A21<>\"\",RANK(A21,A$4:A$1003,1)+SUM(IF(A$4:A21=A21,1,0))-1.5,\"\")","v":17.5},-1.8619381642865569,2.8537335472819444E-2,155.83446544484943]
[-21.964623820960696,-1.8798386688471078,{"$f":"IF(A22<>\"\",RANK(A22,A$4:A$1003,1)+SUM(IF(A$4:A22=A22,1,0))-1.5,\"\")","v":18.5},-1.8371373312844295,3.006503430860762E-2,162.6614021333757]
[-21.591671448188208,-1.8479196021837831,{"$f":"IF(A23<>\"\",RANK(A23,A$4:A$1003,1)+SUM(IF(A$4:A23=A23,1,0))-1.5,\"\")","v":19.5},-1.8134175686740344,3.2306987173026012E-2,169.30116562555932]
[-21.42856745095014,-1.8339603737648973,{"$f":"IF(A24<>\"\",RANK(A24,A$4:A$1003,1)+SUM(IF(A$4:A24=A24,1,0))-1.5,\"\")","v":20.5},-1.7906762729715835,3.3329938256377756E-2,175.96145738281928]
[-21.258141109395183,-1.8193744637280742,{"$f":"IF(A25<>\"\",RANK(A25,A$4:A$1003,1)+SUM(IF(A$4:A25=A25,1,0))-1.5,\"\")","v":21.5},-1.7688250385187059,3.4427159945655691E-2,182.52437560282505]
[-20.933041707762641,-1.791550885624051,{"$f":"IF(A26<>\"\",RANK(A26,A$4:A$1003,1)+SUM(IF(A$4:A26=A26,1,0))-1.5,\"\")","v":22.5},-1.7477871313908646,3.660246826688103E-2,188.85503662893387]
[-20.533942136456062,-1.7573940153321703,{"$f":"IF(A27<>\"\",RANK(A27,A$4:A$1003,1)+SUM(IF(A$4:A27=A27,1,0))-1.5,\"\")","v":23.5},-1.7274955037572379,3.9425336351754874E-2,195.04672970119631]
[-19.452741781125042,-1.6648596631260941,{"$f":"IF(A28<>\"\",RANK(A28,A$4:A$1003,1)+SUM(IF(A$4:A28=A28,1,0))-1.5,\"\")","v":24.5},-1.7078912152358261,4.7970378671130923E-2,201.37251670169911]
[-19.318270483011474,-1.653350959489533,{"$f":"IF(A29<>\"\",RANK(A29,A$4:A$1003,1)+SUM(IF(A$4:A29=A29,1,0))-1.5,\"\")","v":25.5},-1.6889221647895583,4.9129728677938966E-2,207.43077916495704]
[-19.126205447575558,-1.6369131054434545,{"$f":"IF(A30<>\"\",RANK(A30,A$4:A$1003,1)+SUM(IF(A$4:A30=A30,1,0))-1.5,\"\")","v":26.5},-1.6705420624168461,5.0824313596432642E-2,213.45902111505075]
[-19.114699410400135,-1.6359283631695207,{"$f":"IF(A31<>\"\",RANK(A31,A$4:A$1003,1)+SUM(IF(A$4:A31=A31,1,0))-1.5,\"\")","v":27.5},-1.6527095880432503,5.0927290536555543E-2,219.31746662138062]
[-18.979507882690086,-1.6243580188029862,{"$f":"IF(A32<>\"\",RANK(A32,A$4:A$1003,1)+SUM(IF(A$4:A32=A32,1,0))-1.5,\"\")","v":28.5},-1.6353876980312456,5.2149710663620778E-2,225.18308206667976]
[-18.951528334437171,-1.6219633938291447,{"$f":"IF(A33<>\"\",RANK(A33,A$4:A$1003,1)+SUM(IF(A$4:A33=A33,1,0))-1.5,\"\")","v":29.5},-1.6185430491774162,5.2405593182508571E-2,230.98037826940913]
[-18.923418156009575,-1.6195575888935752,{"$f":"IF(A34<>\"\",RANK(A34,A$4:A$1003,1)+SUM(IF(A$4:A34=A34,1,0))-1.5,\"\")","v":30.5},-1.6021455170203514,5.2663673125386452E-2,236.75845359029006]
[-18.390239177113472,-1.5739255548503168,{"$f":"IF(A35<>\"\",RANK(A35,A$4:A$1003,1)+SUM(IF(A$4:A35=A35,1,0))-1.5,\"\")","v":31.5},-1.5861677904580811,5.775233059044424E-2,242.40918103639117]
[-18.381871791399135,-1.5732094335385574,{"$f":"IF(A36<>\"\",RANK(A36,A$4:A$1003,1)+SUM(IF(A$4:A36=A36,1,0))-1.5,\"\")","v":32.5},-1.5705850285674188,5.7835165845078973E-2,247.99280184494947]
[-18.298194406989751,-1.5660479185404879,{"$f":"IF(A37<>\"\",RANK(A37,A$4:A$1003,1)+SUM(IF(A$4:A37=A37,1,0))-1.5,\"\")","v":33.5},-1.5553745684760383,5.8668699712295151E-2,253.54547293350305]
[-17.691209440039529,-1.5140992113109484,{"$f":"IF(A38<>\"\",RANK(A38,A$4:A$1003,1)+SUM(IF(A$4:A38=A38,1,0))-1.5,\"\")","v":34.5},-1.5405156754070479,6.5000339340784641E-2,259.10439154806767]
[-17.667936105341141,-1.5121073668397806,{"$f":"IF(A39<>\"\",RANK(A39,A$4:A$1003,1)+SUM(IF(A$4:A39=A39,1,0))-1.5,\"\")","v":35.5},-1.5259893277711403,6.5253275534110769E-2,264.44422520483147]
[-17.380557018144827,-1.4875120755598932,{"$f":"IF(A40<>\"\",RANK(A40,A$4:A$1003,1)+SUM(IF(A$4:A40=A40,1,0))-1.5,\"\")","v":36.5},-1.5117780315504272,6.843980814847582E-2,269.85617032880106]
[-17.303089857932719,-1.4808820615646821,{"$f":"IF(A41<>\"\",RANK(A41,A$4:A$1003,1)+SUM(IF(A$4:A41=A41,1,0))-1.5,\"\")","v":37.5},-1.4978656592940365,6.9319001986765327E-2,275.10548504197891]
[-17.269489684905238,-1.4780063963563055,{"$f":"IF(A42<>\"\",RANK(A42,A$4:A$1003,1)+SUM(IF(A$4:A42=A42,1,0))-1.5,\"\")","v":38.5},-1.4842373098972275,6.9703033097323785E-2,280.30411428201307]
[-17.020092172493605,-1.4566617518239311,{"$f":"IF(A43<>\"\",RANK(A43,A$4:A$1003,1)+SUM(IF(A$4:A43=A43,1,0))-1.5,\"\")","v":39.5},-1.4708791860145434,7.2604886330837129E-2,285.51034465970247]
[-16.866139342015231,-1.4434857244869381,{"$f":"IF(A44<>\"\",RANK(A44,A$4:A$1003,1)+SUM(IF(A$4:A44=A44,1,0))-1.5,\"\")","v":40.5},-1.4577784865019063,7.4441845516246163E-2,290.63727228101556]
[-16.796517046818735,-1.4375271119565753,{"$f":"IF(A45<>\"\",RANK(A45,A$4:A$1003,1)+SUM(IF(A$4:A45=A45,1,0))-1.5,\"\")","v":41.5},-1.4449233117218239,7.5284137411217353E-2,295.68649445395181]
[-16.598503047533086,-1.4205801168309382,{"$f":"IF(A46<>\"\",RANK(A46,A$4:A$1003,1)+SUM(IF(A$4:A46=A46,1,0))-1.5,\"\")","v":42.5},-1.4323025799023157,7.7719431101042735E-2,300.72093617691939]
[-16.389441980321863,-1.4026876602381186,{"$f":"IF(A47<>\"\",RANK(A47,A$4:A$1003,1)+SUM(IF(A$4:A47=A47,1,0))-1.5,\"\")","v":43.5},-1.4199059530310461,8.0354999303539967E-2,305.7175306918092]
[-16.365646124925661,-1.4006510959201177,{"$f":"IF(A48<>\"\",RANK(A48,A$4:A$1003,1)+SUM(IF(A$4:A48=A48,1,0))-1.5,\"\")","v":44.5},-1.4077237710046304,8.0659216716497187E-2,310.59673529621966]
[-15.878357137276907,-1.3589465491292254,{"$f":"IF(A49<>\"\",RANK(A49,A$4:A$1003,1)+SUM(IF(A$4:A49=A49,1,0))-1.5,\"\")","v":45.5},-1.39574699294967,8.7081763418572433E-2,315.69150800965463]
[-15.853516240485988,-1.3568205451176358,{"$f":"IF(A50<>\"\",RANK(A50,A$4:A$1003,1)+SUM(IF(A$4:A50=A50,1,0))-1.5,\"\")","v":46.5},-1.383967144794809,8.7419118897412856E-2,320.41036262023704]
[-15.768465475606718,-1.3495414895809541,{"$f":"IF(A51<>\"\",RANK(A51,A$4:A$1003,1)+SUM(IF(A$4:A51=A51,1,0))-1.5,\"\")","v":47.5},-1.3723762723084985,8.8581551625579846E-2,325.15048928471259]
[-15.531096521067411,-1.3292263071692692,{"$f":"IF(A52<>\"\",RANK(A52,A$4:A$1003,1)+SUM(IF(A$4:A52=A52,1,0))-1.5,\"\")","v":48.5},-1.3609668989300883,9.1886659174614027E-2,329.96853563739057]
[-15.489520852849637,-1.3256680605343163,{"$f":"IF(A53<>\"\",RANK(A53,A$4:A$1003,1)+SUM(IF(A$4:A53=A53,1,0))-1.5,\"\")","v":49.5},-1.3497319878167826,9.2474835655328547E-2,334.5786827427014]
[-15.416629276017375,-1.3194296470800515,{"$f":"IF(A54<>\"\",RANK(A54,A$4:A$1003,1)+SUM(IF(A$4:A54=A54,1,0))-1.5,\"\")","v":50.5},-1.338664907608661,9.3512757867827215E-2,339.18275196152752]
[-15.350865861880266,-1.3138012962419923,{"$f":"IF(A55<>\"\",RANK(A55,A$4:A$1003,1)+SUM(IF(A$4:A55=A55,1,0))-1.5,\"\")","v":51.5},-1.3277594014814904,9.4456540652868751E-2,343.74869813409879]
[-15.335829282719715,-1.3125143931207008,{"$f":"IF(A56<>\"\",RANK(A56,A$4:A$1003,1)+SUM(IF(A$4:A56=A56,1,0))-1.5,\"\")","v":52.5},-1.3170095591140834,9.4673316462508622E-2,348.27132084924312]
[-15.310988385929704,-1.3103883891091892,{"$f":"IF(A57<>\"\",RANK(A57,A$4:A$1003,1)+SUM(IF(A$4:A57=A57,1,0))-1.5,\"\")","v":53.5},-1.3064097912457113,9.5032239746676822E-2,352.78305697990163]
[-15.004127766367674,-1.2841257741287915,{"$f":"IF(A58<>\"\",RANK(A58,A$4:A$1003,1)+SUM(IF(A$4:A58=A58,1,0))-1.5,\"\")","v":54.5},-1.2959548065404789,9.9548975555559055E-2,357.27774222156643]
[-14.960458488083532,-1.280388346225253,{"$f":"IF(A59<>\"\",RANK(A59,A$4:A$1003,1)+SUM(IF(A$4:A59=A59,1,0))-1.5,\"\")","v":55.5},-1.2856395905111833,0.10020429524039613,361.68705781785724]
[-14.795066699155541,-1.266233317535894,{"$f":"IF(A60<>\"\",RANK(A60,A$4:A$1003,1)+SUM(IF(A$4:A60=A60,1,0))-1.5,\"\")","v":56.5},-1.2754593862856416,0.10271478124537461,366.08872012199936]
[-14.703675079905224,-1.2584115810347039,{"$f":"IF(A61<>\"\",RANK(A61,A$4:A$1003,1)+SUM(IF(A$4:A61=A61,1,0))-1.5,\"\")","v":57.5},-1.2654096770247689,0.10412147287513213,370.43296004304221]
[-14.599601751909177,-1.2495044826041855,{"$f":"IF(A62<>\"\",RANK(A62,A$4:A$1003,1)+SUM(IF(A$4:A62=A62,1,0))-1.5,\"\")","v":58.5},-1.2554861698244286,0.10574030749757636,374.74280832429577]
[-14.355238792125419,-1.2285907194193533,{"$f":"IF(A63<>\"\",RANK(A63,A$4:A$1003,1)+SUM(IF(A$4:A63=A63,1,0))-1.5,\"\")","v":59.5},-1.245684780952663,0.10961264840500116,379.06808395451503]
[-14.246130911501496,-1.2192527396412931,{"$f":"IF(A64<>\"\",RANK(A64,A$4:A$1003,1)+SUM(IF(A$4:A64=A64,1,0))-1.5,\"\")","v":60.5},-1.2360016222910355,0.11137414010529648,383.30282388927623]
[-14.08093330419706,-1.2051143299538216,{"$f":"IF(A65<>\"\",RANK(A65,A$4:A$1003,1)+SUM(IF(A$4:A65=A65,1,0))-1.5,\"\")","v":61.5},-1.2264329888636651,0.11407958427027545,387.53816874273315]
[-14.045567860176561,-1.2020875843217271,{"$f":"IF(A66<>\"\",RANK(A66,A$4:A$1003,1)+SUM(IF(A$4:A66=A66,1,0))-1.5,\"\")","v":62.5},-1.2169753473504625,0.11466479808664927,391.65419960672068]
[-13.952280339759454,-1.1941035874351693,{"$f":"IF(A67<>\"\",RANK(A67,A$4:A$1003,1)+SUM(IF(A$4:A67=A67,1,0))-1.5,\"\")","v":63.5},-1.2076253254924434,0.11621872505650946,395.77348784779144]
[-13.927700703316987,-1.1919999433469575,{"$f":"IF(A68<>\"\",RANK(A68,A$4:A$1003,1)+SUM(IF(A$4:A68=A68,1,0))-1.5,\"\")","v":64.5},-1.1983797023069247,0.11663063374189153,399.83561465116452]
[-13.814147869486987,{"$f":"+IF(A69<>\"\",(A69-K$2)/K$3,\"\")","v":-1.1822815429896008},{"$f":"IF(A69<>\"\",RANK(A69,A$4:A$1003,1)+SUM(IF(A$4:A69=A69,1,0))-1.5,\"\")","v":65.5},{"$f":"IF(A69<>\"\",NORMSINV(C69/($K$1)),\"\")","v":-1.1892353990391256},{"$f":"IF(A69<>\"\",NORMDIST(A69,$K$2,$K$3,1),\"\")","v":0.11854700329452146},{"$f":"IF(A69<>\"\",-2*C69*LN(E69)-(2*$K$1-2*C69)*LN(1-E69),\"\")","v":403.89360627018823}]
[-13.438844153575701,-1.1501612370156431,{"$f":"IF(A70<>\"\",RANK(A70,A$4:A$1003,1)+SUM(IF(A$4:A70=A70,1,0))-1.5,\"\")","v":66.5},-1.1801894707843785,0.12503873416615915,408.09654457922227]
[-13.355428029514769,-1.1430220819409513,{"$f":"IF(A71<>\"\",RANK(A71,A$4:A$1003,1)+SUM(IF(A$4:A71=A71,1,0))-1.5,\"\")","v":67.5},-1.1712390987219439,0.12651471147216123,412.06305565957354]
[-13.313393392048056,-1.1394245544993249,{"$f":"IF(A72<>\"\",RANK(A72,A$4:A$1003,1)+SUM(IF(A$4:A72=A72,1,0))-1.5,\"\")","v":68.5},-1.1623815829073989,0.12726305966307636,415.9601589179025]
[-13.300513974403657,-1.1383222716868566,{"$f":"IF(A73<>\"\",RANK(A73,A$4:A$1003,1)+SUM(IF(A$4:A73=A73,1,0))-1.5,\"\")","v":69.5},-1.1536143355758646,0.1274929687022231,419.81796505895358]
[-13.207032272362994,-1.1303216557984113,{"$f":"IF(A74<>\"\",RANK(A74,A$4:A$1003,1)+SUM(IF(A$4:A74=A74,1,0))-1.5,\"\")","v":70.5},-1.1449348749130688,0.12917035632623147,423.70166816088658]
[-13.137671237514951,-1.1243854031914264,{"$f":"IF(A75<>\"\",RANK(A75,A$4:A$1003,1)+SUM(IF(A$4:A75=A75,1,0))-1.5,\"\")","v":71.5},-1.1363408192553905,0.13042478086729109,427.5417606889747]
[-13.091191646843072,-1.1204074551705814,{"$f":"IF(A76<>\"\",RANK(A76,A$4:A$1003,1)+SUM(IF(A$4:A76=A76,1,0))-1.5,\"\")","v":72.5},-1.1278298816837637,0.13127008472583435,431.34574303592603]
[-12.900171652800964,-1.1040590408180135,{"$f":"IF(A77<>\"\",RANK(A77,A$4:A$1003,1)+SUM(IF(A$4:A77=A77,1,0))-1.5,\"\")","v":73.5},-1.1193998649796508,0.13478376366312586,435.17760003121532]
[-12.836890211977334,-1.098643109252315,{"$f":"IF(A78<>\"\",RANK(A78,A$4:A$1003,1)+SUM(IF(A$4:A78=A78,1,0))-1.5,\"\")","v":74.5},-1.1110486569142424,0.13596188317324356,438.91982901932323]
[-12.754063687339112,-1.0915544149459468,{"$f":"IF(A79<>\"\",RANK(A79,A$4:A$1003,1)+SUM(IF(A$4:A79=A79,1,0))-1.5,\"\")","v":75.5},-1.1027742258446931,0.13751450095570411,442.64293560081887]
[-12.708106617365047,-1.087621186771935,{"$f":"IF(A80<>\"\",RANK(A80,A$4:A$1003,1)+SUM(IF(A$4:A80=A80,1,0))-1.5,\"\")","v":76.5},-1.0945746165935937,0.13838118681945802,446.32404337204798]
[-12.522251806126405,-1.071714833728715,{"$f":"IF(A81<>\"\",RANK(A81,A$4:A$1003,1)+SUM(IF(A$4:A81=A81,1,0))-1.5,\"\")","v":77.5},-1.0864479465899999,0.14192406803596522,450.03114525057617]
[-12.44079866195716,-1.0647436799608809,{"$f":"IF(A82<>\"\",RANK(A82,A$4:A$1003,1)+SUM(IF(A$4:A82=A82,1,0))-1.5,\"\")","v":78.5},-1.0783924022522531,0.14349596889369876,453.66268948198206]
[-12.436614969100447,-1.0643856193050401,{"$f":"IF(A83<>\"\",RANK(A83,A$4:A$1003,1)+SUM(IF(A$4:A83=A83,1,0))-1.5,\"\")","v":79.5},-1.0704062355945709,0.1435770228388609,457.23676536359176]
[-12.380394612246164,-1.0595740094339789,{"$f":"IF(A84<>\"\",RANK(A84,A$4:A$1003,1)+SUM(IF(A$4:A84=A84,1,0))-1.5,\"\")","v":80.5},-1.0624877610409094,0.14466922145933314,460.80969316269341]
[-12.191270519370846,-1.043387855466779,{"$f":"IF(A85<>\"\",RANK(A85,A$4:A$1003,1)+SUM(IF(A$4:A85=A85,1,0))-1.5,\"\")","v":81.5},-1.0546353524310361,0.14838434795418276,464.38782447032509]
[-11.959850528681272,-1.0235818141346527,{"$f":"IF(A86<>\"\",RANK(A86,A$4:A$1003,1)+SUM(IF(A$4:A86=A86,1,0))-1.5,\"\")","v":82.5},-1.0468474402049917,0.15301641927062584,468.00815104403443]
[-11.851854768176963,-1.0143390149716711,{"$f":"IF(A87<>\"\",RANK(A87,A$4:A$1003,1)+SUM(IF(A$4:A87=A87,1,0))-1.5,\"\")","v":83.5},-1.0391225087532998,0.15521050671966899,471.51956761326358]
[-11.444387811156957,-0.97946602336810884,{"$f":"IF(A88<>\"\",RANK(A88,A$4:A$1003,1)+SUM(IF(A$4:A88=A88,1,0))-1.5,\"\")","v":84.5},-1.0314590939212436,0.16367488431072774,475.49079304819406]
[-11.213359710989607,-0.9596935219210101,{"$f":"IF(A89<>\"\",RANK(A89,A$4:A$1003,1)+SUM(IF(A$4:A89=A89,1,0))-1.5,\"\")","v":85.5},-1.0238557806566455,0.16860474228658545,479.27738466973369]
[-11.212314669594889,-0.95960408222742144,{"$f":"IF(A90<>\"\",RANK(A90,A$4:A$1003,1)+SUM(IF(A$4:A90=A90,1,0))-1.5,\"\")","v":86.5},-1.0163112007911452,0.1686272568674696,482.47097241032384]
[-11.139684353110169,-0.95338802869645656,{"$f":"IF(A91<>\"\",RANK(A91,A$4:A$1003,1)+SUM(IF(A$4:A91=A91,1,0))-1.5,\"\")","v":87.5},-1.0088240309461658,0.17019675232414208,485.82238311673905]
[-11.028094499173676,-0.9438376296461134,{"$f":"IF(A92<>\"\",RANK(A92,A$4:A$1003,1)+SUM(IF(A$4:A92=A92,1,0))-1.5,\"\")","v":88.5},-1.0013929905549805,0.17262631403552786,489.24120961722025]
[-10.894078643033026,-0.93236790493489552,{"$f":"IF(A93<>\"\",RANK(A93,A$4:A$1003,1)+SUM(IF(A$4:A93=A93,1,0))-1.5,\"\")","v":89.5},-0.99401683999338131,0.17557321276226731,492.69600327986467]
[-10.765754017669678,-0.92138526326118897,{"$f":"IF(A94<>\"\",RANK(A94,A$4:A$1003,1)+SUM(IF(A$4:A94=A94,1,0))-1.5,\"\")","v":90.5},-0.98669437881177224,0.17842465996067733,496.11972237100008]
[-10.72378293165184,-0.91779317485972234,{"$f":"IF(A95<>\"\",RANK(A95,A$4:A$1003,1)+SUM(IF(A$4:A95=A95,1,0))-1.5,\"\")","v":91.5},-0.97942444406208362,0.17936357806322975,499.28252079194363]
[-10.714631764892147,-0.91700997377782967,{"$f":"IF(A96<>\"\",RANK(A96,A$4:A$1003,1)+SUM(IF(A$4:A96=A96,1,0))-1.5,\"\")","v":92.5},-0.97220590871352175,0.17956870687072279,502.34564200964667]
[-10.643636089225765,-0.91093382070885476,{"$f":"IF(A97<>\"\",RANK(A97,A$4:A$1003,1)+SUM(IF(A$4:A97=A97,1,0))-1.5,\"\")","v":93.5},-0.9650376801514714,0.1811651221669304,505.54237882667121]
[-10.632197130777058,-0.90995481935656686,{"$f":"IF(A98<>\"\",RANK(A98,A$4:A$1003,1)+SUM(IF(A$4:A98=A98,1,0))-1.5,\"\")","v":94.5},-0.95791869875435143,0.18142316873211498,508.58312113531701]
[-10.592058394477135,-0.90651955230030812,{"$f":"IF(A99<>\"\",RANK(A99,A$4:A$1003,1)+SUM(IF(A$4:A99=A99,1,0))-1.5,\"\")","v":95.5},-0.95084793654360611,0.1823304603658748,511.67182177460552]
[-10.462293309918095,-0.8954136291664212,{"$f":"IF(A100<>\"\",RANK(A100,A$4:A$1003,1)+SUM(IF(A$4:A100=A100,1,0))-1.5,\"\")","v":96.5},-0.94382439590232636,0.18528300882577656,514.91896358831173]
[-10.269638675059468,-0.87892531435201926,{"$f":"IF(A101<>\"\",RANK(A101,A$4:A$1003,1)+SUM(IF(A$4:A101=A101,1,0))-1.5,\"\")","v":97.5},-0.93684710835836804,0.18972088603410941,518.30676961665995]
[-10.222177594440836,-0.87486336567766743,{"$f":"IF(A102<>\"\",RANK(A102,A$4:A$1003,1)+SUM(IF(A$4:A102=A102,1,0))-1.5,\"\")","v":98.5},-0.92991513342804033,0.19082412712487692,521.32301581126819]
[-10.161642914555159,-0.86968251518903772,{"$f":"IF(A103<>\"\",RANK(A103,A$4:A$1003,1)+SUM(IF(A$4:A103=A103,1,0))-1.5,\"\")","v":99.5},-0.92302755751680621,0.19223696504064192,524.35039606895793]
[-10.116667334527847,-0.86583328766853285,{"$f":"IF(A104<>\"\",RANK(A104,A$4:A$1003,1)+SUM(IF(A$4:A104=A104,1,0))-1.5,\"\")","v":100.5},-0.91618349287363232,0.19329079584568387,527.31974148833001]
[-10.096663281464316,-0.86412124412118951,{"$f":"IF(A105<>\"\",RANK(A105,A$4:A$1003,1)+SUM(IF(A$4:A105=A105,1,0))-1.5,\"\")","v":101.5},-0.9093820765958347,0.19376064495243664,530.21750093629294]
[-10.056916435687526,-0.86071951695003623,{"$f":"IF(A106<>\"\",RANK(A106,A$4:A$1003,1)+SUM(IF(A$4:A106=A106,1,0))-1.5,\"\")","v":102.5},-0.9026224696815357,0.19469627061189562,533.14163409329615]
[-10.006514412508295,-0.85640586819680597,{"$f":"IF(A107<>\"\",RANK(A107,A$4:A$1003,1)+SUM(IF(A$4:A107=A107,1,0))-1.5,\"\")","v":103.5},-0.8959038561269882,0.195886659962384,536.06705400270812]
[-9.9108084702256747,-0.84821489107796932,{"$f":"IF(A108<>\"\",RANK(A108,A$4:A$1003,1)+SUM(IF(A$4:A108=A108,1,0))-1.5,\"\")","v":104.5},-0.88922544206624932,0.19815915282771054,539.05334510096509]
[-9.8875351355272869,-0.84622304660680181,{"$f":"IF(A109<>\"\",RANK(A109,A$4:A$1003,1)+SUM(IF(A$4:A109=A109,1,0))-1.5,\"\")","v":105.5},-0.88258645495081312,0.19871416374699072,541.88689083551867]
[-9.8717147753204699,-0.84486906371529935,{"$f":"IF(A110<>\"\",RANK(A110,A$4:A$1003,1)+SUM(IF(A$4:A110=A110,1,0))-1.5,\"\")","v":106.5},-0.87598614276697562,0.19909197441701607,544.6978170331821]
[-9.8466126181810978,-0.84272069978033204,{"$f":"IF(A111<>\"\",RANK(A111,A$4:A$1003,1)+SUM(IF(A$4:A111=A111,1,0))-1.5,\"\")","v":107.5},-0.86942377328888587,0.19969233376013354,547.51156236713462]
[-9.8334719401873372,-0.84159605704440832,{"$f":"IF(A112<>\"\",RANK(A112,A$4:A$1003,1)+SUM(IF(A$4:A112=A112,1,0))-1.5,\"\")","v":108.5},-0.8628986333653097,0.20000704854394485,550.30065765447137]
[-9.7586209107394097,-0.83518994416461612,{"$f":"IF(A113<>\"\",RANK(A113,A$4:A$1003,1)+SUM(IF(A$4:A113=A113,1,0))-1.5,\"\")","v":109.5},-0.85641002823829959,0.20180538531027453,553.13602227918295]
[-9.7363290659868653,-0.83328210034687744,{"$f":"IF(A114<>\"\",RANK(A114,A$4:A$1003,1)+SUM(IF(A$4:A114=A114,1,0))-1.5,\"\")","v":110.5},-0.8499572808920578,0.20234282445925555,555.90251456759074]
[-9.7171087939705103,-0.83163713656982297,{"$f":"IF(A115<>\"\",RANK(A115,A$4:A$1003,1)+SUM(IF(A$4:A115=A115,1,0))-1.5,\"\")","v":111.5},-0.84353973143039174,0.2028068968557247,558.65593904554612]
[-9.651998530705896,-0.82606468554032475,{"$f":"IF(A116<>\"\",RANK(A116,A$4:A$1003,1)+SUM(IF(A$4:A116=A116,1,0))-1.5,\"\")","v":112.5},-0.83715673648127353,0.20438369948414467,561.41909047572153]
[-9.6460495668570729,-0.825555544460844,{"$f":"IF(A117<>\"\",RANK(A117,A$4:A$1003,1)+SUM(IF(A$4:A117=A117,1,0))-1.5,\"\")","v":113.5},-0.83080766862705324,0.20452813099738579,564.13873083869578]
[-9.5475968636355901,-0.8171294862648607,{"$f":"IF(A118<>\"\",RANK(A118,A$4:A$1003,1)+SUM(IF(A$4:A118=A118,1,0))-1.5,\"\")","v":114.5},-0.8244919158590549,0.2069272169474245,566.86989644768607]
[-9.521643846724146,-0.81490830163811456,{"$f":"IF(A119<>\"\",RANK(A119,A$4:A$1003,1)+SUM(IF(A$4:A119=A119,1,0))-1.5,\"\")","v":115.5},-0.81820888105526512,0.20756240044433721,569.55969680133148]
[-9.3718111576536103,-0.80208489591680243,{"$f":"IF(A120<>\"\",RANK(A120,A$4:A$1003,1)+SUM(IF(A$4:A120=A120,1,0))-1.5,\"\")","v":116.5},-0.81195798147995679,0.2112519256964551,572.26385934193922]
[-9.3248725977327922,-0.79806766708928401,{"$f":"IF(A121<>\"\",RANK(A121,A$4:A$1003,1)+SUM(IF(A$4:A121=A121,1,0))-1.5,\"\")","v":117.5},-0.80573864830414599,0.21241561165195583,574.91140338854098]
[-9.2436807139129087,-0.7911188732449056,{"$f":"IF(A122<>\"\",RANK(A122,A$4:A$1003,1)+SUM(IF(A$4:A122=A122,1,0))-1.5,\"\")","v":118.5},-0.79955032614585086,0.21443731336630031,577.55163777403641]
[-9.1975259350392662,-0.78716872418767592,{"$f":"IF(A123<>\"\",RANK(A123,A$4:A$1003,1)+SUM(IF(A$4:A123=A123,1,0))-1.5,\"\")","v":119.5},-0.79339247262914137,0.2155915515766213,580.15787974738134]
[-9.1273811191449568,-0.78116539181048006,{"$f":"IF(A124<>\"\",RANK(A124,A$4:A$1003,1)+SUM(IF(A$4:A124=A124,1,0))-1.5,\"\")","v":120.5},-0.78726455796110806,0.21735261283027235,582.75150499843721]
[-9.0812934189962107,-0.77722098367474057,{"$f":"IF(A125<>\"\",RANK(A125,A$4:A$1003,1)+SUM(IF(A$4:A125=A125,1,0))-1.5,\"\")","v":121.5},-0.78116606452583093,0.21851420208459005,585.31825160713129]
[-9.0392587815294974,-0.77362345623311413,{"$f":"IF(A126<>\"\",RANK(A126,A$4:A$1003,1)+SUM(IF(A$4:A126=A126,1,0))-1.5,\"\")","v":122.5},-0.77509648649455243,0.21957674841919356,587.86627578980233]
[-8.7315508294732354,-0.7472883224424236,{"$f":"IF(A127<>\"\",RANK(A127,A$4:A$1003,1)+SUM(IF(A$4:A127=A127,1,0))-1.5,\"\")","v":123.5},-0.76905532945127975,0.22744476992518561,590.53251461004174]
[-8.7161223597904609,-0.74596787943610443,{"$f":"IF(A128<>\"\",RANK(A128,A$4:A$1003,1)+SUM(IF(A$4:A128=A128,1,0))-1.5,\"\")","v":124.5},-0.7630421100330762,0.22784340932333508,592.99059052022085]
[-8.679316456576089,-0.74281785234398545,{"$f":"IF(A129<>\"\",RANK(A129,A$4:A$1003,1)+SUM(IF(A$4:A129=A129,1,0))-1.5,\"\")","v":125.5},-0.7570563555843467,0.22879598280059929,595.45468613484127]
[-8.584853264587764,-0.73473323580195549,{"$f":"IF(A130<>\"\",RANK(A130,A$4:A$1003,1)+SUM(IF(A$4:A130=A130,1,0))-1.5,\"\")","v":126.5},-0.75109760382448332,0.23125098741572231,597.94265689551617]
[-8.5347125017569851,-0.73044194697210285,{"$f":"IF(A131<>\"\",RANK(A131,A$4:A$1003,1)+SUM(IF(A$4:A131=A131,1,0))-1.5,\"\")","v":127.5},-0.74516540252822272,0.2325600429829035,600.37655842292918]
[-8.5214411935894532,-0.72930612427452912,{"$f":"IF(A132<>\"\",RANK(A132,A$4:A$1003,1)+SUM(IF(A$4:A132=A132,1,0))-1.5,\"\")","v":128.5},-0.73925930921815275,0.2329072134429859,602.77059596050367]
[-8.4271086317767185,{"$f":"+IF(A133<>\"\",(A133-K$2)/K$3,\"\")","v":-0.72123268769430482},{"$f":"IF(A133<>\"\",RANK(A133,A$4:A$1003,1)+SUM(IF(A$4:A133=A133,1,0))-1.5,\"\")","v":129.5},{"$f":"IF(A133<>\"\",NORMSINV(C133/($K$1)),\"\")","v":-0.73337889086881569},{"$f":"IF(A133<>\"\",NORMDIST(A133,$K$2,$K$3,1),\"\")","v":0.23538318176792211},{"$f":"IF(A133<>\"\",-2*C133*LN(E133)-(2*$K$1-2*C133)*LN(1-E133),\"\")","v":605.19281452293808}]
[-8.4073658390616401,-0.71954300407033922,{"$f":"IF(A134<>\"\",RANK(A134,A$4:A$1003,1)+SUM(IF(A$4:A134=A134,1,0))-1.5,\"\")","v":130.5},-0.72752372362185691,0.2359032076954492,607.55620542226939]
[-8.3948147604924088,-0.71846882210289453,{"$f":"IF(A135<>\"\",RANK(A135,A$4:A$1003,1)+SUM(IF(A$4:A135=A135,1,0))-1.5,\"\")","v":131.5},-0.7216933925117528,0.23623413256930509,609.90844810639055]
[-8.2224925177697514,-0.70372065168062581,{"$f":"IF(A136<>\"\",RANK(A136,A$4:A$1003,1)+SUM(IF(A$4:A136=A136,1,0))-1.5,\"\")","v":132.5},-0.71588749120163309,0.24080337837690202,612.29704481405861]
[-8.1488171598912231,-0.6974151584561501,{"$f":"IF(A137<>\"\",RANK(A137,A$4:A$1003,1)+SUM(IF(A$4:A137=A137,1,0))-1.5,\"\")","v":133.5},-0.71010562172874347,0.24277150890620169,614.62921900411482]
[-8.0189214451584121,-0.68629805536061339,{"$f":"IF(A138<>\"\",RANK(A138,A$4:A$1003,1)+SUM(IF(A$4:A138=A138,1,0))-1.5,\"\")","v":134.5},-0.70434739425914106,0.24626258750222912,616.98683670384571]
[-7.9948643294137582,-0.68423913111923473,{"$f":"IF(A139<>\"\",RANK(A139,A$4:A$1003,1)+SUM(IF(A$4:A139=A139,1,0))-1.5,\"\")","v":135.5},-0.69861242685120395,0.24691208810432719,619.24050532346178]
[-7.8074419560825845,-0.6681986185355927,{"$f":"IF(A140<>\"\",RANK(A140,A$4:A$1003,1)+SUM(IF(A$4:A140=A140,1,0))-1.5,\"\")","v":136.5},-0.69290034522758903,0.25200340858573245,621.63090263039453]
[-7.7088586226873304,-0.65976138037795939,{"$f":"IF(A141<>\"\",RANK(A141,A$4:A$1003,1)+SUM(IF(A$4:A141=A141,1,0))-1.5,\"\")","v":137.5},-0.68721078255525714,0.25470348509953178,623.92453512692987]
[-7.6791138034413962,-0.65721567498040001,{"$f":"IF(A142<>\"\",RANK(A142,A$4:A$1003,1)+SUM(IF(A$4:A142=A142,1,0))-1.5,\"\")","v":138.5},-0.68154337923324115,0.25552112400546884,626.10724755566446]
[-7.6692424070843117,-0.65637083316845612,{"$f":"IF(A143<>\"\",RANK(A143,A$4:A$1003,1)+SUM(IF(A$4:A143=A143,1,0))-1.5,\"\")","v":139.5},-0.67589778268780809,0.25579277609517714,628.2557483911346]
[-7.5973993989246082,-0.65022216128926624,{"$f":"IF(A144<>\"\",RANK(A144,A$4:A$1003,1)+SUM(IF(A$4:A144=A144,1,0))-1.5,\"\")","v":140.5},-0.67027364717472593,0.25777436403104909,630.45481435610168]
[-7.5364057497899921,-0.64500202999396294,{"$f":"IF(A145<>\"\",RANK(A145,A$4:A$1003,1)+SUM(IF(A$4:A145=A145,1,0))-1.5,\"\")","v":141.5},-0.66467063358831402,0.25946293509722185,632.62398131110649]
[-7.5200628688862707,-0.64360332725570513,{"$f":"IF(A146<>\"\",RANK(A146,A$4:A$1003,1)+SUM(IF(A$4:A146=A146,1,0))-1.5,\"\")","v":142.5},-0.65908840927702084,0.25991634606088554,634.73408241919356]
[-7.248896032419907,-0.62039555875242547,{"$f":"IF(A147<>\"\",RANK(A147,A$4:A$1003,1)+SUM(IF(A$4:A147=A147,1,0))-1.5,\"\")","v":143.5},-0.65352664786524262,0.26749869784119618,637.13196990883011]
[-7.1939184258599198,-0.61569030945817105,{"$f":"IF(A148<>\"\",RANK(A148,A$4:A$1003,1)+SUM(IF(A$4:A148=A148,1,0))-1.5,\"\")","v":144.5},-0.6479850290811312,0.269049467123672,639.23301570297417]
[-7.057028705882658,-0.603974625589487,{"$f":"IF(A149<>\"\",RANK(A149,A$4:A$1003,1)+SUM(IF(A$4:A149=A149,1,0))-1.5,\"\")","v":145.5},-0.64246323859015286,0.27293025619222977,641.46693100783364]
[-6.8949026713144121,-0.59009909594269971,{"$f":"IF(A150<>\"\",RANK(A150,A$4:A$1003,1)+SUM(IF(A$4:A150=A150,1,0))-1.5,\"\")","v":146.5},-0.63696096783416034,0.27756210745657145,643.76834940235426]
[-6.834367991428735,-0.58491824545407001,{"$f":"IF(A151<>\"\",RANK(A151,A$4:A$1003,1)+SUM(IF(A$4:A151=A151,1,0))-1.5,\"\")","v":147.5},-0.63147791387576269,0.27930134486328873,645.82251001724808]
[-6.7044722766959239,-0.57380114235853319,{"$f":"IF(A152<>\"\",RANK(A152,A$4:A$1003,1)+SUM(IF(A$4:A152=A152,1,0))-1.5,\"\")","v":148.5},-0.62601377924777157,0.28305118781717831,648.04030759245597]
[-6.6673415616833154,-0.57062331630279883,{"$f":"IF(A153<>\"\",RANK(A153,A$4:A$1003,1)+SUM(IF(A$4:A153=A153,1,0))-1.5,\"\")","v":149.5},-0.62056827180753826,0.28412750489340122,649.99469883487143]
[-6.6121662462237509,-0.56590114612532649,{"$f":"IF(A154<>\"\",RANK(A154,A$4:A$1003,1)+SUM(IF(A$4:A154=A154,1,0))-1.5,\"\")","v":150.5},-0.61514110459597382,0.2857304912032963,651.98093488671577]
[-6.5464663835355168,-0.56027823432742696,{"$f":"IF(A155<>\"\",RANK(A155,A$4:A$1003,1)+SUM(IF(A$4:A155=A155,1,0))-1.5,\"\")","v":151.5},-0.60973199570108105,0.28764483559675968,653.97732960130816]
[-6.4216052214314914,-0.54959201257951007,{"$f":"IF(A156<>\"\",RANK(A156,A$4:A$1003,1)+SUM(IF(A$4:A156=A156,1,0))-1.5,\"\")","v":152.5},-0.60434066812581888,0.29129961926259906,656.1220316372179]
[-6.4142828771127824,-0.54896533096141709,{"$f":"IF(A157<>\"\",RANK(A157,A$4:A$1003,1)+SUM(IF(A$4:A157=A157,1,0))-1.5,\"\")","v":153.5},-0.59896684966012592,0.29151462109508208,657.91976053789858]
[-6.378327833669573,-0.54588812456099922,{"$f":"IF(A158<>\"\",RANK(A158,A$4:A$1003,1)+SUM(IF(A$4:A158=A158,1,0))-1.5,\"\")","v":154.5},-0.59361027275695866,0.29257142096580585,659.78530833686091]
[-6.3666911663203791,-0.54489220232541535,{"$f":"IF(A159<>\"\",RANK(A159,A$4:A$1003,1)+SUM(IF(A$4:A159=A159,1,0))-1.5,\"\")","v":155.5},-0.58827067441217329,0.29291382978481362,661.57809814908182]
[-6.2367954515866586,-0.53377509922980082,{"$f":"IF(A160<>\"\",RANK(A160,A$4:A$1003,1)+SUM(IF(A$4:A160=A160,1,0))-1.5,\"\")","v":156.5},-0.58294779604812486,0.29674857180836356,663.64717286135783]
[-6.2367319001377837,-0.533769660189641,{"$f":"IF(A161<>\"\",RANK(A161,A$4:A$1003,1)+SUM(IF(A$4:A161=A161,1,0))-1.5,\"\")","v":157.5},-0.57764138340082438,0.29675045356852364,665.37298255574558]
[-6.1025854138224531,-0.5222887555166954,{"$f":"IF(A162<>\"\",RANK(A162,A$4:A$1003,1)+SUM(IF(A$4:A162=A162,1,0))-1.5,\"\")","v":158.5},-0.5723511864105375,0.30073464853475917,667.42176864685598]
[-6.0512689794231846,-0.51789684703160421,{"$f":"IF(A163<>\"\",RANK(A163,A$4:A$1003,1)+SUM(IF(A$4:A163=A163,1,0))-1.5,\"\")","v":159.5},-0.56707695911568679,0.30226512099730501,669.24073950536217]
[-6.0387814523010093,-0.51682810410416358,{"$f":"IF(A164<>\"\",RANK(A164,A$4:A$1003,1)+SUM(IF(A$4:A164=A164,1,0))-1.5,\"\")","v":160.5},-0.56181845954993936,0.30263807976419732,670.94411032139897]
[-5.8592039439863584,-0.50145899298544783,{"$f":"IF(A165<>\"\",RANK(A165,A$4:A$1003,1)+SUM(IF(A$4:A165=A165,1,0))-1.5,\"\")","v":161.5},-0.55657544964236316,0.30802406537729454,673.07974872239151]
[-5.8297203850897859,-0.49893564751134389,{"$f":"IF(A166<>\"\",RANK(A166,A$4:A$1003,1)+SUM(IF(A$4:A166=A166,1,0))-1.5,\"\")","v":162.5},-0.55134769512053772,0.30891235998857802,674.78122737757349]
[-5.6219656196217329,-0.4811549905354906,{"$f":"IF(A167<>\"\",RANK(A167,A$4:A$1003,1)+SUM(IF(A$4:A167=A167,1,0))-1.5,\"\")","v":163.5},-0.54613496541651507,0.31520317370852935,677.03265079950597]
[-5.6151022445510534,-0.48056758972399327,{"$f":"IF(A168<>\"\",RANK(A168,A$4:A$1003,1)+SUM(IF(A$4:A168=A168,1,0))-1.5,\"\")","v":164.5},-0.54093703357552436,0.31541192740387747,678.60719704231042]
[-5.4866434617360937,-0.46957346620715068,{"$f":"IF(A169<>\"\",RANK(A169,A$4:A$1003,1)+SUM(IF(A$4:A169=A169,1,0))-1.5,\"\")","v":165.5},-0.53575367616732628,0.31932989272456713,680.5878203685445]
[-5.4643516169835493,-0.46766562238941206,{"$f":"IF(A170<>\"\",RANK(A170,A$4:A$1003,1)+SUM(IF(A$4:A170=A170,1,0))-1.5,\"\")","v":166.5},-0.5305846732001186,0.32001186445221147,682.17801410512834]
[-5.455200450223856,-0.46688242130751939,{"$f":"IF(A171<>\"\",RANK(A171,A$4:A$1003,1)+SUM(IF(A$4:A171=A171,1,0))-1.5,\"\")","v":167.5},-0.52542980803690487,0.32029200135260538,683.71496099532874]
[-5.4447394544449708,-0.4659871187273299,{"$f":"IF(A172<>\"\",RANK(A172,A$4:A$1003,1)+SUM(IF(A$4:A172=A172,1,0))-1.5,\"\")","v":168.5},-0.52028886731423896,0.32061236042978736,685.25110595832666]
[-5.4159761251457894,-0.46352541398327723,{"$f":"IF(A173<>\"\",RANK(A173,A$4:A$1003,1)+SUM(IF(A$4:A173=A173,1,0))-1.5,\"\")","v":169.5},-0.51516164086325966,0.32149390137442918,686.83365396147133]
[-5.3881272070666455,-0.4611419689710855,{"$f":"IF(A174<>\"\",RANK(A174,A$4:A$1003,1)+SUM(IF(A$4:A174=A174,1,0))-1.5,\"\")","v":170.5},-0.51004792163294088,0.32234837639022407,688.40149692995374]
[-5.3749229776249194,-0.46001188719507974,{"$f":"IF(A175<>\"\",RANK(A175,A$4:A$1003,1)+SUM(IF(A$4:A175=A175,1,0))-1.5,\"\")","v":171.5},-0.50494750561547486,0.32275384406311003,689.92017863795331]
[-5.3689069350502905,-0.45949700519403097,{"$f":"IF(A176<>\"\",RANK(A176,A$4:A$1003,1)+SUM(IF(A$4:A176=A176,1,0))-1.5,\"\")","v":172.5},-0.49986019177371771,0.32293865108078534,691.41594498698623]
[-5.3249763964167869,-0.45573721736703687,{"$f":"IF(A177<>\"\",RANK(A177,A$4:A$1003,1)+SUM(IF(A$4:A177=A177,1,0))-1.5,\"\")","v":173.5},-0.49478578197062606,0.32428947783791395,692.9878811226356]
[-5.1610886181333626,-0.44171090917801792,{"$f":"IF(A178<>\"\",RANK(A178,A$4:A$1003,1)+SUM(IF(A$4:A178=A178,1,0))-1.5,\"\")","v":174.5},-0.48972408090061603,0.32934920722007016,694.83285473103285]
[-5.1078092038405885,-0.43715099938591323,{"$f":"IF(A179<>\"\",RANK(A179,A$4:A$1003,1)+SUM(IF(A$4:A179=A179,1,0))-1.5,\"\")","v":175.5},-0.48467489602278113,0.3310009216994092,696.39055735386319]
[-5.1045399222039123,-0.43687119846193329,{"$f":"IF(A180<>\"\",RANK(A180,A$4:A$1003,1)+SUM(IF(A$4:A180=A180,1,0))-1.5,\"\")","v":176.5},-0.47963803749590433,0.33110238026337879,697.8057218448065]
[-5.0327604654930838,-0.43072796562290311,{"$f":"IF(A181<>\"\",RANK(A181,A$4:A$1003,1)+SUM(IF(A$4:A181=A181,1,0))-1.5,\"\")","v":177.5},-0.47461331811520274,0.33333309105685904,699.37722070287282]
[-4.9966112404263185,-0.4276341402205977,{"$f":"IF(A182<>\"\",RANK(A182,A$4:A$1003,1)+SUM(IF(A$4:A182=A182,1,0))-1.5,\"\")","v":178.5},-0.46960055325075234,0.33445875301836747,700.84599215182902]
[-4.8831890367710002,-0.41792691982496877,{"$f":"IF(A183<>\"\",RANK(A183,A$4:A$1003,1)+SUM(IF(A$4:A183=A183,1,0))-1.5,\"\")","v":179.5},-0.46459956078752895,0.33800027485931705,702.49039166451053]
[-4.7500240404024225,-0.40653001580552989,{"$f":"IF(A184<>\"\",RANK(A184,A$4:A$1003,1)+SUM(IF(A$4:A184=A184,1,0))-1.5,\"\")","v":180.5},-0.45961016106701963,0.34217660356639457,704.19242793790613]
[-4.6493506242168223,-0.39791389826064144,{"$f":"IF(A185<>\"\",RANK(A185,A$4:A$1003,1)+SUM(IF(A$4:A185=A185,1,0))-1.5,\"\")","v":181.5},-0.45463217683034735,0.34534682743063383,705.7993202087755]
[-4.5673078806248668,-0.39089228372448409,{"$f":"IF(A186<>\"\",RANK(A186,A$4:A$1003,1)+SUM(IF(A$4:A186=A186,1,0))-1.5,\"\")","v":182.5},-0.44966543316286056,0.34793842890750615,707.33642065448521]
[-4.4728446886383608,-0.38280766718260978,{"$f":"IF(A187<>\"\",RANK(A187,A$4:A$1003,1)+SUM(IF(A$4:A187=A187,1,0))-1.5,\"\")","v":183.5},-0.44470975744014091,0.35093118808222523,708.90422082937471]
[-4.4418571190972216,-0.38015560120816588,{"$f":"IF(A188<>\"\",RANK(A188,A$4:A$1003,1)+SUM(IF(A$4:A188=A188,1,0))-1.5,\"\")","v":184.5},-0.43976497927538261,0.351914957291386,710.2372358218679]
[-4.1665065897732347,-0.35658977204896758,{"$f":"IF(A189<>\"\",RANK(A189,A$4:A$1003,1)+SUM(IF(A$4:A189=A189,1,0))-1.5,\"\")","v":185.5},-0.43483093046809762,0.3606994677474612,712.50579397466549]
[-4.1526492094599234,-0.35540379046447862,{"$f":"IF(A190<>\"\",RANK(A190,A$4:A$1003,1)+SUM(IF(A$4:A190=A190,1,0))-1.5,\"\")","v":186.5},-0.42990744495410521,0.36114355480267246,713.70919478734618]
[-4.1495105579988376,-0.35513516950230434,{"$f":"IF(A191<>\"\",RANK(A191,A$4:A$1003,1)+SUM(IF(A$4:A191=A191,1,0))-1.5,\"\")","v":187.5},-0.42499435875676506,0.36124416509741497,714.86256782795158]
[-4.1007431756370352,-0.35096142121098617,{"$f":"IF(A192<>\"\",RANK(A192,A$4:A$1003,1)+SUM(IF(A$4:A192=A192,1,0))-1.5,\"\")","v":188.5},-0.4200915099394113,0.36280864554247616,716.19044294960486]
[-4.0709312776652951,-0.34840997489185876,{"$f":"IF(A193<>\"\",RANK(A193,A$4:A$1003,1)+SUM(IF(A$4:A193=A193,1,0))-1.5,\"\")","v":189.5},-0.41519873855895434,0.36376615619499919,717.42924143163145]
[-4.0398801566770999,-0.34575246987741076,{"$f":"IF(A194<>\"\",RANK(A194,A$4:A$1003,1)+SUM(IF(A$4:A194=A194,1,0))-1.5,\"\")","v":190.5},-0.41031588662060708,0.36476437402360651,718.66049637919673]
[-4.0144496604625601,-0.34357600509741998,{"$f":"IF(A195<>\"\",RANK(A195,A$4:A$1003,1)+SUM(IF(A$4:A195=A195,1,0))-1.5,\"\")","v":191.5},-0.40544279803370531,0.36558258625413864,719.85915375564673]
[-3.9297272346584577,-0.33632505040576177,{"$f":"IF(A196<>\"\",RANK(A196,A$4:A$1003,1)+SUM(IF(A$4:A196=A196,1,0))-1.5,\"\")","v":192.5},-0.40057931856858597,0.36831288078579438,721.25832151238728]
[-3.8538947152637775,{"$f":"+IF(A197<>\"\",(A197-K$2)/K$3,\"\")","v":-0.3298349368724629},{"$f":"IF(A197<>\"\",RANK(A197,A$4:A$1003,1)+SUM(IF(A$4:A197=A197,1,0))-1.5,\"\")","v":193.5},{"$f":"IF(A197<>\"\",NORMSINV(C197/($K$1)),\"\")","v":-0.39572529581448734},{"$f":"IF(A197<>\"\",NORMDIST(A197,$K$2,$K$3,1),\"\")","v":0.37076234371877465},{"$f":"IF(A197<>\"\",-2*C197*LN(E197)-(2*$K$1-2*C197)*LN(1-E197),\"\")","v":722.61209709651894}]
[-3.8478151212402736,-0.32931461583125438,{"$f":"IF(A198<>\"\",RANK(A198,A$4:A$1003,1)+SUM(IF(A$4:A198=A198,1,0))-1.5,\"\")","v":194.5},-0.39088057913844493,0.37095894892686282,723.69158264065572]
[-3.8044071033045839,-0.32559954785109352,{"$f":"IF(A199<>\"\",RANK(A199,A$4:A$1003,1)+SUM(IF(A$4:A199=A199,1,0))-1.5,\"\")","v":195.5},-0.38604501964514715,0.37236367716603141,724.8952689019344]
[-3.7467498145315403,-0.32066495840126041,{"$f":"IF(A200<>\"\",RANK(A200,A$4:A$1003,1)+SUM(IF(A$4:A200=A200,1,0))-1.5,\"\")","v":196.5},-0.3812184701377227,0.37423215257597853,726.13390039640683]
[-3.7338703968880509,-0.31956267558887003,{"$f":"IF(A201<>\"\",RANK(A201,A$4:A$1003,1)+SUM(IF(A$4:A201=A201,1,0))-1.5,\"\")","v":197.5},-0.37640078507943142,0.37464993617208109,727.20424452671011]
[-3.6426764865364021,-0.31175785997081995,{"$f":"IF(A202<>\"\",RANK(A202,A$4:A$1003,1)+SUM(IF(A$4:A202=A202,1,0))-1.5,\"\")","v":198.5},-0.37159182055622908,0.37761227591375912,728.52572544845532]
[-3.580768426180839,-0.30645946894357801,{"$f":"IF(A203<>\"\",RANK(A203,A$4:A$1003,1)+SUM(IF(A$4:A203=A203,1,0))-1.5,\"\")","v":199.5},-0.3667914342401824,0.37962741762348745,729.73322516940107]
[-3.5703074304010443,-0.30556416636331069,{"$f":"IF(A204<>\"\",RANK(A204,A$4:A$1003,1)+SUM(IF(A$4:A204=A204,1,0))-1.5,\"\")","v":200.5},-0.3619994853537038,0.37996825367008774,730.74965378434422]
[-3.4079872142101522,-0.29167201771471368,{"$f":"IF(A205<>\"\",RANK(A205,A$4:A$1003,1)+SUM(IF(A$4:A205=A205,1,0))-1.5,\"\")","v":201.5},-0.35721583463458467,0.38526870299494242,732.28471187997366]
[-3.3211076268898978,-0.28423644271423226,{"$f":"IF(A206<>\"\",RANK(A206,A$4:A$1003,1)+SUM(IF(A$4:A206=A206,1,0))-1.5,\"\")","v":202.5},-0.35244034430180049,0.3881145947039798,733.54704305386963]
[-3.2793342497725462,-0.28066127519606138,{"$f":"IF(A207<>\"\",RANK(A207,A$4:A$1003,1)+SUM(IF(A$4:A207=A207,1,0))-1.5,\"\")","v":203.5},-0.34767287802206598,0.38948510661951696,734.61715992979657]
[-3.268809702542967,-0.27976053357555647,{"$f":"IF(A208<>\"\",RANK(A208,A$4:A$1003,1)+SUM(IF(A$4:A208=A208,1,0))-1.5,\"\")","v":204.5},-0.3429133008771163,0.38983061635023142,735.55481277440845]
[-3.2650179002093864,-0.27943601280482111,{"$f":"IF(A209<>\"\",RANK(A209,A$4:A$1003,1)+SUM(IF(A$4:A209=A209,1,0))-1.5,\"\")","v":205.5},-0.33816147933169205,0.38995511855292792,736.46389384764757]
[-3.2476935293598217,-0.27795330941313429,{"$f":"IF(A210<>\"\",RANK(A210,A$4:A$1003,1)+SUM(IF(A$4:A210=A210,1,0))-1.5,\"\")","v":206.5},-0.33341728120220893,0.39052410029267176,737.41458049023436]
[-3.2383446537005511,-0.27715318744802364,{"$f":"IF(A211<>\"\",RANK(A211,A$4:A$1003,1)+SUM(IF(A$4:A211=A211,1,0))-1.5,\"\")","v":207.5},-0.32868057562608866,0.39083124153415155,738.3328984306437]
[-3.2129812362118173,-0.27498246358960088,{"$f":"IF(A212<>\"\",RANK(A212,A$4:A$1003,1)+SUM(IF(A$4:A212=A212,1,0))-1.5,\"\")","v":208.5},-0.32395123303173357,0.39166485558751712,739.29199154246214]
[-3.209842584749822,-0.27471384262734871,{"$f":"IF(A213<>\"\",RANK(A213,A$4:A$1003,1)+SUM(IF(A$4:A213=A213,1,0))-1.5,\"\")","v":209.5},-0.31922912510912399,0.39176804766010243,740.18083252847691]
[-3.1794446146323025,-0.27211223742130608,{"$f":"IF(A214<>\"\",RANK(A214,A$4:A$1003,1)+SUM(IF(A$4:A214=A214,1,0))-1.5,\"\")","v":210.5},-0.31451412478102059,0.39276786017977605,741.13423218002845]
[-3.1385220972870229,-0.26860989059491419,{"$f":"IF(A215<>\"\",RANK(A215,A$4:A$1003,1)+SUM(IF(A$4:A215=A215,1,0))-1.5,\"\")","v":211.5},-0.30980610617475302,0.39411495017421067,742.10082877668231]
[-3.0722997139009749,-0.26294225895018147,{"$f":"IF(A216<>\"\",RANK(A216,A$4:A$1003,1)+SUM(IF(A$4:A216=A216,1,0))-1.5,\"\")","v":212.5},-0.30510494459457788,0.39629754202526779,743.11470039122128]
[-3.0660224109778937,-0.26240501702575497,{"$f":"IF(A217<>\"\",RANK(A217,A$4:A$1003,1)+SUM(IF(A$4:A217=A217,1,0))-1.5,\"\")","v":213.5},-0.30041051649458861,0.39650460257052161,743.97053167207798]
[-3.0460183579152726,-0.26069297347848952,{"$f":"IF(A218<>\"\",RANK(A218,A$4:A$1003,1)+SUM(IF(A$4:A218=A218,1,0))-1.5,\"\")","v":214.5},-0.29572269945216134,0.39716464254952094,744.85106193376782]
[-3.0048345802197218,-0.25716826672856424,{"$f":"IF(A219<>\"\",RANK(A219,A$4:A$1003,1)+SUM(IF(A$4:A219=A219,1,0))-1.5,\"\")","v":215.5},-0.29104137214191883,0.39852443991426123,745.76392249768151]
[-2.9861368289011807,-0.25556802279834301,{"$f":"IF(A220<>\"\",RANK(A220,A$4:A$1003,1)+SUM(IF(A$4:A220=A220,1,0))-1.5,\"\")","v":216.5},-0.28636641431020077,0.3991422063234088,746.62038283224888]
[-2.9663304847381369,-0.25387290013429548,{"$f":"IF(A221<>\"\",RANK(A221,A$4:A$1003,1)+SUM(IF(A$4:A221=A221,1,0))-1.5,\"\")","v":217.5},-0.2816977067500202,0.39979687579415718,747.4701391533506]
[-2.9618184528071652,-0.2534867386335089,{"$f":"IF(A222<>\"\",RANK(A222,A$4:A$1003,1)+SUM(IF(A$4:A222=A222,1,0))-1.5,\"\")","v":218.5},-0.27703513127649743,0.39994605382243659,748.2890136280746]
[-2.9007612522245836,-0.24826116829812378,{"$f":"IF(A223<>\"\",RANK(A223,A$4:A$1003,1)+SUM(IF(A$4:A223=A223,1,0))-1.5,\"\")","v":219.5},-0.27237857070275195,0.40196617091703912,749.17834712857996]
[-2.8807571991619625,-0.2465491247508583,{"$f":"IF(A224<>\"\",RANK(A224,A$4:A$1003,1)+SUM(IF(A$4:A224=A224,1,0))-1.5,\"\")","v":220.5},-0.26772790881624153,0.40262859084807562,749.99706181588567]
[-2.7622368914289837,-0.23640558396744976,{"$f":"IF(A225<>\"\",RANK(A225,A$4:A$1003,1)+SUM(IF(A$4:A225=A225,1,0))-1.5,\"\")","v":221.5},-0.26308303035553421,0.40655898180163191,750.93841328282736]
[-2.714514550462809,-0.23232127536979816,{"$f":"IF(A226<>\"\",RANK(A226,A$4:A$1003,1)+SUM(IF(A$4:A226=A226,1,0))-1.5,\"\")","v":222.5},-0.25844382098750129,0.40814424454356146,751.76324696181791]
[-2.6643067089053147,-0.22802424561829976,{"$f":"IF(A227<>\"\",RANK(A227,A$4:A$1003,1)+SUM(IF(A$4:A227=A227,1,0))-1.5,\"\")","v":223.5},-0.25381016728491673,0.40981369585583655,752.57724432956093]
[-2.6337781086140239,-0.22541146045060717,{"$f":"IF(A228<>\"\",RANK(A228,A$4:A$1003,1)+SUM(IF(A$4:A228=A228,1,0))-1.5,\"\")","v":224.5},-0.2491819567044527,0.41082959844826061,753.3476086879366]
[-2.5744861790235518,-0.22033697053886195,{"$f":"IF(A229<>\"\",RANK(A229,A$4:A$1003,1)+SUM(IF(A$4:A229=A229,1,0))-1.5,\"\")","v":225.5},-0.24455907756505796,0.41280436462351022,754.14540824880476]
[-2.5423229379148324,-0.21758428490925727,{"$f":"IF(A230<>\"\",RANK(A230,A$4:A$1003,1)+SUM(IF(A$4:A230=A230,1,0))-1.5,\"\")","v":226.5},-0.2399414190267081,0.41387651498529465,754.89047595717534]
[-2.5340191036493707,-0.21687360263765751,{"$f":"IF(A231<>\"\",RANK(A231,A$4:A$1003,1)+SUM(IF(A$4:A231=A231,1,0))-1.5,\"\")","v":227.5},-0.23532887106951692,0.41415342502700542,755.59538296431924]
[-2.3857539766722766,-0.20418435645684521,{"$f":"IF(A232<>\"\",RANK(A232,A$4:A$1003,1)+SUM(IF(A$4:A232=A232,1,0))-1.5,\"\")","v":228.5},-0.23072132447319676,0.41910471779069325,756.46808812034783]
[-2.3724826685047447,-0.20304853375927145,{"$f":"IF(A233<>\"\",RANK(A233,A$4:A$1003,1)+SUM(IF(A$4:A233=A233,1,0))-1.5,\"\")","v":229.5},-0.22611867079685813,0.41954854889658599,757.13886377125277]
[-2.3450927196745397,-0.2007043695537532,{"$f":"IF(A234<>\"\",RANK(A234,A$4:A$1003,1)+SUM(IF(A$4:A234=A234,1,0))-1.5,\"\")","v":230.5},-0.22152080235913765,0.42046487141595956,757.82034467787071]
[-2.31659065072472,-0.1982650247331561,{"$f":"IF(A235<>\"\",RANK(A235,A$4:A$1003,1)+SUM(IF(A$4:A235=A235,1,0))-1.5,\"\")","v":231.5},-0.21692761221864429,0.42141885734567408,758.4918708720229]
[-2.1903561081508087,-0.18746126244662692,{"$f":"IF(A236<>\"\",RANK(A236,A$4:A$1003,1)+SUM(IF(A$4:A236=A236,1,0))-1.5,\"\")","v":232.5},-0.21233899415471519,0.42564949666758767,759.27323759138994]
[-2.1521768244665509,-0.18419369481589562,{"$f":"IF(A237<>\"\",RANK(A237,A$4:A$1003,1)+SUM(IF(A$4:A237=A237,1,0))-1.5,\"\")","v":233.5},-0.20775484264846933,0.42693075283269311,759.92273757615658]
[-2.1379911050789815,-0.18297961238646096,{"$f":"IF(A238<>\"\",RANK(A238,A$4:A$1003,1)+SUM(IF(A$4:A238=A238,1,0))-1.5,\"\")","v":234.5},-0.20317505286415161,0.42740700774746232,760.52819629764133]
[-1.9861954361158496,-0.16998820535821318,{"$f":"IF(A239<>\"\",RANK(A239,A$4:A$1003,1)+SUM(IF(A$4:A239=A239,1,0))-1.5,\"\")","v":235.5},-0.19859952063075681,0.43250970620703244,761.31485726445885]
[-1.9580217062393785,-0.16757696138248396,{"$f":"IF(A240<>\"\",RANK(A240,A$4:A$1003,1)+SUM(IF(A$4:A240=A240,1,0))-1.5,\"\")","v":236.5},-0.19402814242392633,0.43345804851082681,761.90087871577157]
[-1.9556668358245588,-0.16737542019052062,{"$f":"IF(A241<>\"\",RANK(A241,A$4:A$1003,1)+SUM(IF(A$4:A241=A241,1,0))-1.5,\"\")","v":237.5},-0.18946081534810694,0.43353733209634587,762.43950653797583]
[-1.9533790441346355,-0.16717961992004746,{"$f":"IF(A242<>\"\",RANK(A242,A$4:A$1003,1)+SUM(IF(A$4:A242=A242,1,0))-1.5,\"\")","v":238.5},-0.18489743711896459,0.43361435984217217,762.97680000661182]
[-1.8365569286688697,-0.15718141863878865,{"$f":"IF(A243<>\"\",RANK(A243,A$4:A$1003,1)+SUM(IF(A$4:A243=A243,1,0))-1.5,\"\")","v":239.5},-0.18033790604604438,0.43755093602233375,763.63882666836002]
[-1.7496773413486153,-0.14974584363830723,{"$f":"IF(A244<>\"\",RANK(A244,A$4:A$1003,1)+SUM(IF(A$4:A244=A244,1,0))-1.5,\"\")","v":240.5},-0.17578212101566829,0.44048256897132682,764.25793932392321]
[-1.6972487868279131,-0.14525875453798151,{"$f":"IF(A245<>\"\",RANK(A245,A$4:A$1003,1)+SUM(IF(A$4:A245=A245,1,0))-1.5,\"\")","v":241.5},-0.1712299814740646,0.44225328918862072,764.8113894029309]
[-1.6934569844943326,-0.14493423376724615,{"$f":"IF(A246<>\"\",RANK(A246,A$4:A$1003,1)+SUM(IF(A$4:A246=A246,1,0))-1.5,\"\")","v":242.5},-0.1666813874107187,0.44238139857867109,765.28037315971574]
[-1.6661976658388085,-0.14260124952345568,{"$f":"IF(A247<>\"\",RANK(A247,A$4:A$1003,1)+SUM(IF(A$4:A247=A247,1,0))-1.5,\"\")","v":243.5},-0.16213623934193927,0.44330255529559148,765.77360936408354]
[-1.5203509607254091,-0.13011898357476651,{"$f":"IF(A248<>\"\",RANK(A248,A$4:A$1003,1)+SUM(IF(A$4:A248=A248,1,0))-1.5,\"\")","v":244.5},-0.15759443829463285,0.44823614554207325,766.41624468405325]
[-1.5042693401701399,-0.12874264075988631,{"$f":"IF(A249<>\"\",RANK(A249,A$4:A$1003,1)+SUM(IF(A$4:A249=A249,1,0))-1.5,\"\")","v":245.5},-0.15305588579027779,0.44878064685183144,766.85480991600321]
[-1.4853103285022371,-0.12712003690620952,{"$f":"IF(A250<>\"\",RANK(A250,A$4:A$1003,1)+SUM(IF(A$4:A250=A250,1,0))-1.5,\"\")","v":246.5},-0.14852048382909327,0.44942269647805771,767.28961115789241]
[-1.4805370362228132,-0.12671151548204523,{"$f":"IF(A251<>\"\",RANK(A251,A$4:A$1003,1)+SUM(IF(A$4:A251=A251,1,0))-1.5,\"\")","v":247.5},-0.14398813487439385,0.44958436563593318,767.70054759278366]
[-1.4743938907504344,-0.12618575540067695,{"$f":"IF(A252<>\"\",RANK(A252,A$4:A$1003,1)+SUM(IF(A$4:A252=A252,1,0))-1.5,\"\")","v":248.5},-0.13945874183712378,0.44979244338768898,768.11008404271547]
[-1.4434063212111141,-0.12353368942638873,{"$f":"IF(A253<>\"\",RANK(A253,A$4:A$1003,1)+SUM(IF(A$4:A253=A253,1,0))-1.5,\"\")","v":249.5},-0.13493220806056549,0.45084224914325816,768.53199577299665]
[-1.3720858337474056,-0.11742973739387638,{"$f":"IF(A254<>\"\",RANK(A254,A$4:A$1003,1)+SUM(IF(A$4:A254=A254,1,0))-1.5,\"\")","v":250.5},-0.1304084373052132,0.45325976002809593,768.96940531335702]
[-1.3629982184365872,-0.11665197535214347,{"$f":"IF(A255<>\"\",RANK(A255,A$4:A$1003,1)+SUM(IF(A$4:A255=A255,1,0))-1.5,\"\")","v":251.5},-0.12588733373380909,0.45356792423473502,769.34929235588288]
[-1.353779972951088,-0.1158630333486828,{"$f":"IF(A256<>\"\",RANK(A256,A$4:A$1003,1)+SUM(IF(A$4:A256=A256,1,0))-1.5,\"\")","v":252.5},-0.12136880189653143,0.45388054672127509,769.72467748517374]
[-1.3078229029770227,-0.11192980517467109,{"$f":"IF(A257<>\"\",RANK(A257,A$4:A$1003,1)+SUM(IF(A$4:A257=A257,1,0))-1.5,\"\")","v":253.5},-0.116852746716332,0.45543953198934295,770.10292066690658]
[-1.2098291690044789,-0.1035430277853613,{"$f":"IF(A258<>\"\",RANK(A258,A$4:A$1003,1)+SUM(IF(A$4:A258=A258,1,0))-1.5,\"\")","v":254.5},-0.11233907347441428,0.45876600087822089,770.48770529172407]
[-1.1771434071979456,-0.10074562230892335,{"$f":"IF(A259<>\"\",RANK(A259,A$4:A$1003,1)+SUM(IF(A$4:A259=A259,1,0))-1.5,\"\")","v":255.5},-0.1078276877958492,0.45987619710947786,770.82959776844314]
[-1.0599964799348527,-9.0719622064127065E-2,{"$f":"IF(A260<>\"\",RANK(A260,A$4:A$1003,1)+SUM(IF(A$4:A260=A260,1,0))-1.5,\"\")","v":256.5},-0.10331849563531949,0.46385768938494726,771.20521327066672]
[-1.0441090410031393,{"$f":"+IF(A261<>\"\",(A261-K$2)/K$3,\"\")","v":-8.9359898251134426E-2},{"$f":"IF(A261<>\"\",RANK(A261,A$4:A$1003,1)+SUM(IF(A$4:A261=A261,1,0))-1.5,\"\")","v":257.5},{"$f":"IF(A261<>\"\",NORMSINV(C261/($K$1)),\"\")","v":-9.8811403262989275E-2},{"$f":"IF(A261<>\"\",NORMDIST(A261,$K$2,$K$3,1),\"\")","v":0.46439794624358222},{"$f":"IF(A261<>\"\",-2*C261*LN(E261)-(2*$K$1-2*C261)*LN(1-E261),\"\")","v":771.5033174483076}]
[-0.98390270019172021,-8.4207148607450447E-2,{"$f":"IF(A262<>\"\",RANK(A262,A$4:A$1003,1)+SUM(IF(A$4:A262=A262,1,0))-1.5,\"\")","v":258.5},-9.4306317250492239E-2,0.46644586730553145,771.81612146718544]
[-0.96644769916747464,-8.2713265254035842E-2,{"$f":"IF(A263<>\"\",RANK(A263,A$4:A$1003,1)+SUM(IF(A$4:A263=A263,1,0))-1.5,\"\")","v":259.5},-8.9803144457032483E-2,0.46703976843531525,772.09168389034164]
[-0.94801120819738571,-8.1135381247192315E-2,{"$f":"IF(A264<>\"\",RANK(A264,A$4:A$1003,1)+SUM(IF(A$4:A264=A264,1,0))-1.5,\"\")","v":260.5},-8.5301792015594347E-2,0.46766714413212601,772.35953196638184]
[-0.91722134755764273,-7.8500236156122047E-2,{"$f":"IF(A265<>\"\",RANK(A265,A$4:A$1003,1)+SUM(IF(A$4:A265=A265,1,0))-1.5,\"\")","v":261.5},-8.0802167319253285E-2,0.4687150711892703,772.62039814862669]
[-0.89492950280509831,-7.65923923383834E-2,{"$f":"IF(A266<>\"\",RANK(A266,A$4:A$1003,1)+SUM(IF(A$4:A266=A266,1,0))-1.5,\"\")","v":262.5},-7.6304178007584184E-2,0.46947390560518598,772.86932188585001]
[-0.89414572175883222,-7.652531256817241E-2,{"$f":"IF(A267<>\"\",RANK(A267,A$4:A$1003,1)+SUM(IF(A$4:A267=A267,1,0))-1.5,\"\")","v":263.5},-7.1807731953161674E-2,0.46950058825005131,773.11360834781271]
[-0.77895824711140449,-6.666701174890359E-2,{"$f":"IF(A268<>\"\",RANK(A268,A$4:A$1003,1)+SUM(IF(A$4:A268=A268,1,0))-1.5,\"\")","v":264.5},-6.7312737248146085E-2,0.47342339833733094,773.3279043706782]
[-0.774252033556877,-6.6264231246229474E-2,{"$f":"IF(A269<>\"\",RANK(A269,A$4:A$1003,1)+SUM(IF(A$4:A269=A269,1,0))-1.5,\"\")","v":265.5},-6.2819102190952214E-2,0.47358372997024156,773.53967393874632]
[-0.73071338544741593,-6.2537983304418704E-2,{"$f":"IF(A270<>\"\",RANK(A270,A$4:A$1003,1)+SUM(IF(A$4:A270=A270,1,0))-1.5,\"\")","v":266.5},-5.8326735272993049E-2,0.47506720740973069,773.73511233224485]
[-0.69626235264786374,-5.958949740426301E-2,{"$f":"IF(A271<>\"\",RANK(A271,A$4:A$1003,1)+SUM(IF(A$4:A271=A271,1,0))-1.5,\"\")","v":267.5},-5.3835545165495387E-2,0.47624129168097507,773.9195888083741]
[-0.64017262596735236,-5.4789067494851865E-2,{"$f":"IF(A272<>\"\",RANK(A272,A$4:A$1003,1)+SUM(IF(A$4:A272=A272,1,0))-1.5,\"\")","v":268.5},-4.9345440706381916E-2,0.47815325509804468,774.08302814606964]
[-0.63703397450626653,-5.4520446532677548E-2,{"$f":"IF(A273<>\"\",RANK(A273,A$4:A$1003,1)+SUM(IF(A$4:A273=A273,1,0))-1.5,\"\")","v":269.5},-4.4856330887213788E-2,0.47826025941895178,774.25604166907306]
[-0.59741775890324789,-5.1129899323174237E-2,{"$f":"IF(A274<>\"\",RANK(A274,A$4:A$1003,1)+SUM(IF(A$4:A274=A274,1,0))-1.5,\"\")","v":270.5},-4.0368124840191193E-2,0.47961100546537822,774.40002946244635]
[-0.58650132115144515,-5.0195617817641661E-2,{"$f":"IF(A275<>\"\",RANK(A275,A$4:A$1003,1)+SUM(IF(A$4:A275=A275,1,0))-1.5,\"\")","v":271.5},-3.5880731825204196E-2,0.47998325181437024,774.5534082128147]
[-0.57512591415070347,-4.922205550543559E-2,{"$f":"IF(A276<>\"\",RANK(A276,A$4:A$1003,1)+SUM(IF(A$4:A276=A276,1,0))-1.5,\"\")","v":272.5},-3.1394061216931217E-2,0.48037116740823516,774.70094340585752]
[-0.55995870481638121,-4.792397242249416E-2,{"$f":"IF(A277<>\"\",RANK(A277,A$4:A$1003,1)+SUM(IF(A$4:A277=A277,1,0))-1.5,\"\")","v":273.5},-2.6908022491978715E-2,0.48088841705388202,774.8380467455313]
[-0.46150952887273888,-3.9498216107996954E-2,{"$f":"IF(A278<>\"\",RANK(A278,A$4:A$1003,1)+SUM(IF(A$4:A278=A278,1,0))-1.5,\"\")","v":274.5},-2.2422525216059669E-2,0.48424658787409003,774.86338645994715]
[-0.3697895705463452,-3.1648378761705398E-2,{"$f":"IF(A279<>\"\",RANK(A279,A$4:A$1003,1)+SUM(IF(A$4:A279=A279,1,0))-1.5,\"\")","v":275.5},-1.7937479031203175E-2,0.48737623101062716,774.89094294827169]
[-0.34632205422440165,-2.9639915288650284E-2,{"$f":"IF(A280<>\"\",RANK(A280,A$4:A$1003,1)+SUM(IF(A$4:A280=A280,1,0))-1.5,\"\")","v":276.5},-1.3452793642992681E-2,0.48817711574491596,774.96738255585694]
[-0.22734277724339336,-1.9457093698646098E-2,{"$f":"IF(A281<>\"\",RANK(A281,A$4:A$1003,1)+SUM(IF(A$4:A281=A281,1,0))-1.5,\"\")","v":277.5},-8.9683788078274602E-3,0.49223823241268311,774.94907374178888]
[-0.15844071164428897,-1.35601218983347E-2,{"$f":"IF(A282<>\"\",RANK(A282,A$4:A$1003,1)+SUM(IF(A$4:A282=A282,1,0))-1.5,\"\")","v":278.5},-4.48414432020187E-3,0.49459045982944982,774.96070603299063]
[-0.13412233555118291,-1.1478837733578436E-2,{"$f":"IF(A283<>\"\",RANK(A283,A$4:A$1003,1)+SUM(IF(A$4:A283=A283,1,0))-1.5,\"\")","v":279.5},0,0.49542070686254225,774.98543858636447]
[-8.9799906395455764E-2,-7.68551002155669E-3,{"$f":"IF(A284<>\"\",RANK(A284,A$4:A$1003,1)+SUM(IF(A$4:A284=A284,1,0))-1.5,\"\")","v":280.5},4.48414432020187E-3,0.49693395528969181,774.98409673541005]
[-4.4757247640518472E-2,-3.8305415793280567E-3,{"$f":"IF(A285<>\"\",RANK(A285,A$4:A$1003,1)+SUM(IF(A$4:A285=A285,1,0))-1.5,\"\")","v":281.5},8.9683788078274602E-3,0.49847183874430206,774.96822022560787]
[5.1863105862139491E-2,4.4386952713694749E-3,{"$f":"IF(A286<>\"\",RANK(A286,A$4:A$1003,1)+SUM(IF(A$4:A286=A286,1,0))-1.5,\"\")","v":282.5},1.3452793642992822E-2,0.50177077739891796,774.9030603939384]
[0.10376913968593726,8.8810645249397732E-3,{"$f":"IF(A287<>\"\",RANK(A287,A$4:A$1003,1)+SUM(IF(A$4:A287=A287,1,0))-1.5,\"\")","v":283.5},1.7937479031203313E-2,0.50354298555941246,774.85323907674115]
[0.12743436490745808,1.0906448881212834E-2,{"$f":"IF(A288<>\"\",RANK(A288,A$4:A$1003,1)+SUM(IF(A$4:A288=A288,1,0))-1.5,\"\")","v":284.5},2.2422525216059527E-2,0.50435095732939783,774.80683611763357]
[0.18568125310321193,1.589149909936937E-2,{"$f":"IF(A289<>\"\",RANK(A289,A$4:A$1003,1)+SUM(IF(A$4:A289=A289,1,0))-1.5,\"\")","v":285.5},2.6908022491978573E-2,0.50633952405827998,774.72410549548681]
[0.18744652409532137,1.6042579523009273E-2,{"$f":"IF(A290<>\"\",RANK(A290,A$4:A$1003,1)+SUM(IF(A$4:A290=A290,1,0))-1.5,\"\")","v":286.5},3.1394061216931078E-2,0.50639978874433322,774.67172813932507]
[0.2528851264351033,2.1643131397531039E-2,{"$f":"IF(A291<>\"\",RANK(A291,A$4:A$1003,1)+SUM(IF(A$4:A291=A291,1,0))-1.5,\"\")","v":287.5},3.5880731825204196E-2,0.50863368615022808,774.552634517873]
[0.26961989786195772,2.3075374020894428E-2,{"$f":"IF(A292<>\"\",RANK(A292,A$4:A$1003,1)+SUM(IF(A$4:A292=A292,1,0))-1.5,\"\")","v":288.5},4.0368124840191193E-2,0.50920492543022777,774.46520819691386]
[0.29315449290879769,2.5089578415439712E-2,{"$f":"IF(A293<>\"\",RANK(A293,A$4:A$1003,1)+SUM(IF(A$4:A293=A293,1,0))-1.5,\"\")","v":289.5},4.4856330887213788E-2,0.5100082436065696,774.36179510677039]
[0.36179529815944989,3.0964190292373399E-2,{"$f":"IF(A294<>\"\",RANK(A294,A$4:A$1003,1)+SUM(IF(A$4:A294=A294,1,0))-1.5,\"\")","v":290.5},4.9345440706381916E-2,0.51235095101146721,774.19263997237317]
[0.42318083781628957,3.6217861472704255E-2,{"$f":"IF(A295<>\"\",RANK(A295,A$4:A$1003,1)+SUM(IF(A$4:A295=A295,1,0))-1.5,\"\")","v":291.5},5.3835545165495532E-2,0.51444567803155428,774.01817471909089]
[0.46848475691967906,4.0095189838310598E-2,{"$f":"IF(A296<>\"\",RANK(A296,A$4:A$1003,1)+SUM(IF(A$4:A296=A296,1,0))-1.5,\"\")","v":292.5},5.8326735272993181E-2,0.51599138166364877,773.84696891587714]
[0.53065407762278483,4.541594078885243E-2,{"$f":"IF(A297<>\"\",RANK(A297,A$4:A$1003,1)+SUM(IF(A$4:A297=A297,1,0))-1.5,\"\")","v":293.5},6.2819102190952353E-2,0.51811211240726918,773.64310167501083]
[0.7929945591276919,6.7868307173854683E-2,{"$f":"IF(A298<>\"\",RANK(A298,A$4:A$1003,1)+SUM(IF(A$4:A298=A298,1,0))-1.5,\"\")","v":294.5},6.7312737248145946E-2,0.52705476611327029,773.32786589048999]
[0.86732306787780544,7.4229700206813562E-2,{"$f":"IF(A299<>\"\",RANK(A299,A$4:A$1003,1)+SUM(IF(A$4:A299=A299,1,0))-1.5,\"\")","v":295.5},7.1807731953161549E-2,0.5295861931564585,773.10778703307915]
[0.86856581817301048,7.4336060783698046E-2,{"$f":"IF(A300<>\"\",RANK(A300,A$4:A$1003,1)+SUM(IF(A$4:A300=A300,1,0))-1.5,\"\")","v":296.5},7.6304178007584184E-2,0.52962850798086358,772.87066796355646]
[0.87418644294757542,7.4817101018233065E-2,{"$f":"IF(A301<>\"\",RANK(A301,A$4:A$1003,1)+SUM(IF(A$4:A301=A301,1,0))-1.5,\"\")","v":297.5},8.0802167319253285E-2,0.52981988234632427,772.63123520068689]
[0.9300149092787251,7.9595171004188656E-2,{"$f":"IF(A302<>\"\",RANK(A302,A$4:A$1003,1)+SUM(IF(A$4:A302=A302,1,0))-1.5,\"\")","v":298.5},8.5301792015594347E-2,0.53172038199357274,772.36492974994246]
[0.94622716000776563,8.0982693780718776E-2,{"$f":"IF(A303<>\"\",RANK(A303,A$4:A$1003,1)+SUM(IF(A$4:A303=A303,1,0))-1.5,\"\")","v":299.5},8.9803144457032483E-2,0.53227214217159413,772.10145530777754]
[0.9750575680327529,8.3450139446339458E-2,{"$f":"IF(A304<>\"\",RANK(A304,A$4:A$1003,1)+SUM(IF(A$4:A304=A304,1,0))-1.5,\"\")","v":300.5},9.4306317250492239E-2,0.53325318900245278,771.82174980417403]
[0.99185941818541323,8.4888122991270853E-2,{"$f":"IF(A305<>\"\",RANK(A305,A$4:A$1003,1)+SUM(IF(A$4:A305=A305,1,0))-1.5,\"\")","v":301.5},9.8811403262989386E-2,0.53382483290819671,771.54039335124287]
[0.99316571992858371,8.4999922608237258E-2,{"$f":"IF(A306<>\"\",RANK(A306,A$4:A$1003,1)+SUM(IF(A$4:A306=A306,1,0))-1.5,\"\")","v":302.5},0.10331849563531963,0.53386927388111693,771.26792370305657]
[1.1226024654133653,9.6077744897178366E-2,{"$f":"IF(A307<>\"\",RANK(A307,A$4:A$1003,1)+SUM(IF(A$4:A307=A307,1,0))-1.5,\"\")","v":303.5},0.10782768779584904,0.53827058673780148,770.86075605572955]
[1.1675144939927122,9.9921533377601374E-2,{"$f":"IF(A308<>\"\",RANK(A308,A$4:A$1003,1)+SUM(IF(A$4:A308=A308,1,0))-1.5,\"\")","v":304.5},0.11233907347441414,0.53979668962920546,770.51492721253226]
[1.1953634120718561,0.10230497838979313,{"$f":"IF(A309<>\"\",RANK(A309,A$4:A$1003,1)+SUM(IF(A$4:A309=A309,1,0))-1.5,\"\")","v":305.5},0.11685274671633186,0.54074269806982389,770.16929969204102]
[1.1956246724193988,0.102327338313093,{"$f":"IF(A310<>\"\",RANK(A310,A$4:A$1003,1)+SUM(IF(A$4:A310=A310,1,0))-1.5,\"\")","v":306.5},0.12136880189653143,0.54075157181899258,769.84233206782255]
[1.4042938491083987,0.12018625502088505,{"$f":"IF(A311<>\"\",RANK(A311,A$4:A$1003,1)+SUM(IF(A$4:A311=A311,1,0))-1.5,\"\")","v":307.5},0.12588733373380909,0.54783219712385978,769.33061000044904]
[1.435281418649538,0.12283832099532895,{"$f":"IF(A312<>\"\",RANK(A312,A$4:A$1003,1)+SUM(IF(A$4:A312=A312,1,0))-1.5,\"\")","v":308.5},0.1304084373052132,0.54888243586333019,768.93008552758624]
[1.5490955128270798,0.13257908127598553,{"$f":"IF(A313<>\"\",RANK(A313,A$4:A$1003,1)+SUM(IF(A$4:A313=A313,1,0))-1.5,\"\")","v":309.5},0.13493220806056549,0.5527368614603515,768.4880109035264]
[1.6421853243455189,0.14054615727940326,{"$f":"IF(A314<>\"\",RANK(A314,A$4:A$1003,1)+SUM(IF(A$4:A314=A314,1,0))-1.5,\"\")","v":310.5},0.13945874183712395,0.55588575693065123,768.04823183506528]
[1.6921954570016169,0.14482626614752803,{"$f":"IF(A315<>\"\",RANK(A315,A$4:A$1003,1)+SUM(IF(A$4:A315=A315,1,0))-1.5,\"\")","v":311.5},0.14398813487439399,0.55757597826473304,767.59533328169141]
[1.7187380733375903,0.14709791154275337,{"$f":"IF(A316<>\"\",RANK(A316,A$4:A$1003,1)+SUM(IF(A$4:A316=A316,1,0))-1.5,\"\")","v":312.5},0.14852048382909341,0.55847263085237087,767.12856941438872]
[1.8194114895213715,0.15571402908748613,{"$f":"IF(A317<>\"\",RANK(A317,A$4:A$1003,1)+SUM(IF(A$4:A317=A317,1,0))-1.5,\"\")","v":313.5},0.15305588579027762,0.56187078077434183,766.64860413132612]
[1.8252298231973327,0.15621199020539478,{"$f":"IF(A318<>\"\",RANK(A318,A$4:A$1003,1)+SUM(IF(A$4:A318=A318,1,0))-1.5,\"\")","v":314.5},0.15759443829463271,0.5620670370284091,766.15051506980626]
[1.8545156731934185,0.15871841479620288,{"$f":"IF(A319<>\"\",RANK(A319,A$4:A$1003,1)+SUM(IF(A$4:A319=A319,1,0))-1.5,\"\")","v":315.5},0.16213623934193927,0.56305463540860323,765.64314955459588]
[1.8773971173686732,0.16067671938226497,{"$f":"IF(A320<>\"\",RANK(A320,A$4:A$1003,1)+SUM(IF(A$4:A320=A320,1,0))-1.5,\"\")","v":316.5},0.1666813874107187,0.56382598679621254,765.12637375176701]
[1.9768948619857838,0.16919221727191477,{"$f":"IF(A321<>\"\",RANK(A321,A$4:A$1003,1)+SUM(IF(A$4:A321=A321,1,0))-1.5,\"\")","v":317.5},0.1712299814740646,0.56717727437087206,764.57520299313046]
[2.0072928321023937,0.17179382247787955,{"$f":"IF(A322<>\"\",RANK(A322,A$4:A$1003,1)+SUM(IF(A$4:A322=A322,1,0))-1.5,\"\")","v":318.5},0.17578212101566829,0.56820018886446177,764.02482933573287]
[2.0085991338455642,0.17190562209484594,{"$f":"IF(A323<>\"\",RANK(A323,A$4:A$1003,1)+SUM(IF(A$4:A323=A323,1,0))-1.5,\"\")","v":319.5},0.18033790604604438,0.56824413670275886,763.47513817891672]
[2.0983561122784522,0.179587458134124,{"$f":"IF(A324<>\"\",RANK(A324,A$4:A$1003,1)+SUM(IF(A$4:A324=A324,1,0))-1.5,\"\")","v":320.5},0.18489743711896478,0.57126177422241198,762.87632237625212]
[2.2334170098147297,{"$f":"+IF(A325<>\"\",(A325-K$2)/K$3,\"\")","v":0.19114662253900835},{"$f":"IF(A325<>\"\",RANK(A325,A$4:A$1003,1)+SUM(IF(A$4:A325=A325,1,0))-1.5,\"\")","v":321.5},{"$f":"IF(A325<>\"\",NORMSINV(C325/($K$1)),\"\")","v":0.1894608153481071},{"$f":"IF(A325<>\"\",NORMDIST(A325,$K$2,$K$3,1),\"\")","v":0.57579463926059415},{"$f":"IF(A325<>\"\",-2*C325*LN(E325)-(2*$K$1-2*C325)*LN(1-E325),\"\")","v":762.269067449678}]
[2.2427658854749097,0.19194674450419683,{"$f":"IF(A326<>\"\",RANK(A326,A$4:A$1003,1)+SUM(IF(A$4:A326=A326,1,0))-1.5,\"\")","v":322.5},0.19402814242392619,0.5761080393288297,761.65660659716241]
[2.2573434953856122,0.19319436681873697,{"$f":"IF(A327<>\"\",RANK(A327,A$4:A$1003,1)+SUM(IF(A$4:A327=A327,1,0))-1.5,\"\")","v":323.5},0.19859952063075664,0.57659662486971475,761.03769459641796]
[2.289114845972108,0.19591351256331402,{"$f":"IF(A328<>\"\",RANK(A328,A$4:A$1003,1)+SUM(IF(A$4:A328=A328,1,0))-1.5,\"\")","v":324.5},0.2031750528641515,0.57766106963828012,760.40361680305568]
[2.3007515133213019,0.1969094347988978,{"$f":"IF(A329<>\"\",RANK(A329,A$4:A$1003,1)+SUM(IF(A$4:A329=A329,1,0))-1.5,\"\")","v":325.5},0.20775484264846933,0.57805079483672028,759.76933888461235]
[2.3574943908733985,0.20176576451679215,{"$f":"IF(A330<>\"\",RANK(A330,A$4:A$1003,1)+SUM(IF(A$4:A330=A330,1,0))-1.5,\"\")","v":326.5},0.21233899415471519,0.57995007648415375,759.09554977885887]
[2.3631820943737694,0.20225254567289519,{"$f":"IF(A331<>\"\",RANK(A331,A$4:A$1003,1)+SUM(IF(A$4:A331=A331,1,0))-1.5,\"\")","v":327.5},0.21692761221864429,0.58014035183890922,758.44532820364998]
[2.4545066348991895,0.21006854125259516,{"$f":"IF(A332<>\"\",RANK(A332,A$4:A$1003,1)+SUM(IF(A$4:A332=A332,1,0))-1.5,\"\")","v":328.5},0.22152080235913765,0.58319291095702752,757.71462651368029]
[2.5486450150892779,0.21812535883100984,{"$f":"IF(A333<>\"\",RANK(A333,A$4:A$1003,1)+SUM(IF(A$4:A333=A333,1,0))-1.5,\"\")","v":329.5},0.2261186707968583,0.58633428020544542,756.97512786118]
[2.5755124432216689,0.22042480318969482,{"$f":"IF(A334<>\"\",RANK(A334,A$4:A$1003,1)+SUM(IF(A$4:A334=A334,1,0))-1.5,\"\")","v":330.5},0.23072132447319693,0.58722983487251046,756.25907942481331]
[2.6535021241315917,0.2270995370317391,{"$f":"IF(A335<>\"\",RANK(A335,A$4:A$1003,1)+SUM(IF(A$4:A335=A335,1,0))-1.5,\"\")","v":331.5},0.23532887106951708,0.58982682798002817,755.50014109615904]
[3.0030505320310112,0.2570155792621685,{"$f":"IF(A336<>\"\",RANK(A336,A$4:A$1003,1)+SUM(IF(A$4:A336=A336,1,0))-1.5,\"\")","v":332.5},0.23994141902670796,0.60141662677569285,754.81767475603567]
[3.0449545393230437,0.26060192674206717,{"$f":"IF(A337<>\"\",RANK(A337,A$4:A$1003,1)+SUM(IF(A$4:A337=A337,1,0))-1.5,\"\")","v":333.5},0.24455907756505785,0.60280024815648481,754.03049335216065]
[3.046850440489834,0.26076418712743482,{"$f":"IF(A338<>\"\",RANK(A338,A$4:A$1003,1)+SUM(IF(A$4:A338=A338,1,0))-1.5,\"\")","v":334.5},0.2491819567044527,0.6028628181608422,753.19749790309561]
[3.0929381406394896,0.26470859526325213,{"$f":"IF(A339<>\"\",RANK(A339,A$4:A$1003,1)+SUM(IF(A$4:A339=A339,1,0))-1.5,\"\")","v":335.5},0.25381016728491673,0.6043830222146136,752.38714779777956]
[3.1652401180472225,0.27089654794903772,{"$f":"IF(A340<>\"\",RANK(A340,A$4:A$1003,1)+SUM(IF(A$4:A340=A340,1,0))-1.5,\"\")","v":336.5},0.25844382098750129,0.60676469993446658,751.57982921454936]
[3.1915850254827092,0.27315127246096732,{"$f":"IF(A341<>\"\",RANK(A341,A$4:A$1003,1)+SUM(IF(A$4:A341=A341,1,0))-1.5,\"\")","v":337.5},0.26308303035553421,0.60763153250416668,750.72634690983523]
[3.19171565565739,0.2731624524226951,{"$f":"IF(A342<>\"\",RANK(A342,A$4:A$1003,1)+SUM(IF(A$4:A342=A342,1,0))-1.5,\"\")","v":338.5},0.26772790881624153,0.60763582933259386,749.85165438291847]
[3.19727272898308,0.27363805361707033,{"$f":"IF(A343<>\"\",RANK(A343,A$4:A$1003,1)+SUM(IF(A$4:A343=A343,1,0))-1.5,\"\")","v":339.5},0.27237857070275212,0.60781860641566232,748.97722034407639]
[3.2003443017192694,0.27390093365775448,{"$f":"IF(A344<>\"\",RANK(A344,A$4:A$1003,1)+SUM(IF(A$4:A344=A344,1,0))-1.5,\"\")","v":340.5},0.27703513127649759,0.60791962296975932,748.10032200763021]
[3.2789235820519025,0.28062612826812222,{"$f":"IF(A345<>\"\",RANK(A345,A$4:A$1003,1)+SUM(IF(A$4:A345=A345,1,0))-1.5,\"\")","v":341.5},0.28169770675002004,0.61050141323040341,747.20254326154259]
[3.3056603800096127,0.28291439266507945,{"$f":"IF(A346<>\"\",RANK(A346,A$4:A$1003,1)+SUM(IF(A$4:A346=A346,1,0))-1.5,\"\")","v":342.5},0.28636641431020055,0.61137876931000301,746.29643498564326]
[3.3667846593189097,0.28814570392211042,{"$f":"IF(A347<>\"\",RANK(A347,A$4:A$1003,1)+SUM(IF(A$4:A347=A347,1,0))-1.5,\"\")","v":343.5},0.29104137214191883,0.6133823955929133,745.37030692694111]
[3.4674580755036004,0.29676182146692104,{"$f":"IF(A348<>\"\",RANK(A348,A$4:A$1003,1)+SUM(IF(A$4:A348=A348,1,0))-1.5,\"\")","v":344.5},0.29572269945216134,0.61667582244428831,744.42777710094151]
[3.4705967269655957,0.29703044242917315,{"$f":"IF(A349<>\"\",RANK(A349,A$4:A$1003,1)+SUM(IF(A$4:A349=A349,1,0))-1.5,\"\")","v":345.5},0.30041051649458861,0.61677836615269355,743.47620190315126]
[3.5085112230235609,0.30027534825504065,{"$f":"IF(A350<>\"\",RANK(A350,A$4:A$1003,1)+SUM(IF(A$4:A350=A350,1,0))-1.5,\"\")","v":346.5},0.30510494459457788,0.61801643231989334,742.50999836207552]
[3.5292355056835731,0.30204903253235738,{"$f":"IF(A351<>\"\",RANK(A351,A$4:A$1003,1)+SUM(IF(A$4:A351=A351,1,0))-1.5,\"\")","v":347.5},0.30980610617475302,0.61869265754241942,741.53717978652594]
[3.6069639262450437,0.30870140645102395,{"$f":"IF(A352<>\"\",RANK(A352,A$4:A$1003,1)+SUM(IF(A$4:A352=A352,1,0))-1.5,\"\")","v":348.5},0.31451412478102064,0.62122566307116966,740.52740625574825]
[3.7089436441738144,0.31742932361287879,{"$f":"IF(A353<>\"\",RANK(A353,A$4:A$1003,1)+SUM(IF(A$4:A353=A353,1,0))-1.5,\"\")","v":349.5},0.31922912510912416,0.62454107009938664,739.50098543138665]
[3.7707210743537871,0.32271653467831513,{"$f":"IF(A354<>\"\",RANK(A354,A$4:A$1003,1)+SUM(IF(A$4:A354=A354,1,0))-1.5,\"\")","v":350.5},0.32395123303173373,0.62654503562323616,738.46919774760067]
[3.7709187832542739,0.32273345556161093,{"$f":"IF(A355<>\"\",RANK(A355,A$4:A$1003,1)+SUM(IF(A$4:A355=A355,1,0))-1.5,\"\")","v":351.5},0.32868057562608849,0.62655144354059167,737.43428228805863]
[3.8232167076002952,0.32720936470020889,{"$f":"IF(A356<>\"\",RANK(A356,A$4:A$1003,1)+SUM(IF(A$4:A356=A356,1,0))-1.5,\"\")","v":352.5},0.33341728120220876,0.62824523079743477,736.37352626182712]
[3.9988717834085037,0.34224277508661721,{"$f":"IF(A357<>\"\",RANK(A357,A$4:A$1003,1)+SUM(IF(A$4:A357=A357,1,0))-1.5,\"\")","v":353.5},0.33816147933169205,0.63391590159654254,735.2888514426844]
[4.0056716070293987,0.34282473685787701,{"$f":"IF(A358<>\"\",RANK(A358,A$4:A$1003,1)+SUM(IF(A$4:A358=A358,1,0))-1.5,\"\")","v":354.5},0.3429133008771163,0.63413484243029539,734.19059439483726]
[4.0636572348757909,0.34778742715257799,{"$f":"IF(A359<>\"\",RANK(A359,A$4:A$1003,1)+SUM(IF(A$4:A359=A359,1,0))-1.5,\"\")","v":355.5},0.34767287802206598,0.63600008369588612,733.08259925641937]
[4.1870814650628745,0.35835066932187859,{"$f":"IF(A360<>\"\",RANK(A360,A$4:A$1003,1)+SUM(IF(A$4:A360=A360,1,0))-1.5,\"\")","v":356.5},0.35244034430180049,0.6399595481428948,731.97102096321623]
[4.217871325703527,0.36098581441302668,{"$f":"IF(A361<>\"\",RANK(A361,A$4:A$1003,1)+SUM(IF(A$4:A361=A361,1,0))-1.5,\"\")","v":357.5},0.35721583463458467,0.640944974222039,730.82503333441355]
[4.2495120461144325,0.36369378019579812,{"$f":"IF(A362<>\"\",RANK(A362,A$4:A$1003,1)+SUM(IF(A$4:A362=A362,1,0))-1.5,\"\")","v":358.5},0.36199948535370396,0.64195665578108296,729.66672261044505]
[4.3110917673957374,0.36896407037809437,{"$f":"IF(A363<>\"\",RANK(A363,A$4:A$1003,1)+SUM(IF(A$4:A363=A363,1,0))-1.5,\"\")","v":359.5},0.36679143424018246,0.64392274705748476,728.49733652480631]
[4.3594037077855319,0.37309883974414726,{"$f":"IF(A364<>\"\",RANK(A364,A$4:A$1003,1)+SUM(IF(A$4:A364=A364,1,0))-1.5,\"\")","v":360.5},0.37159182055622902,0.64546255890660598,727.31090589966334]
[4.3643711816876021,0.37352398017012123,{"$f":"IF(A365<>\"\",RANK(A365,A$4:A$1003,1)+SUM(IF(A$4:A365=A365,1,0))-1.5,\"\")","v":361.5},0.3764007850794312,0.64562074945111381,726.11171142806063]
[4.411440371783101,0.37755238895936749,{"$f":"IF(A366<>\"\",RANK(A366,A$4:A$1003,1)+SUM(IF(A$4:A366=A366,1,0))-1.5,\"\")","v":362.5},0.3812184701377227,0.64711843040130856,724.89656861201411]
[4.4989731099749406,0.38504386376833211,{"$f":"IF(A367<>\"\",RANK(A367,A$4:A$1003,1)+SUM(IF(A$4:A367=A367,1,0))-1.5,\"\")","v":363.5},0.38604501964514715,0.64989754119915322,723.65979157186553]
[4.5233585647947621,0.38713088885473423,{"$f":"IF(A368<>\"\",RANK(A368,A$4:A$1003,1)+SUM(IF(A$4:A368=A368,1,0))-1.5,\"\")","v":364.5},0.39088057913844493,0.65067034446479055,722.41587694899977]
[4.5269526582278559,0.38743848874217379,{"$f":"IF(A369<>\"\",RANK(A369,A$4:A$1003,1)+SUM(IF(A$4:A369=A369,1,0))-1.5,\"\")","v":365.5},0.39572529581448734,0.65078419273741983,721.17015614248555]
[4.5508791437996479,0.38948623302198027,{"$f":"IF(A370<>\"\",RANK(A370,A$4:A$1003,1)+SUM(IF(A$4:A370=A370,1,0))-1.5,\"\")","v":366.5},0.40057931856858597,0.65154175363766742,719.90850570076941]
[4.7738011186011136,0.40856497308069711,{"$f":"IF(A371<>\"\",RANK(A371,A$4:A$1003,1)+SUM(IF(A$4:A371=A371,1,0))-1.5,\"\")","v":367.5},0.40544279803370559,0.65857052997949783,718.5747074615299]
[4.8017806668540288,0.4109595980545388,{"$f":"IF(A372<>\"\",RANK(A372,A$4:A$1003,1)+SUM(IF(A$4:A372=A372,1,0))-1.5,\"\")","v":368.5},0.41031588662060714,0.65944891991516064,717.25995905269224]
[4.8039378283701808,0.41114421836336207,{"$f":"IF(A373<>\"\",RANK(A373,A$4:A$1003,1)+SUM(IF(A$4:A373=A373,1,0))-1.5,\"\")","v":369.5},0.41519873855895434,0.6595166060232861,715.93776840351006]
[4.9114110681757666,0.42034229767943238,{"$f":"IF(A374<>\"\",RANK(A374,A$4:A$1003,1)+SUM(IF(A$4:A374=A374,1,0))-1.5,\"\")","v":370.5},0.42009150993941113,0.66288229272759436,714.58878082658146]
[4.9350092146714815,0.42236194111413744,{"$f":"IF(A375<>\"\",RANK(A375,A$4:A$1003,1)+SUM(IF(A$4:A375=A375,1,0))-1.5,\"\")","v":371.5},0.42499435875676483,0.66361957349544709,713.2315469656412]
[4.9688741753261638,0.42526026812745576,{"$f":"IF(A376<>\"\",RANK(A376,A$4:A$1003,1)+SUM(IF(A$4:A376=A376,1,0))-1.5,\"\")","v":372.5},0.42990744495410521,0.66467652299861535,711.86085180221016]
[5.0173802973376951,0.42941165649524055,{"$f":"IF(A377<>\"\",RANK(A377,A$4:A$1003,1)+SUM(IF(A$4:A377=A377,1,0))-1.5,\"\")","v":373.5},0.43483093046809762,0.6661881638120003,710.47175802425409]
[5.0470580378578234,0.43195162097123196,{"$f":"IF(A378<>\"\",RANK(A378,A$4:A$1003,1)+SUM(IF(A$4:A378=A378,1,0))-1.5,\"\")","v":374.5},0.43976497927538261,0.66711171228346633,709.07445324062292]
[5.1250477187677461,0.43862635481327628,{"$f":"IF(A379<>\"\",RANK(A379,A$4:A$1003,1)+SUM(IF(A$4:A379=A379,1,0))-1.5,\"\")","v":375.5},0.44470975744014091,0.66953385129865728,707.64247350011738]
[5.14224145944263,0.44009787824323532,{"$f":"IF(A380<>\"\",RANK(A380,A$4:A$1003,1)+SUM(IF(A$4:A380=A380,1,0))-1.5,\"\")","v":376.5},0.44966543316286056,0.67006689070221803,706.2202848581685]
[5.1861719980761336,0.44385766607022942,{"$f":"IF(A381<>\"\",RANK(A381,A$4:A$1003,1)+SUM(IF(A$4:A381=A381,1,0))-1.5,\"\")","v":377.5},0.45463217683034762,0.67142725338693143,704.77186688846064]
[5.2449414069697013,0.4488874361352192,{"$f":"IF(A382<>\"\",RANK(A382,A$4:A$1003,1)+SUM(IF(A$4:A382=A382,1,0))-1.5,\"\")","v":378.5},0.4596101610670198,0.67324357009895897,703.29863973597924]
[5.287106674610186,0.45249614353849554,{"$f":"IF(A383<>\"\",RANK(A383,A$4:A$1003,1)+SUM(IF(A$4:A383=A383,1,0))-1.5,\"\")","v":379.5},0.46459956078752873,0.67454420058723152,701.81979299485431]
[5.3981104564018096,0.46199638370200136,{"$f":"IF(A384<>\"\",RANK(A384,A$4:A$1003,1)+SUM(IF(A$4:A384=A384,1,0))-1.5,\"\")","v":380.5},0.46960055325075217,0.67795804311643904,700.28499429143517]
[5.398241086575581,0.46200756366365131,{"$f":"IF(A385<>\"\",RANK(A385,A$4:A$1003,1)+SUM(IF(A$4:A385=A385,1,0))-1.5,\"\")","v":381.5},0.47461331811520274,0.67796205179476488,698.79609461210293]
[5.5428450413937753,0.47438346903545603,{"$f":"IF(A386<>\"\",RANK(A386,A$4:A$1003,1)+SUM(IF(A$4:A386=A386,1,0))-1.5,\"\")","v":382.5},0.47963803749590433,0.68238676042632407,697.21445867543298]
[5.5544817087429692,0.47537939127103979,{"$f":"IF(A387<>\"\",RANK(A387,A$4:A$1003,1)+SUM(IF(A$4:A387=A387,1,0))-1.5,\"\")","v":383.5},0.48467489602278113,0.68274170953602653,695.67855653498646]
[5.7494876867422136,0.49206894539623042,{"$f":"IF(A388<>\"\",RANK(A388,A$4:A$1003,1)+SUM(IF(A$4:A388=A388,1,0))-1.5,\"\")","v":384.5},0.48972408090061603,0.68866469760716453,694.08039456278766]
[5.7556343594906139,{"$f":"+IF(A389<>\"\",(A389-K$2)/K$3,\"\")","v":0.49259500735892914},{"$f":"IF(A389<>\"\",RANK(A389,A$4:A$1003,1)+SUM(IF(A$4:A389=A389,1,0))-1.5,\"\")","v":385.5},{"$f":"IF(A389<>\"\",NORMSINV(C389/($K$1)),\"\")","v":0.49478578197062606},{"$f":"IF(A389<>\"\",NORMDIST(A389,$K$2,$K$3,1),\"\")","v":0.68885061176983697},{"$f":"IF(A389<>\"\",-2*C389*LN(E389)-(2*$K$1-2*C389)*LN(1-E389),\"\")","v":692.49178619152826}]
[5.76576701619706,0.49346220909432859,{"$f":"IF(A390<>\"\",RANK(A390,A$4:A$1003,1)+SUM(IF(A$4:A390=A390,1,0))-1.5,\"\")","v":386.5},0.49986019177371788,0.68915698206052167,690.89843216231907]
[5.8792527713003437,0.50317486853003945,{"$f":"IF(A391<>\"\",RANK(A391,A$4:A$1003,1)+SUM(IF(A$4:A391=A391,1,0))-1.5,\"\")","v":387.5},0.50494750561547508,0.69257933380802017,689.26428652373284]
[5.9329240761162509,0.50776831820724966,{"$f":"IF(A392<>\"\",RANK(A392,A$4:A$1003,1)+SUM(IF(A$4:A392=A392,1,0))-1.5,\"\")","v":388.5},0.51004792163294066,0.6941920847037979,687.62626359735646]
[5.9539096191256249,0.50956436240802183,{"$f":"IF(A393<>\"\",RANK(A393,A$4:A$1003,1)+SUM(IF(A$4:A393=A393,1,0))-1.5,\"\")","v":389.5},0.51516164086325944,0.69482165184357414,685.97913983997933]
[6.1168829861881022,0.52351241086510214,{"$f":"IF(A394<>\"\",RANK(A394,A$4:A$1003,1)+SUM(IF(A$4:A394=A394,1,0))-1.5,\"\")","v":390.5},0.52028886731423885,0.69969114167381752,684.29986758809696]
[6.1900358233697261,0.52977318424282238,{"$f":"IF(A395<>\"\",RANK(A395,A$4:A$1003,1)+SUM(IF(A$4:A395=A395,1,0))-1.5,\"\")","v":391.5},0.52542980803690487,0.70186540017777399,682.61309581722458]
[6.3580437430609891,0.54415211404752239,{"$f":"IF(A396<>\"\",RANK(A396,A$4:A$1003,1)+SUM(IF(A$4:A396=A396,1,0))-1.5,\"\")","v":392.5},0.5305846732001186,0.70683159948034158,680.9595166306292]
[6.3596783838793272,0.54429201450951237,{"$f":"IF(A397<>\"\",RANK(A397,A$4:A$1003,1)+SUM(IF(A$4:A397=A397,1,0))-1.5,\"\")","v":393.5},0.53575367616732628,0.70687972939078314,679.20018440882563]
[6.5127803545856295,0.55739522115472651,{"$f":"IF(A398<>\"\",RANK(A398,A$4:A$1003,1)+SUM(IF(A$4:A398=A398,1,0))-1.5,\"\")","v":394.5},0.54093703357552436,0.71137128507934411,677.52251092290976]
[6.5887435041540812,0.56389651464967538,{"$f":"IF(A399<>\"\",RANK(A399,A$4:A$1003,1)+SUM(IF(A$4:A399=A399,1,0))-1.5,\"\")","v":395.5},0.54613496541651507,0.71358771890842065,675.77848635833391]
[6.6154803021117914,0.56618477904663256,{"$f":"IF(A400<>\"\",RANK(A400,A$4:A$1003,1)+SUM(IF(A$4:A400=A400,1,0))-1.5,\"\")","v":396.5},0.55134769512053794,0.71436591205668531,673.9726556041719]
[6.73635548025959,0.57652986102200443,{"$f":"IF(A401<>\"\",RANK(A401,A$4:A$1003,1)+SUM(IF(A$4:A401=A401,1,0))-1.5,\"\")","v":397.5},0.55657544964236316,0.71787145391743867,672.23625314437345]
[6.7451147564961502,0.57727952221879164,{"$f":"IF(A402<>\"\",RANK(A402,A$4:A$1003,1)+SUM(IF(A$4:A402=A402,1,0))-1.5,\"\")","v":398.5},0.56181845954993914,0.71812467762215604,670.37555363458534]
[6.7991779518351905,0.58190651178110731,{"$f":"IF(A403<>\"\",RANK(A403,A$4:A$1003,1)+SUM(IF(A$4:A403=A403,1,0))-1.5,\"\")","v":399.5},0.56707695911568645,0.71968517296112056,668.5417706079636]
[6.8097695777896661,0.58281299432310241,{"$f":"IF(A404<>\"\",RANK(A404,A$4:A$1003,1)+SUM(IF(A$4:A404=A404,1,0))-1.5,\"\")","v":400.5},0.5723511864105375,0.71999040179627949,666.66168859856009]
[6.8480124129227988,0.58608600099399344,{"$f":"IF(A405<>\"\",RANK(A405,A$4:A$1003,1)+SUM(IF(A$4:A405=A405,1,0))-1.5,\"\")","v":401.5},0.57764138340082438,0.72109113840383288,664.78688115201294]
[6.856838767885165,0.58684140311234867,{"$f":"IF(A406<>\"\",RANK(A406,A$4:A$1003,1)+SUM(IF(A$4:A406=A406,1,0))-1.5,\"\")","v":402.5},0.58294779604812486,0.72134488644958084,662.88878831368675]
[6.8896551598654696,0.5896499885504366,{"$f":"IF(A407<>\"\",RANK(A407,A$4:A$1003,1)+SUM(IF(A$4:A407=A407,1,0))-1.5,\"\")","v":403.5},0.58827067441217329,0.7222873346756723,660.98645916342605]
[6.9705857833369009,0.59657642247143727,{"$f":"IF(A408<>\"\",RANK(A408,A$4:A$1003,1)+SUM(IF(A$4:A408=A408,1,0))-1.5,\"\")","v":404.5},0.59361027275695866,0.72460489171082243,659.07263106232494]
[7.09655906556236,0.60735782483458867,{"$f":"IF(A409<>\"\",RANK(A409,A$4:A$1003,1)+SUM(IF(A$4:A409=A409,1,0))-1.5,\"\")","v":405.5},0.59896684966012625,0.72819326442198895,657.15795788227058]
[7.2656120266492508,0.62182619433295527,{"$f":"IF(A410<>\"\",RANK(A410,A$4:A$1003,1)+SUM(IF(A$4:A410=A410,1,0))-1.5,\"\")","v":406.5},0.6043406681258191,0.73297191988384447,655.27917599669411]
[7.2711690999749408,0.62230179552733056,{"$f":"IF(A411<>\"\",RANK(A411,A$4:A$1003,1)+SUM(IF(A$4:A411=A411,1,0))-1.5,\"\")","v":407.5},0.60973199570108094,0.73312827961636184,653.26330444187613]
[7.2876426110524335,0.62371167822723839,{"$f":"IF(A412<>\"\",RANK(A412,A$4:A$1003,1)+SUM(IF(A$4:A412=A412,1,0))-1.5,\"\")","v":408.5},0.61514110459597326,0.73359152389165228,651.24906089890442]
[7.2989544666052097,0.62467980149936253,{"$f":"IF(A413<>\"\",RANK(A413,A$4:A$1003,1)+SUM(IF(A$4:A413=A413,1,0))-1.5,\"\")","v":409.5},0.62056827180753793,0.73390938378811321,649.225386570615]
[7.3022872996889419,0.62496504146334653,{"$f":"IF(A414<>\"\",RANK(A414,A$4:A$1003,1)+SUM(IF(A$4:A414=A414,1,0))-1.5,\"\")","v":410.5},0.62601377924777157,0.73400299879872699,647.19607976768953]
[7.3240566237445819,0.62682816543432973,{"$f":"IF(A415<>\"\",RANK(A415,A$4:A$1003,1)+SUM(IF(A$4:A415=A415,1,0))-1.5,\"\")","v":411.5},0.63147791387576269,0.7346140605450282,645.15962488760567]
[7.4381319782714854,0.63659128563844192,{"$f":"IF(A416<>\"\",RANK(A416,A$4:A$1003,1)+SUM(IF(A$4:A416=A416,1,0))-1.5,\"\")","v":412.5},0.63696096783416034,0.73780444852685556,643.09183259031192]
[7.5507033221547317,0.64622568534229186,{"$f":"IF(A417<>\"\",RANK(A417,A$4:A$1003,1)+SUM(IF(A$4:A417=A417,1,0))-1.5,\"\")","v":413.5},0.64246323859015286,0.74093339627071564,641.01643274401943]
[7.7068133141492581,0.6595863329881082,{"$f":"IF(A418<>\"\",RANK(A418,A$4:A$1003,1)+SUM(IF(A$4:A418=A418,1,0))-1.5,\"\")","v":414.5},0.6479850290811312,0.74524033644077814,638.9548384040977]
[7.7625111503057269,0.66435322301233601,{"$f":"IF(A419<>\"\",RANK(A419,A$4:A$1003,1)+SUM(IF(A$4:A419=A419,1,0))-1.5,\"\")","v":415.5},0.65352664786524284,0.74676786796115602,636.83251824505419]
[7.7803580418531055,0.66588064625085608,{"$f":"IF(A420<>\"\",RANK(A420,A$4:A$1003,1)+SUM(IF(A$4:A420=A420,1,0))-1.5,\"\")","v":416.5},0.65908840927702117,0.74725630402533516,634.67520410744623]
[7.8207580385014808,0.66933827323049255,{"$f":"IF(A421<>\"\",RANK(A421,A$4:A$1003,1)+SUM(IF(A$4:A421=A421,1,0))-1.5,\"\")","v":417.5},0.66467063358831358,0.74836014126047723,632.51328456115334]
[7.8858683017660951,0.67491072425999077,{"$f":"IF(A422<>\"\",RANK(A422,A$4:A$1003,1)+SUM(IF(A$4:A422=A422,1,0))-1.5,\"\")","v":418.5},0.67027364717472604,0.75013375670074955,630.33973371264278]
[7.9398679456571699,0.67953227478222455,{"$f":"IF(A423<>\"\",RANK(A423,A$4:A$1003,1)+SUM(IF(A$4:A423=A423,1,0))-1.5,\"\")","v":419.5},0.67589778268780809,0.75159966751421359,628.14476147513005]
[8.0379923098034851,0.68793023213318416,{"$f":"IF(A424<>\"\",RANK(A424,A$4:A$1003,1)+SUM(IF(A$4:A424=A424,1,0))-1.5,\"\")","v":420.5},0.68154337923324115,0.75425164131243616,625.94145216545076]
[8.1437638300658364,0.69698267006577441,{"$f":"IF(A425<>\"\",RANK(A425,A$4:A$1003,1)+SUM(IF(A$4:A425=A425,1,0))-1.5,\"\")","v":421.5},0.68721078255525714,0.75709318037118134,623.72699372983061]
[8.1791963528112319,0.70001515661935898,{"$f":"IF(A426<>\"\",RANK(A426,A$4:A$1003,1)+SUM(IF(A$4:A426=A426,1,0))-1.5,\"\")","v":422.5},0.69290034522758903,0.75804108046583218,621.46349430170335]
[8.2115573028213475,0.70278476313233729,{"$f":"IF(A427<>\"\",RANK(A427,A$4:A$1003,1)+SUM(IF(A$4:A427=A427,1,0))-1.5,\"\")","v":423.5},0.69861242685120395,0.75890505292175514,619.18414434417809]
[8.2630043673952969,0.70718785157915631,{"$f":"IF(A428<>\"\",RANK(A428,A$4:A$1003,1)+SUM(IF(A$4:A428=A428,1,0))-1.5,\"\")","v":424.5},0.70434739425914106,0.76027512647667672,616.89243986347469]
[8.2754248157916663,0.70825085358502893,{"$f":"IF(A429<>\"\",RANK(A429,A$4:A$1003,1)+SUM(IF(A$4:A429=A429,1,0))-1.5,\"\")","v":425.5},0.7101056217287437,0.76060525444682481,614.58256272328049]
[8.2985675203162828,0.71023151809454654,{"$f":"IF(A430<>\"\",RANK(A430,A$4:A$1003,1)+SUM(IF(A$4:A430=A430,1,0))-1.5,\"\")","v":426.5},0.71588749120163286,0.76121971057613835,612.26279394720882]
[8.5161266034147047,0.72885127596069788,{"$f":"IF(A431<>\"\",RANK(A431,A$4:A$1003,1)+SUM(IF(A$4:A431=A431,1,0))-1.5,\"\")","v":427.5},0.7216933925117528,0.76695367897926303,609.92043065803421]
[8.5806507945344492,0.73437356810335874,{"$f":"IF(A432<>\"\",RANK(A432,A$4:A$1003,1)+SUM(IF(A$4:A432=A432,1,0))-1.5,\"\")","v":428.5},0.72752372362185691,0.76863945419310264,607.55126508120952]
[8.6213120515312767,0.73785355500637284,{"$f":"IF(A433<>\"\",RANK(A433,A$4:A$1003,1)+SUM(IF(A$4:A433=A433,1,0))-1.5,\"\")","v":429.5},0.73337889086881569,0.76969827747295649,605.15552841206522]
[8.6500118293815831,0.74030982071026574,{"$f":"IF(A434<>\"\",RANK(A434,A$4:A$1003,1)+SUM(IF(A$4:A434=A434,1,0))-1.5,\"\")","v":430.5},0.73925930921815275,0.7704439883427715,602.742057779633]
[8.8320748382875536,0.75589165298282834,{"$f":"IF(A435<>\"\",RANK(A435,A$4:A$1003,1)+SUM(IF(A$4:A435=A435,1,0))-1.5,\"\")","v":431.5},0.74516540252822272,0.77514292055263279,600.34689882199712]
[8.8384156926595097,0.75643433394741466,{"$f":"IF(A436<>\"\",RANK(A436,A$4:A$1003,1)+SUM(IF(A$4:A436=A436,1,0))-1.5,\"\")","v":432.5},0.75109760382448332,0.77530558538330385,597.87332159980633]
[8.9135279824558893,0.76286280675058449,{"$f":"IF(A437<>\"\",RANK(A437,A$4:A$1003,1)+SUM(IF(A$4:A437=A437,1,0))-1.5,\"\")","v":433.5},0.7570563555843467,0.77722739021729281,595.40588379832082]
[8.9437953223987279,0.76545323199489934,{"$f":"IF(A438<>\"\",RANK(A438,A$4:A$1003,1)+SUM(IF(A$4:A438=A438,1,0))-1.5,\"\")","v":434.5},0.7630421100330762,0.77799914737608544,592.90838033816863]
[8.9819746060829857,0.76872079962563067,{"$f":"IF(A439<>\"\",RANK(A439,A$4:A$1003,1)+SUM(IF(A$4:A439=A439,1,0))-1.5,\"\")","v":435.5},0.76905532945128019,0.77897046272436232,590.39660988818719]
[8.9950482053509404,0.76983970143998637,{"$f":"IF(A440<>\"\",RANK(A440,A$4:A$1003,1)+SUM(IF(A$4:A440=A440,1,0))-1.5,\"\")","v":436.5},0.77509648649455154,0.77930250701114256,587.87354119059273]
[9.0384562232857206,0.7735547694200694,{"$f":"IF(A441<>\"\",RANK(A441,A$4:A$1003,1)+SUM(IF(A$4:A441=A441,1,0))-1.5,\"\")","v":437.5},0.78116606452583093,0.78040293578626141,585.33030278720707]
[9.0933031996719365,0.77824883875267392,{"$f":"IF(A442<>\"\",RANK(A442,A$4:A$1003,1)+SUM(IF(A$4:A442=A442,1,0))-1.5,\"\")","v":438.5},0.78726455796110806,0.78178883497734475,582.76400344230115]
[9.1042867161495451,0.77918886117977448,{"$f":"IF(A443<>\"\",RANK(A443,A$4:A$1003,1)+SUM(IF(A$4:A443=A443,1,0))-1.5,\"\")","v":439.5},0.79339247262914137,0.78206576467149902,580.20395656025448]
[9.1211521177501709,0.78063228376478788,{"$f":"IF(A444<>\"\",RANK(A444,A$4:A$1003,1)+SUM(IF(A$4:A444=A444,1,0))-1.5,\"\")","v":440.5},0.79955032614585086,0.78249060081499566,577.63246943520562]
[9.1658028859810656,0.78445371232183314,{"$f":"IF(A445<>\"\",RANK(A445,A$4:A$1003,1)+SUM(IF(A$4:A445=A445,1,0))-1.5,\"\")","v":441.5},0.80573864830414599,0.78361303395968673,575.02212104249998]
[9.1787458550743395,0.78556143417446112,{"$f":"IF(A446<>\"\",RANK(A446,A$4:A$1003,1)+SUM(IF(A$4:A446=A446,1,0))-1.5,\"\")","v":442.5},0.81195798147995679,0.78393776712081387,572.43168164651729]
[9.2653641820461417,0.79297464925156491,{"$f":"IF(A447<>\"\",RANK(A447,A$4:A$1003,1)+SUM(IF(A$4:A447=A447,1,0))-1.5,\"\")","v":443.5},0.81820888105526512,0.78610370357725579,569.73421475585906]
[9.3863699903677116,0.80333091118858668,{"$f":"IF(A448<>\"\",RANK(A448,A$4:A$1003,1)+SUM(IF(A$4:A448=A448,1,0))-1.5,\"\")","v":444.5},0.82449191585905557,0.78910825196382461,566.97918323597287]
[9.3940842252095536,0.80399113269178513,{"$f":"IF(A449<>\"\",RANK(A449,A$4:A$1003,1)+SUM(IF(A$4:A449=A449,1,0))-1.5,\"\")","v":445.5},0.83080766862705258,0.78929895192917199,564.33012729142911]
[9.4387985448884137,0.80781800028891237,{"$f":"IF(A450<>\"\",RANK(A450,A$4:A$1003,1)+SUM(IF(A$4:A450=A450,1,0))-1.5,\"\")","v":446.5},0.83715673648127353,0.79040231932938199,561.62259919579083]
[9.5438533628303048,0.81680909937285961,{"$f":"IF(A451<>\"\",RANK(A451,A$4:A$1003,1)+SUM(IF(A$4:A451=A451,1,0))-1.5,\"\")","v":447.5},0.84353973143039174,0.79298123432652623,558.81329206434646]
[9.6094861467927331,0.82242627024919113,{"$f":"IF(A452<>\"\",RANK(A452,A$4:A$1003,1)+SUM(IF(A$4:A452=A452,1,0))-1.5,\"\")","v":448.5},0.8499572808920578,0.79458283347037406,556.03386408598385]
[9.6368125441749726,{"$f":"+IF(A453<>\"\",(A453-K$2)/K$3,\"\")","v":0.82476499541462744},{"$f":"IF(A453<>\"\",RANK(A453,A$4:A$1003,1)+SUM(IF(A$4:A453=A453,1,0))-1.5,\"\")","v":449.5},{"$f":"IF(A453<>\"\",NORMSINV(C453/($K$1)),\"\")","v":0.85641002823829959},{"$f":"IF(A453<>\"\",NORMDIST(A453,$K$2,$K$3,1),\"\")","v":0.79524748824441016},{"$f":"IF(A453<>\"\",-2*C453*LN(E453)-(2*$K$1-2*C453)*LN(1-E453),\"\")","v":553.28638448685444}]
[9.7454614555499575,0.83406369438601424,{"$f":"IF(A454<>\"\",RANK(A454,A$4:A$1003,1)+SUM(IF(A$4:A454=A454,1,0))-1.5,\"\")","v":450.5},0.8628986333653097,0.7978774538267408,550.40323320500102]
[9.7922023065702888,0.83806400233023692,{"$f":"IF(A455<>\"\",RANK(A455,A$4:A$1003,1)+SUM(IF(A$4:A455=A455,1,0))-1.5,\"\")","v":451.5},0.86942377328888587,0.79900262055890847,547.58475409297091]
[9.8145612300486391,0.83997758706954362,{"$f":"IF(A456<>\"\",RANK(A456,A$4:A$1003,1)+SUM(IF(A$4:A456=A456,1,0))-1.5,\"\")","v":452.5},0.87598614276697562,0.79953952335406664,544.78640952928322]
[9.839010236316426,0.84207005119602762,{"$f":"IF(A457<>\"\",RANK(A457,A$4:A$1003,1)+SUM(IF(A$4:A457=A457,1,0))-1.5,\"\")","v":453.5},0.88258645495081312,0.80012562811093568,541.97276017758065]
[10.081869185456526,0.86285509388059767,{"$f":"IF(A458<>\"\",RANK(A458,A$4:A$1003,1)+SUM(IF(A$4:A458=A458,1,0))-1.5,\"\")","v":454.5},0.88922544206625009,0.8058914283529518,538.78944551031691]
[10.141620084295937,0.86796886459901634,{"$f":"IF(A459<>\"\",RANK(A459,A$4:A$1003,1)+SUM(IF(A$4:A459=A459,1,0))-1.5,\"\")","v":455.5},0.89590385612698731,0.8072943111890688,535.85939291685918]
[10.223532197713212,0.87497929917344597,{"$f":"IF(A460<>\"\",RANK(A460,A$4:A$1003,1)+SUM(IF(A$4:A460=A460,1,0))-1.5,\"\")","v":456.5},0.9026224696815357,0.80920741533315022,532.87862803846235]
[10.318256650049079,0.88308627563877584,{"$f":"IF(A461<>\"\",RANK(A461,A$4:A$1003,1)+SUM(IF(A$4:A461=A461,1,0))-1.5,\"\")","v":457.5},0.9093820765958347,0.81140517060097761,529.85912449062039]
[10.340746203701201,0.88501104033973244,{"$f":"IF(A462<>\"\",RANK(A462,A$4:A$1003,1)+SUM(IF(A$4:A462=A462,1,0))-1.5,\"\")","v":458.5},0.91618349287363232,0.81192466156885734,526.90830799322305]
[10.355323813612813,0.88625866265435038,{"$f":"IF(A463<>\"\",RANK(A463,A$4:A$1003,1)+SUM(IF(A$4:A463=A463,1,0))-1.5,\"\")","v":459.5},0.92302755751680621,0.81226092059641974,523.95876219613501]
[10.456978719744257,0.89495878085266778,{"$f":"IF(A464<>\"\",RANK(A464,A$4:A$1003,1)+SUM(IF(A$4:A464=A464,1,0))-1.5,\"\")","v":460.5},0.92991513342804033,0.81459543867263751,520.85101190974808]
[10.523723623828118,0.90067113234423379,{"$f":"IF(A465<>\"\",RANK(A465,A$4:A$1003,1)+SUM(IF(A$4:A465=A465,1,0))-1.5,\"\")","v":461.5},0.93684710835836804,0.81611839913584006,517.77508247181845]
[10.621456097451301,0.90903554981008805,{"$f":"IF(A466<>\"\",RANK(A466,A$4:A$1003,1)+SUM(IF(A$4:A466=A466,1,0))-1.5,\"\")","v":462.5},0.94382439590232636,0.81833431953341296,514.62632803195504]
[10.624856009261748,0.90932653069571789,{"$f":"IF(A467<>\"\",RANK(A467,A$4:A$1003,1)+SUM(IF(A$4:A467=A467,1,0))-1.5,\"\")","v":463.5},0.95084793654360333,0.81841110489088797,511.6098925540806]
[10.745010957812156,0.91960997194103855,{"$f":"IF(A468<>\"\",RANK(A468,A$4:A$1003,1)+SUM(IF(A$4:A468=A468,1,0))-1.5,\"\")","v":464.5},0.95791869875435121,0.8211116931133281,508.37010827917902]
[10.893537345138611,0.93232157804530635,{"$f":"IF(A469<>\"\",RANK(A469,A$4:A$1003,1)+SUM(IF(A$4:A469=A469,1,0))-1.5,\"\")","v":465.5},0.9650376801514714,0.82441482026396584,505.06982968386717]
[10.904323152715733,0.93324467958911117,{"$f":"IF(A470<>\"\",RANK(A470,A$4:A$1003,1)+SUM(IF(A$4:A470=A470,1,0))-1.5,\"\")","v":466.5},0.97220590871352175,0.82465317463563981,501.95832658418919]
[10.914522888147985,0.93411762224607864,{"$f":"IF(A471<>\"\",RANK(A471,A$4:A$1003,1)+SUM(IF(A$4:A471=A471,1,0))-1.5,\"\")","v":467.5},0.97942444406208362,0.82487838864110996,498.84181224827989]
[11.01441252328641,0.94266666002067823,{"$f":"IF(A472<>\"\",RANK(A472,A$4:A$1003,1)+SUM(IF(A$4:A472=A472,1,0))-1.5,\"\")","v":468.5},0.98669437881177224,0.82707428413560913,495.5351990372202]
[11.074096343400015,0.94777468981752899,{"$f":"IF(A473<>\"\",RANK(A473,A$4:A$1003,1)+SUM(IF(A$4:A473=A473,1,0))-1.5,\"\")","v":469.5},0.99401683999338131,0.82837791593385512,492.28078672356401]
[11.19575530259408,0.95818685156311179,{"$f":"IF(A474<>\"\",RANK(A474,A$4:A$1003,1)+SUM(IF(A$4:A474=A474,1,0))-1.5,\"\")","v":470.5},1.0013929905549805,0.83101572691362791,488.88235602433053]
[11.248445117463234,0.96269630058681521,{"$f":"IF(A475<>\"\",RANK(A475,A$4:A$1003,1)+SUM(IF(A$4:A475=A475,1,0))-1.5,\"\")","v":471.5},1.0088240309461658,0.83215002311183972,485.58903481840326]
[11.278059306534487,0.96523082602264687,{"$f":"IF(A476<>\"\",RANK(A476,A$4:A$1003,1)+SUM(IF(A$4:A476=A476,1,0))-1.5,\"\")","v":472.5},1.0163112007911452,0.83278539486514225,482.32199870278816]
[11.316171511492939,0.96849265273181018,{"$f":"IF(A477<>\"\",RANK(A477,A$4:A$1003,1)+SUM(IF(A$4:A477=A477,1,0))-1.5,\"\")","v":473.5},1.0238557806566417,0.83360080668334424,479.02012367592386]
[11.329181559312019,0.96960611550600617,{"$f":"IF(A478<>\"\",RANK(A478,A$4:A$1003,1)+SUM(IF(A$4:A478=A478,1,0))-1.5,\"\")","v":474.5},1.0314590939212447,0.83387856827561824,475.76357172028247]
[11.515036370550661,0.98551246854922636,{"$f":"IF(A479<>\"\",RANK(A479,A$4:A$1003,1)+SUM(IF(A$4:A479=A479,1,0))-1.5,\"\")","v":475.5},1.0391225087532998,0.83781379503338183,472.06309578943655]
[11.528371230167068,0.98665373028695991,{"$f":"IF(A480<>\"\",RANK(A480,A$4:A$1003,1)+SUM(IF(A$4:A480=A480,1,0))-1.5,\"\")","v":476.5},1.0468474402049917,0.8380937898924844,468.74565638278796]
[11.655848523035274,0.99756385315029572,{"$f":"IF(A481<>\"\",RANK(A481,A$4:A$1003,1)+SUM(IF(A$4:A481=A481,1,0))-1.5,\"\")","v":477.5},1.0546353524310361,0.84075455182567949,465.13131278007245]
[11.663040237180212,0.99817935480673881,{"$f":"IF(A482<>\"\",RANK(A482,A$4:A$1003,1)+SUM(IF(A$4:A482=A482,1,0))-1.5,\"\")","v":478.5},1.0624877610409094,0.84090380219616001,461.78470109378077]
[11.723183026541847,1.0033266654101851,{"$f":"IF(A483<>\"\",RANK(A483,A$4:A$1003,1)+SUM(IF(A$4:A483=A483,1,0))-1.5,\"\")","v":479.5},1.0704062355945709,0.84214836280150474,458.28516629071271]
[11.740048428143382,1.0047700879952763,{"$f":"IF(A484<>\"\",RANK(A484,A$4:A$1003,1)+SUM(IF(A$4:A484=A484,1,0))-1.5,\"\")","v":480.5},1.0783924022522531,0.84249621485779569,454.88606001691659]
[11.744493381348548,1.0051505085744949,{"$f":"IF(A485<>\"\",RANK(A485,A$4:A$1003,1)+SUM(IF(A$4:A485=A485,1,0))-1.5,\"\")","v":481.5},1.0864479465899999,0.84258780890606944,451.51769566385894]
[11.781952435435414,1.0083564354751748,{"$f":"IF(A486<>\"\",RANK(A486,A$4:A$1003,1)+SUM(IF(A$4:A486=A486,1,0))-1.5,\"\")","v":482.5},1.0945746165935941,0.84335831050350663,448.03118135201004]
[12.170004938816419,1.041567844299873,{"$f":"IF(A487<>\"\",RANK(A487,A$4:A$1003,1)+SUM(IF(A$4:A487=A487,1,0))-1.5,\"\")","v":483.5},1.1027742258446926,0.85119395828693811,443.47029950238505]
[12.278784480366085,1.0508777232329878,{"$f":"IF(A488<>\"\",RANK(A488,A$4:A$1003,1)+SUM(IF(A$4:A488=A488,1,0))-1.5,\"\")","v":484.5},1.1110486569142424,0.85334262354460033,439.70649640717704]
[12.536616457216951,1.0729442299986116,{"$f":"IF(A489<>\"\",RANK(A489,A$4:A$1003,1)+SUM(IF(A$4:A489=A489,1,0))-1.5,\"\")","v":485.5},1.1193998649796508,0.85835193024965173,435.60981982593131]
[12.806540543389019,1.0960456379250845,{"$f":"IF(A490<>\"\",RANK(A490,A$4:A$1003,1)+SUM(IF(A$4:A490=A490,1,0))-1.5,\"\")","v":486.5},1.1278298816837637,0.86347059859721675,431.55817187718674]
[12.892505719489236,1.1034029531937051,{"$f":"IF(A491<>\"\",RANK(A491,A$4:A$1003,1)+SUM(IF(A$4:A491=A491,1,0))-1.5,\"\")","v":487.5},1.1363408192553905,0.8650738926067163,427.74984638636465]
[12.97062603057293,1.1100888669973994,{"$f":"IF(A492<>\"\",RANK(A492,A$4:A$1003,1)+SUM(IF(A$4:A492=A492,1,0))-1.5,\"\")","v":488.5},1.1449348749130688,0.86651963293280176,423.92121395048196]
[12.974940353603415,1.1104581076148901,{"$f":"IF(A493<>\"\",RANK(A493,A$4:A$1003,1)+SUM(IF(A$4:A493=A493,1,0))-1.5,\"\")","v":489.5},1.1536143355758646,0.86659916468743492,420.17314701724354]
[12.977228145293338,1.1106539078853632,{"$f":"IF(A494<>\"\",RANK(A494,A$4:A$1003,1)+SUM(IF(A$4:A494=A494,1,0))-1.5,\"\")","v":490.5},1.1623815829073989,0.86664132541896921,416.42629053030214]
[13.333770558437209,1.1411685308889399,{"$f":"IF(A495<>\"\",RANK(A495,A$4:A$1003,1)+SUM(IF(A$4:A495=A495,1,0))-1.5,\"\")","v":491.5},1.1712390987219441,0.8731001014118851,412.08623485200371]
[13.342137944150636,1.1418846522006216,{"$f":"IF(A496<>\"\",RANK(A496,A$4:A$1003,1)+SUM(IF(A$4:A496=A496,1,0))-1.5,\"\")","v":492.5},1.180189470784379,0.87324901550389877,408.21711046736402]
[13.357174523310277,1.1431715553218353,{"$f":"IF(A497<>\"\",RANK(A497,A$4:A$1003,1)+SUM(IF(A$4:A497=A497,1,0))-1.5,\"\")","v":493.5},1.1892353990391253,0.87351631511916106,404.33159734574326]
[13.596764190813701,1.1636767970824253,{"$f":"IF(A498<>\"\",RANK(A498,A$4:A$1003,1)+SUM(IF(A$4:A498=A498,1,0))-1.5,\"\")","v":494.5},1.1983797023069247,0.87772249203294306,400.07874965133772]
[13.887935080342686,1.1885966091329705,{"$f":"IF(A499<>\"\",RANK(A499,A$4:A$1003,1)+SUM(IF(A$4:A499=A499,1,0))-1.5,\"\")","v":495.5},1.2076253254924434,0.8827007785722637,395.81053329734016]
[13.939318593469579,1.1929942585397852,{"$f":"IF(A500<>\"\",RANK(A500,A$4:A$1003,1)+SUM(IF(A$4:A500=A500,1,0))-1.5,\"\")","v":496.5},1.2169753473504625,0.88356418918291468,391.72668945572923]
[13.978345209648978,1.1963343449808874,{"$f":"IF(A501<>\"\",RANK(A501,A$4:A$1003,1)+SUM(IF(A$4:A501=A501,1,0))-1.5,\"\")","v":497.5},1.2264329888636651,0.88421694442260024,387.6301271207912]
[14.071043130643375,1.2042678810991219,{"$f":"IF(A502<>\"\",RANK(A502,A$4:A$1003,1)+SUM(IF(A$4:A502=A502,1,0))-1.5,\"\")","v":498.5},1.2360016222910355,0.8857569716469571,383.44942629549053]
[14.227742722059702,1.2176789895131839,{"$f":"IF(A503<>\"\",RANK(A503,A$4:A$1003,1)+SUM(IF(A$4:A503=A503,1,0))-1.5,\"\")","v":499.5},1.245684780952663,0.88832700783958507,379.16640290961283]
[14.274352942906262,1.2216681174957564,{"$f":"IF(A504<>\"\",RANK(A504,A$4:A$1003,1)+SUM(IF(A$4:A504=A504,1,0))-1.5,\"\")","v":500.5},1.2554861698244288,0.8890834211523575,374.96207256414903]
[14.439289289861335,1.2357841672597725,{"$f":"IF(A505<>\"\",RANK(A505,A$4:A$1003,1)+SUM(IF(A$4:A505=A505,1,0))-1.5,\"\")","v":501.5},1.2654096770247685,0.89173059914410457,370.59524567764691]
[14.494136266247551,1.240478236592377,{"$f":"IF(A506<>\"\",RANK(A506,A$4:A$1003,1)+SUM(IF(A$4:A506=A506,1,0))-1.5,\"\")","v":502.5},1.2754593862856403,0.8926007204781069,366.30980321545724]
[14.55173000357081,1.2454073870019724,{"$f":"IF(A507<>\"\",RANK(A507,A$4:A$1003,1)+SUM(IF(A$4:A507=A507,1,0))-1.5,\"\")","v":503.5},1.2856395905111833,0.89350898033458748,361.99318874623248]
[14.687246343078186,1.2570055303320442,{"$f":"IF(A508<>\"\",RANK(A508,A$4:A$1003,1)+SUM(IF(A$4:A508=A508,1,0))-1.5,\"\")","v":504.5},1.2959548065404789,0.89562418349084039,357.54004434973638]
[14.9404356578234,1.2786746956351538,{"$f":"IF(A509<>\"\",RANK(A509,A$4:A$1003,1)+SUM(IF(A$4:A509=A509,1,0))-1.5,\"\")","v":505.5},1.3064097912457113,0.89949418296216721,352.92458712272708]
[15.015223135822453,1.2850753694747861,{"$f":"IF(A510<>\"\",RANK(A510,A$4:A$1003,1)+SUM(IF(A$4:A510=A510,1,0))-1.5,\"\")","v":506.5},1.3170095591140834,0.90061702615932915,348.45726237803433]
[15.025747683052032,1.2859761110952912,{"$f":"IF(A511<>\"\",RANK(A511,A$4:A$1003,1)+SUM(IF(A$4:A511=A511,1,0))-1.5,\"\")","v":507.5},1.3277594014814904,0.90077430050753882,344.03495768042796]
[15.039343803016891,1.2871397327564023,{"$f":"IF(A512<>\"\",RANK(A512,A$4:A$1003,1)+SUM(IF(A$4:A512=A512,1,0))-1.5,\"\")","v":508.5},1.338664907608661,0.90097720561170291,339.60092724291519]
[15.043594574598501,1.2875035343337333,{"$f":"IF(A513<>\"\",RANK(A513,A$4:A$1003,1)+SUM(IF(A$4:A513=A513,1,0))-1.5,\"\")","v":509.5},1.3497319878167826,0.90104058074581694,335.1763739072926]
[15.1832946069635,1.2994597383197237,{"$f":"IF(A514<>\"\",RANK(A514,A$4:A$1003,1)+SUM(IF(A$4:A514=A514,1,0))-1.5,\"\")","v":510.5},1.3609668989300907,0.90310689901510577,330.46680696460584]
[15.248080058430787,1.3050043903856845,{"$f":"IF(A515<>\"\",RANK(A515,A$4:A$1003,1)+SUM(IF(A$4:A515=A515,1,0))-1.5,\"\")","v":511.5},1.3723762723084989,0.90405432359416771,325.86318821922504]
[15.433804239495657,1.3208995634672547,{"$f":"IF(A516<>\"\",RANK(A516,A$4:A$1003,1)+SUM(IF(A$4:A516=A516,1,0))-1.5,\"\")","v":512.5},1.3839671447948068,0.90673257232766447,320.97785813532732]
[15.571477740519185,{"$f":"+IF(A517<>\"\",(A517-K$2)/K$3,\"\")","v":1.3326823271061499},{"$f":"IF(A517<>\"\",RANK(A517,A$4:A$1003,1)+SUM(IF(A$4:A517=A517,1,0))-1.5,\"\")","v":513.5},{"$f":"IF(A517<>\"\",NORMSINV(C517/($K$1)),\"\")","v":1.39574699294967},{"$f":"IF(A517<>\"\",NORMDIST(A517,$K$2,$K$3,1),\"\")","v":0.90868196234902443},{"$f":"IF(A517<>\"\",-2*C517*LN(E517)-(2*$K$1-2*C517)*LN(1-E517),\"\")","v":316.14567784481181}]
[15.910762861538387,1.3617199876395298,{"$f":"IF(A518<>\"\",RANK(A518,A$4:A$1003,1)+SUM(IF(A$4:A518=A518,1,0))-1.5,\"\")","v":514.5},1.4077237710046304,0.91335686455257714,310.9470504152967]
[16.001303621017541,1.3694689034490188,{"$f":"IF(A519<>\"\",RANK(A519,A$4:A$1003,1)+SUM(IF(A$4:A519=A519,1,0))-1.5,\"\")","v":515.5},1.4199059530310461,0.91457362562991751,306.09425583753614]
[16.018889252216468,1.3709739667641614,{"$f":"IF(A520<>\"\",RANK(A520,A$4:A$1003,1)+SUM(IF(A$4:A520=A520,1,0))-1.5,\"\")","v":516.5},1.4323025799023157,0.91480846421476869,301.32142457206135]
[16.666471924714642,1.4263972218565553,{"$f":"IF(A521<>\"\",RANK(A521,A$4:A$1003,1)+SUM(IF(A$4:A521=A521,1,0))-1.5,\"\")","v":517.5},1.4449233117218241,0.92312314241402926,295.73306263023903]
[16.683535035215755,1.4278575653248644,{"$f":"IF(A522<>\"\",RANK(A522,A$4:A$1003,1)+SUM(IF(A$4:A522=A522,1,0))-1.5,\"\")","v":518.5},1.457778486501907,0.9233335701294445,290.74760549293751]
[17.015430733191351,1.4562628033186613,{"$f":"IF(A523<>\"\",RANK(A523,A$4:A$1003,1)+SUM(IF(A$4:A523=A523,1,0))-1.5,\"\")","v":519.5},1.4708791860145434,0.92734000799774952,285.51214701656062]
[17.054001907398742,1.459563910834498,{"$f":"IF(A524<>\"\",RANK(A524,A$4:A$1003,1)+SUM(IF(A$4:A524=A524,1,0))-1.5,\"\")","v":520.5},1.4842373098972286,0.92779501809091081,280.39213899422293]
[17.226846670818304,1.4743568011035222,{"$f":"IF(A525<>\"\",RANK(A525,A$4:A$1003,1)+SUM(IF(A$4:A525=A525,1,0))-1.5,\"\")","v":521.5},1.4978656592940365,0.92980722544437067,275.14569522302816]
[17.36792008365228,1.4864305456280471,{"$f":"IF(A526<>\"\",RANK(A526,A$4:A$1003,1)+SUM(IF(A$4:A526=A526,1,0))-1.5,\"\")","v":522.5},1.5117780315504272,0.93141736235201034,269.86421745115251]
[17.404856617041332,1.4895917526818938,{"$f":"IF(A527<>\"\",RANK(A527,A$4:A$1003,1)+SUM(IF(A$4:A527=A527,1,0))-1.5,\"\")","v":523.5},1.5259893277711403,0.93183419407362578,264.61126906748433]
[17.533117690955805,1.5005689553154407,{"$f":"IF(A528<>\"\",RANK(A528,A$4:A$1003,1)+SUM(IF(A$4:A528=A528,1,0))-1.5,\"\")","v":524.5},1.5405156754070479,0.93326645701598909,259.23497066836421]
[17.589468677985678,1.5053917451483074,{"$f":"IF(A529<>\"\",RANK(A529,A$4:A$1003,1)+SUM(IF(A$4:A529=A529,1,0))-1.5,\"\")","v":525.5},1.5553745684760383,0.9338883049373341,253.88620039146861]
[17.755711326684832,1.5196195945293676,{"$f":"IF(A530<>\"\",RANK(A530,A$4:A$1003,1)+SUM(IF(A$4:A530=A530,1,0))-1.5,\"\")","v":526.5},1.5705850285674188,0.93569669484386764,248.35586168600736]
[18.070416811261566,1.5465536109745357,{"$f":"IF(A531<>\"\",RANK(A531,A$4:A$1003,1)+SUM(IF(A$4:A531=A531,1,0))-1.5,\"\")","v":527.5},1.5861677904580811,0.93901453844792726,242.603700463872]
[18.203645359079928,1.5579559540342121,{"$f":"IF(A532<>\"\",RANK(A532,A$4:A$1003,1)+SUM(IF(A$4:A532=A532,1,0))-1.5,\"\")","v":528.5},1.6021455170203514,0.9403781551547421,236.98089195322308]
[18.330730761425002,1.5688325370124425,{"$f":"IF(A533<>\"\",RANK(A533,A$4:A$1003,1)+SUM(IF(A$4:A533=A533,1,0))-1.5,\"\")","v":529.5},1.6185430491774164,0.94165651761321467,231.30451917491507]
[18.54103457893234,1.5868313541822245,{"$f":"IF(A534<>\"\",RANK(A534,A$4:A$1003,1)+SUM(IF(A$4:A534=A534,1,0))-1.5,\"\")","v":530.5},1.6353876980312458,0.94372457724410608,225.47144338017648]
[18.604707910279103,1.5922808256330285,{"$f":"IF(A535<>\"\",RANK(A535,A$4:A$1003,1)+SUM(IF(A$4:A535=A535,1,0))-1.5,\"\")","v":531.5},1.6527095880432499,0.94433919035128744,219.74421080752225]
[18.686881284045739,1.5993136201309137,{"$f":"IF(A536<>\"\",RANK(A536,A$4:A$1003,1)+SUM(IF(A$4:A536=A536,1,0))-1.5,\"\")","v":532.5},1.6705420624168457,0.94512453265774932,213.94959848339985]
[19.146321353616258,1.6386347219096922,{"$f":"IF(A537<>\"\",RANK(A537,A$4:A$1003,1)+SUM(IF(A$4:A537=A537,1,0))-1.5,\"\")","v":533.5},1.6889221647895578,0.94935532174459192,207.5832436397281]
[19.235096842102394,1.6462325572954635,{"$f":"IF(A538<>\"\",RANK(A538,A$4:A$1003,1)+SUM(IF(A$4:A538=A538,1,0))-1.5,\"\")","v":534.5},1.7078912152358261,0.95014205565715848,201.60298773876843]
[19.278635490212764,1.6499588052373519,{"$f":"IF(A539<>\"\",RANK(A539,A$4:A$1003,1)+SUM(IF(A$4:A539=A539,1,0))-1.5,\"\")","v":535.5},1.7274955037572379,0.95052431904388102,195.63905974059952]
[19.306092517767866,1.6523087103643606,{"$f":"IF(A540<>\"\",RANK(A540,A$4:A$1003,1)+SUM(IF(A$4:A540=A540,1,0))-1.5,\"\")","v":536.5},1.7477871313908646,0.95076418272238739,189.67595427702568]
[19.431214940221253,1.6630172920357329,{"$f":"IF(A541<>\"\",RANK(A541,A$4:A$1003,1)+SUM(IF(A$4:A541=A541,1,0))-1.5,\"\")","v":537.5},1.7688250385187059,0.95184551292318553,183.4876348155089]
[19.450043321715384,1.6646287159277597,{"$f":"IF(A542<>\"\",RANK(A542,A$4:A$1003,1)+SUM(IF(A$4:A542=A542,1,0))-1.5,\"\")","v":538.5},1.7906762729715839,0.9520065736752682,177.47479659359718]
[19.922034469855134,1.7050239996739831,{"$f":"IF(A543<>\"\",RANK(A543,A$4:A$1003,1)+SUM(IF(A$4:A543=A543,1,0))-1.5,\"\")","v":539.5},1.813417568674035,0.95590502575806202,170.39432606131169]
[20.096252613743673,1.7199344304815416,{"$f":"IF(A544<>\"\",RANK(A544,A$4:A$1003,1)+SUM(IF(A$4:A544=A544,1,0))-1.5,\"\")","v":540.5},1.8371373312844288,0.95727781945716428,163.86058958821349]
[20.295703544948083,1.7370044051859508,{"$f":"IF(A545<>\"\",RANK(A545,A$4:A$1003,1)+SUM(IF(A$4:A545=A545,1,0))-1.5,\"\")","v":541.5},1.8619381642865562,0.95880680334398016,157.18900807293829]
[21.154049004202534,1.8104657582548003,{"$f":"IF(A546<>\"\",RANK(A546,A$4:A$1003,1)+SUM(IF(A$4:A546=A546,1,0))-1.5,\"\")","v":542.5},1.8879401232066653,0.96488820510976758,149.30539142041789]
[21.628130235131721,1.8510399213882007,{"$f":"IF(A547<>\"\",RANK(A547,A$4:A$1003,1)+SUM(IF(A$4:A547=A547,1,0))-1.5,\"\")","v":543.5},1.9152849666553875,0.96791809495269954,142.06804374601737]
[22.364816735192107,1.9140891127114674,{"$f":"IF(A548<>\"\",RANK(A548,A$4:A$1003,1)+SUM(IF(A$4:A548=A548,1,0))-1.5,\"\")","v":544.5},1.9441417966631021,0.97219561479893446,134.60217314020923]
[22.36520862571524,1.9141226525965729,{"$f":"IF(A549<>\"\",RANK(A549,A$4:A$1003,1)+SUM(IF(A$4:A549=A549,1,0))-1.5,\"\")","v":545.5},1.9747146745228341,0.9721977571334568,127.49312287766531]
[22.536026857794241,1.9287421025185794,{"$f":"IF(A550<>\"\",RANK(A550,A$4:A$1003,1)+SUM(IF(A$4:A550=A550,1,0))-1.5,\"\")","v":546.5},2.0072531101066922,0.97311855667129943,120.19152469417679]
[22.831120179831487,1.9539976153015877,{"$f":"IF(A551<>\"\",RANK(A551,A$4:A$1003,1)+SUM(IF(A$4:A551=A551,1,0))-1.5,\"\")","v":547.5},2.0420668401666333,0.97464925039529571,112.64076992248339]
[22.892308010588749,1.9592343655987006,{"$f":"IF(A552<>\"\",RANK(A552,A$4:A$1003,1)+SUM(IF(A$4:A552=A552,1,0))-1.5,\"\")","v":548.5},2.0795472015725602,0.97495732686923708,105.25230281703114]
[24.630570544251896,2.108003274824009,{"$f":"IF(A553<>\"\",RANK(A553,A$4:A$1003,1)+SUM(IF(A$4:A553=A553,1,0))-1.5,\"\")","v":549.5},2.1201990020987811,0.98248464691762305,96.268819346536105]
[25.346726943274916,2.1692954008717686,{"$f":"IF(A554<>\"\",RANK(A554,A$4:A$1003,1)+SUM(IF(A$4:A554=A554,1,0))-1.5,\"\")","v":550.5},2.1646897963197596,0.98496986790840402,88.034667260870577]
[26.729622735364501,2.2876503067488949,{"$f":"IF(A555<>\"\",RANK(A555,A$4:A$1003,1)+SUM(IF(A$4:A555=A555,1,0))-1.5,\"\")","v":551.5},2.2139294645272254,0.98892105311821821,79.828905112866281]
[26.763943137989372,2.290587612687323,{"$f":"IF(A556<>\"\",RANK(A556,A$4:A$1003,1)+SUM(IF(A$4:A556=A556,1,0))-1.5,\"\")","v":552.5},2.2692057962849623,0.98900636197481773,70.850939635962163]
[27.720670694462569,2.3724689811491793,{"$f":"IF(A557<>\"\",RANK(A557,A$4:A$1003,1)+SUM(IF(A$4:A557=A557,1,0))-1.5,\"\")","v":553.5},2.3324316174480213,0.99116517663936332,61.843204397059985]
[30.348982959239947,2.5974126482662685,{"$f":"IF(A558<>\"\",RANK(A558,A$4:A$1003,1)+SUM(IF(A$4:A558=A558,1,0))-1.5,\"\")","v":554.5},2.4066366628024016,0.99530354962259715,53.469166957306228]
[33.736008781206692,2.8872906887197325,{"$f":"IF(A559<>\"\",RANK(A559,A$4:A$1003,1)+SUM(IF(A$4:A559=A559,1,0))-1.5,\"\")","v":555.5},2.4970717585635267,0.99805712475488673,45.865738224801852]
[34.460599644668036,2.9493046770006641,{"$f":"IF(A560<>\"\",RANK(A560,A$4:A$1003,1)+SUM(IF(A$4:A560=A560,1,0))-1.5,\"\")","v":556.5},2.6141664905746826,0.99840755088656186,33.986219212929072]
[34.625207652548852,2.9633926259197345,{"$f":"IF(A561<>\"\",RANK(A561,A$4:A$1003,1)+SUM(IF(A$4:A561=A561,1,0))-1.5,\"\")","v":557.5},2.7841557120667124,0.99847865902690913,21.162076158589937]
[39.112784732036744,3.3474611623179791,{"$f":"IF(A562<>\"\",RANK(A562,A$4:A$1003,1)+SUM(IF(A$4:A562=A562,1,0))-1.5,\"\")","v":558.5},3.1232086556279053,0.9995922229274119,8.2603698075121468]

{"sheet":"Example data set","index":10,"n_rows":565,"n_cols":2,"rows_kept":565,"cut":false,"hidden":false,"merged":[]}
["Example Data Set"]
[]
[{"$f":"+'General Info'!B7","v":"Length"}]
["Test Method"]
["X","Y"]
["Alternate","Designated"]
[5655.74,5650]
[6044.16,6040]
[5783.44,5790]
[5530.85,5520]
[6138.03,6140]
[5865.06,5860]
[5666.66,5650]
[6123.04,6130]
[5829.36,5820]
[6040.95,6010]
[6008.81,6000]
[5435.37,5430]
[5601.08,5600]
[5492.71,5490]
[5796.65,5810]
[6112.29,6110]
[5957.71,5940]
[5977.64,5980]
[6081.94,6100]
[5486.68,5490]
[5504.95,5500]
[5761.72,5780]
[6107.12,6100]
[5352,5340]
[6037.93,6040]
[6096.5,6080]
[6108.76,6100]
[5561.14,5560]
[5850.84,5850]
[5704.65,5710]
[6012.85,6010]
[5745.6,5750]
[5949.39,5960]
[5875.73,5880]
[5892.61,5890]
[5498.75,5500]
[6106.17,6110]
[5650.65,5660]
[5577.68,5580]
[5934.85,5930]
[5671.56,5680]
[6180.97,6200]
[5835.95,5840]
[5998.74,6000]
[5950.86,5950]
[5672.99,5680]
[5669,5680]
[5441.75,5420]
[6022.06,6030]
[5986.08,6000]
[5527.25,5520]
[5919.79,5930]
[5768.17,5750]
[5689.97,5700]
[5658.84,5640]
[5363.19,5360]
[5542.67,5540]
[5721.89,5720]
[6302.83,6310]
[6097.26,6100]
[5502.26,5510]
[5384.3,5380]
[6362.51,6360]
[5890.45,5880]
[5989.1,5980]
[6177.46,6180]
[6170.59,6160]
[5637.03,5620]
[5825.74,5830]
[5553.63,5540]
[6075.04,6060]
[5937.82,5930]
[6316.07,6320]
[5674.49,5670]
[5392.21,5390]
[5662.55,5670]
[5875.88,5890]
[5696.89,5710]
[5499.8,5500]
[5691.9,5700]
[5827.25,5840]
[5959.23,5930]
[6120.21,6120]
[5342.72,5350]
[5490.68,5460]
[6066.05,6050]
[5852.83,5850]
[5523.61,5540]
[5852.31,5850]
[5484.85,5480]
[6094.07,6090]
[5937.11,5940]
[5709.46,5690]
[5429.21,5430]
[5857.94,5860]
[6164.34,6190]
[5969.56,5970]
[5650.91,5640]
[5526.36,5520]
[5524.78,5520]
[6010.76,6020]
[6406.39,6430]
[6160.05,6140]
[6173.3,6150]
[5902.01,5940]
[5751,5740]
[5939.29,5940]
[5433.76,5430]
[6001.7,6000]
[5440.46,5430]
[5593.15,5570]
[6082.44,6080]
[5688.63,5710]
[5634.39,5630]
[5701.17,5690]
[5073.57,5100]
[5889.66,5880]
[6072.94,6060]
[5811.92,5810]
[6134.88,6130]
[6232.1,6230]
[5453.07,5460]
[5896.32,5900]
[6186.05,6200]
[5551.89,5550]
[5873.7,5850]
[6087.98,6080]
[5531.83,5520]
[5594.44,5600]
[5716.22,5730]
[5921.94,5930]
[5887.96,5880]
[5995.15,6000]
[5602.15,5600]
[6130,6110]
[5765.75,5750]
[5333.87,5350]
[6044.14,6040]
[5481.8,5470]
[6116.64,6130]
[6131.8,6120]
[5559.5,5560]
[5610.82,5610]
[5718.68,5710]
[6158.77,6160]
[5934.97,5930]
[5411.43,5420]
[5993.06,5990]
[5480.58,5470]
[6211.61,6230]
[6081.7,6090]
[5900.13,5900]
[5963.04,5980]
[5404.19,5400]
[5485.92,5490]
[5920.77,5950]
[6315.12,6300]
[5848.67,5840]
[5649.89,5640]
[5307.48,5300]
[5739.96,5740]
[5517.06,5510]
[6114.72,6120]
[5964.79,5940]
[5930.66,5940]
[5653.64,5670]
[5433.93,5440]
[5708.84,5680]
[5494.19,5510]
[5616.72,5650]
[6236.38,6230]
[6044.33,6070]
[5486.16,5490]
[5368.49,5340]
[6321.26,6310]
[5990.48,6000]
[6170.94,6160]
[5751.27,5740]
[5496.08,5500]
[5847.8,5860]
[6022.26,6030]
[6046.05,6060]
[6047.46,6040]
[5430.9,5440]
[5956.99,5940]
[5904.26,5890]
[5645.53,5630]
[5493.92,5490]
[5396.6,5430]
[5689.51,5700]
[5640.99,5640]
[5542.64,5530]
[5406.04,5420]
[6114.65,6110]
[6043.77,6050]
[5787.41,5820]
[5651.15,5620]
[6138.1,6150]
[6152.24,6160]
[5782.51,5780]
[6119.36,6120]
[5986.57,5980]
[6339.88,6360]
[5635.83,5660]
[5612.61,5590]
[5623.62,5610]
[5475.33,5480]
[5608.29,5630]
[6060.13,6050]
[5786.52,5750]
[5496.27,5500]
[5724.25,5710]
[6006.87,5990]
[5971.83,5990]
[6150.62,6140]
[5550.12,5560]
[6027.9,6030]
[5688.36,5680]
[6035.33,6040]
[5798.01,5780]
[5700.94,5710]
[5452.88,5450]
[6138.71,6160]
[6056.68,6060]
[5691.88,5680]
[6044.04,6060]
[5947.05,5950]
[5561.11,5570]
[5378.92,5360]
[5878.77,5880]
[6027.2,6020]
[5751.25,5740]
[5832.07,5810]
[5950.83,5940]
[6167.79,6170]
[5564.63,5550]
[5446.59,5440]
[6120.61,6120]
[5386.54,5400]
[5936.12,5920]
[5940.37,5950]
[5650.3,5630]
[5541.33,5540]
[5926.89,5940]
[5559.55,5560]
[6083.62,6080]
[6103.22,6100]
[5518.47,5500]
[6085.33,6090]
[5790.79,5800]
[5956.31,5960]
[6218.51,6220]
[5813.32,5820]
[5806.25,5800]
[6193.05,6190]
[5429.97,5440]
[5915.16,5910]
[5602.27,5610]
[5999.44,6010]
[5814.32,5810]
[5939.51,5930]
[5862.8,5880]
[5779.98,5780]
[5393.34,5400]
[5815.51,5780]
[5792.15,5800]
[6097.32,6090]
[5724.57,5730]
[5545.99,5530]
[5898.89,5900]
[5677.19,5690]
[5417.15,5430]
[5660.49,5640]
[5360.11,5360]
[5814.17,5820]
[5932.56,5930]
[5617.98,5620]
[5546.65,5540]
[6191.67,6200]
[5928.86,5930]
[5378.95,5390]
[5752.89,5760]
[5995.35,5980]
[5464.35,5460]
[6214.36,6200]
[5963.33,5970]
[6128.38,6110]
[5743.75,5760]
[5988.74,6010]
[5661.33,5660]
[5594.19,5590]
[6126.06,6130]
[5356.23,5350]
[6315.11,6310]
[6083.84,6070]
[6463.71,6470]
[5476.52,5460]
[5730.97,5730]
[5784.46,5770]
[6307.57,6310]
[5581.65,5570]
[6273.42,6270]
[6147.98,6150]
[5564.46,5560]
[5521.84,5520]
[6060.93,6020]
[5644.44,5640]
[5879.25,5880]
[5932.81,5930]
[6202.08,6210]
[6169.59,6160]
[5791.19,5790]
[5743.5,5740]
[5760.91,5750]
[5444.6,5450]
[5635.06,5640]
[5432.59,5430]
[5579.91,5590]
[5553.51,5550]
[6096.56,6100]
[5931.48,5940]
[6163.13,6170]
[5465.21,5480]
[6291.5,6300]
[6081.73,6070]
[5989.59,6000]
[6227.69,6230]
[5665.82,5660]
[5918.5,5900]
[5891.7,5890]
[5416.91,5420]
[5912.54,5920]
[6162.42,6170]
[6136.52,6130]
[5903.36,5910]
[6004.51,6000]
[6024.25,6030]
[5422.28,5420]
[5733.93,5750]
[5956.56,5970]
[5449.36,5450]
[6211.62,6210]
[6018.81,6020]
[6181.76,6200]
[6176.1,6170]
[5851.77,5850]
[5888.55,5890]
[6278.24,6290]
[6154.31,6150]
[5974.75,5980]
[5946.34,5950]
[5517.43,5520]
[5550.84,5540]
[5898.47,5900]
[5762.03,5770]
[6149.48,6140]
[5904.97,5900]
[6067.15,6080]
[5462.24,5450]
[6091.98,6100]
[6158.74,6150]
[5830.59,5810]
[5421.31,5420]
[5665.26,5680]
[6231.95,6220]
[6207.29,6210]
[5619.44,5630]
[5762.61,5780]
[5959.26,5950]
[6034.91,6020]
[5851.19,5840]
[6063.05,6050]
[6103.79,6090]
[5929.11,5930]
[5574.09,5570]
[6170.02,6150]
[5792.04,5790]
[5567.58,5550]
[5993.49,5990]
[5473.4,5470]
[5365.66,5380]
[5586.07,5580]
[5964.92,5970]
[5539.88,5550]
[5707.82,5720]
[5625.16,5640]
[6228.52,6240]
[6067.56,6070]
[6113.98,6100]
[5813.08,5780]
[5485.68,5480]
[6173.22,6170]
[6066.73,6070]
[5450.31,5460]
[6258.08,6270]
[5806,5810]
[5855.06,5840]
[6206.43,6200]
[5907.5,5900]
[5887.54,5880]
[6028.12,6040]
[6109.76,6100]
[6102.39,6100]
[6145.24,6140]
[6190.05,6200]
[5376.19,5390]
[5490.26,5490]
[6393.86,6380]
[5974.07,5970]
[5541.97,5540]
[5850.71,5850]
[6148.83,6150]
[5487.61,5500]
[5383.99,5380]
[6400.03,6400]
[5871.29,5880]
[5731.03,5730]
[6058.34,6050]
[5475.31,5470]
[5429.95,5420]
[5529.1,5530]
[5906.51,5900]
[6251.13,6270]
[5651.76,5650]
[5545.95,5550]
[6173.59,6160]
[5922.82,5930]
[5947.66,5940]
[5719.55,5700]
[5458.81,5450]
[6154.98,6130]
[6114.27,6120]
[6060.56,6060]
[5830.27,5830]
[6098.08,6100]
[5570.26,5570]
[6077.73,6090]
[5834.04,5840]
[6161.44,6160]
[5846.55,5840]
[5427.51,5430]
[5358.29,5350]
[5939.7,5930]
[5500.33,5500]
[5670.9,5670]
[5449.47,5460]
[5661.03,5670]
[5522.72,5520]
[5496.82,5490]
[6121.24,6110]
[5375.48,5380]
[6281.88,6290]
[5889.69,5890]
[6079.11,6080]
[5726.4,5700]
[5791.91,5810]
[5503,5520]
[5281.71,5280]
[5892.52,5910]
[5640.88,5660]
[5764.43,5760]
[5840.25,5820]
[5750.26,5760]
[5839.94,5840]
[6342.87,6340]
[5492.1,5490]
[5964.32,5960]
[5907.93,5910]
[5921.68,5930]
[5915.87,5910]
[6150.27,6140]
[5950.32,5950]
[5821.05,5810]
[5947.91,5930]
[5691.42,5700]
[5716.99,5710]
[5579.56,5600]
[5953.81,5960]
[5883.08,5880]
[5696.8,5700]
[6062.23,6050]
[5601.53,5600]
[6022.69,6000]
[5876.91,5880]
[6266.58,6250]
[6001.33,6000]
[5647.54,5630]
[5516.65,5520]
[5654.38,5640]
[5763.76,5740]
[5827.75,5820]
[5532.41,5520]
[5479.68,5490]
[5627.6,5620]
[5823.33,5810]
[6178.02,6180]
[5940.14,5940]
[6202.01,6200]
[5826.76,5820]
[6135.09,6130]
[6194.38,6210]
[5795.19,5780]
[5832.45,5850]
[5702.07,5710]
[6080.92,6070]
[6100.21,6090]
[6474.15,6480]
[6023.66,6030]
[6041.28,6050]
[5887.82,5890]
[5493.78,5490]
[6298.15,6310]
[5574.39,5580]
[5813.59,5820]
[5477.21,5480]
[5796.48,5780]
[5834.47,5850]
[6183.73,6180]
[6049.52,6040]
[5605.25,5610]
[5443.95,5450]
[6111.35,6100]
[5765.3,5760]
[6176.88,6180]
[5473.59,5460]
[6140.16,6150]
[5462.47,5440]
[5983.74,5980]
[5932.33,5920]
[5426.57,5410]
[6164.18,6170]
[6016.85,6020]
[5592.91,5600]
[5902.04,5900]
[5574.07,5570]
[5869.31,5870]
[5805.04,5780]
[6096.57,6090]
[5785.85,5770]
[5904.37,5900]
[6070.17,6060]
[5659.39,5670]
[5579.57,5560]
[5605.64,5610]
[5875.57,5870]
[5443.46,5460]
[5760.53,5770]
[6009.12,6000]
[5884.39,5890]
[5526.25,5500]
[5794.5,5780]
[5507.87,5500]
[6086.19,6080]
[6100.97,6090]
[5613.91,5620]
[5476.71,5480]
[5459.02,5450]
[6058.26,6080]
[5995.67,6010]